{"id":9892,"date":"2025-04-21T16:28:42","date_gmt":"2025-04-21T19:28:42","guid":{"rendered":"https:\/\/redelitoralrs.com\/?p=9892"},"modified":"2025-04-21T16:28:42","modified_gmt":"2025-04-21T19:28:42","slug":"assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene","status":"publish","type":"post","link":"https:\/\/redelitoralrs.com\/index.php\/2025\/04\/21\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\/","title":{"rendered":"Assembleia Legislativa adia sess\u00e3o solene de abertura das comemora\u00e7\u00f5es pelos 190 anos"},"content":{"rendered":"\n<p><strong>A Assembleia Legislativa do Rio Grande do Sul transferiu para o dia 30 de abril a sess\u00e3o solene que marca o in\u00edcio das comemora\u00e7\u00f5es pelos 190 anos de sua instala\u00e7\u00e3o<\/strong>. A altera\u00e7\u00e3o ocorre em raz\u00e3o do luto oficial decretado pelo falecimento do Papa Francisco. A cerim\u00f4nia, inicialmente prevista para esta ter\u00e7a-feira (22), ser\u00e1 realizada no Plen\u00e1rio 20 de Setembro, com programa\u00e7\u00e3o especial alusiva \u00e0 data hist\u00f3rica.<\/p>\n\n\n\n<p>As atividades comemorativas destacam a funda\u00e7\u00e3o do Parlamento ga\u00facho em 1835 e contar\u00e3o com a presen\u00e7a de autoridades dos Tr\u00eas Poderes, al\u00e9m da participa\u00e7\u00e3o da Banda da Brigada Militar. Durante o evento, haver\u00e1 manifesta\u00e7\u00f5es das bancadas parlamentares e uma apresenta\u00e7\u00e3o do ator Werner Sch\u00fcnemann, que interpretar\u00e1 trecho da obra&nbsp;<em>Os Var\u00f5es Assinalados<\/em>, relembrando a atua\u00e7\u00e3o de Bento Gon\u00e7alves como deputado provincial. Ainda na ocasi\u00e3o, ser\u00e1 descerrada uma placa em homenagem aos 28 primeiros parlamentares do Estado, que ficar\u00e1 exposta no Memorial do Legislativo.<\/p>\n\n\n\n<p>A agenda comemorativa dever\u00e1 seguir ao longo dos pr\u00f3ximos meses. No dia seguinte \u00e0 sess\u00e3o, est\u00e1 prevista a realiza\u00e7\u00e3o de um sarau na Pra\u00e7a da Matriz, com apresenta\u00e7\u00e3o da fanfarra Bate Sopra. Em maio, ser\u00e1 lan\u00e7ado um livro in\u00e9dito do escritor Alcy Cheuiche, que abordar\u00e1 os primeiros meses de funcionamento da Assembleia. A programa\u00e7\u00e3o se estender\u00e1 com uma mostra de cinema, a partir de junho, e uma exposi\u00e7\u00e3o permanente de documentos hist\u00f3ricos, prevista para agosto, tamb\u00e9m no Memorial do Legislativo.<\/p>\n\n\n\n<p>As celebra\u00e7\u00f5es integram as a\u00e7\u00f5es preparat\u00f3rias para o bicenten\u00e1rio da Assembleia Legislativa, a ser comemorado em 2035. Novas informa\u00e7\u00f5es sobre os eventos ser\u00e3o divulgadas nos canais oficiais do Parlamento ga\u00facho.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"946\" height=\"650\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/04\/Captura-de-Tela-2025-04-19-as-21.11.20.png\" alt=\"\" class=\"wp-image-9894\" srcset=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/04\/Captura-de-Tela-2025-04-19-as-21.11.20.png 946w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/04\/Captura-de-Tela-2025-04-19-as-21.11.20-300x206.png 300w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/04\/Captura-de-Tela-2025-04-19-as-21.11.20-768x528.png 768w\" sizes=\"(max-width: 946px) 100vw, 946px\" \/><figcaption class=\"wp-element-caption\">Imagem: Divulga\u00e7\u00e3o\/ALRS<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A Assembleia Legislativa do Rio Grande do Sul transferiu para o dia 30 de abril a sess\u00e3o solene que marca o in\u00edcio das comemora\u00e7\u00f5es pelos 190 anos de sua instala\u00e7\u00e3o. A altera\u00e7\u00e3o ocorre em raz\u00e3o do luto oficial decretado pelo falecimento do Papa Francisco. A cerim\u00f4nia, inicialmente prevista para esta ter\u00e7a-feira (22), ser\u00e1 realizada no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9893,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[188,15],"tags":[534,92,128],"class_list":["post-9892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rio-grande-do-sul","category-noticias","tag-assembleia-legislativa","tag-noticia","tag-rio-grande-do-sul"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Assembleia Legislativa adia sess\u00e3o solene de abertura das comemora\u00e7\u00f5es pelos 190 anos - Rede Litoral RS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redelitoralrs.com\/index.php\/2025\/04\/21\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assembleia Legislativa adia sess\u00e3o solene de abertura das comemora\u00e7\u00f5es pelos 190 anos - Rede Litoral RS\" \/>\n<meta property=\"og:description\" content=\"A Assembleia Legislativa do Rio Grande do Sul transferiu para o dia 30 de abril a sess\u00e3o solene que marca o in\u00edcio das comemora\u00e7\u00f5es pelos 190 anos de sua instala\u00e7\u00e3o. A altera\u00e7\u00e3o ocorre em raz\u00e3o do luto oficial decretado pelo falecimento do Papa Francisco. A cerim\u00f4nia, inicialmente prevista para esta ter\u00e7a-feira (22), ser\u00e1 realizada no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redelitoralrs.com\/index.php\/2025\/04\/21\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\/\" \/>\n<meta property=\"og:site_name\" content=\"Rede Litoral RS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tvlitoralrsoficial\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-21T19:28:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/04\/28102632_2124598_GDO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/04\\\/21\\\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/04\\\/21\\\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\"},\"headline\":\"Assembleia Legislativa adia sess\u00e3o solene de abertura das comemora\u00e7\u00f5es pelos 190 anos\",\"datePublished\":\"2025-04-21T19:28:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/04\\\/21\\\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\\\/\"},\"wordCount\":311,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/04\\\/21\\\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/28102632_2124598_GDO.jpg\",\"keywords\":[\"assembleia legislativa\",\"not\u00edcia\",\"rio grande do sul\"],\"articleSection\":[\"Rio Grande do Sul\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/04\\\/21\\\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/04\\\/21\\\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/04\\\/21\\\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\\\/\",\"name\":\"Assembleia Legislativa adia sess\u00e3o solene de abertura das comemora\u00e7\u00f5es pelos 190 anos - Rede Litoral RS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/04\\\/21\\\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/04\\\/21\\\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/28102632_2124598_GDO.jpg\",\"datePublished\":\"2025-04-21T19:28:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/04\\\/21\\\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/04\\\/21\\\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/04\\\/21\\\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/28102632_2124598_GDO.jpg\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/28102632_2124598_GDO.jpg\",\"width\":800,\"height\":533,\"caption\":\"Foto: Lauro Alves\\\/Secom\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/04\\\/21\\\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/redelitoralrs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Assembleia Legislativa adia sess\u00e3o solene de abertura das comemora\u00e7\u00f5es pelos 190 anos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"name\":\"TV Litoral\",\"description\":\"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redelitoralrs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\",\"name\":\"TV Litoral\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"width\":454,\"height\":454,\"caption\":\"TV Litoral\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tvlitoralrsoficial\",\"https:\\\/\\\/www.instagram.com\\\/tvlitoral.rs\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\",\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"caption\":\"Reda\u00e7\u00e3o TV Litoral\"},\"description\":\"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.\",\"sameAs\":[\"https:\\\/\\\/redelitoralrs.com\",\"https:\\\/\\\/www.instagram.com\\\/redelitoralrs\",\"https:\\\/\\\/www.youtube.com\\\/@redelitoralrs\"],\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/author\\\/redacaotvlitoral\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Assembleia Legislativa adia sess\u00e3o solene de abertura das comemora\u00e7\u00f5es pelos 190 anos - Rede Litoral RS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redelitoralrs.com\/index.php\/2025\/04\/21\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\/","og_locale":"pt_BR","og_type":"article","og_title":"Assembleia Legislativa adia sess\u00e3o solene de abertura das comemora\u00e7\u00f5es pelos 190 anos - Rede Litoral RS","og_description":"A Assembleia Legislativa do Rio Grande do Sul transferiu para o dia 30 de abril a sess\u00e3o solene que marca o in\u00edcio das comemora\u00e7\u00f5es pelos 190 anos de sua instala\u00e7\u00e3o. A altera\u00e7\u00e3o ocorre em raz\u00e3o do luto oficial decretado pelo falecimento do Papa Francisco. A cerim\u00f4nia, inicialmente prevista para esta ter\u00e7a-feira (22), ser\u00e1 realizada no [&hellip;]","og_url":"https:\/\/redelitoralrs.com\/index.php\/2025\/04\/21\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\/","og_site_name":"Rede Litoral RS","article_publisher":"https:\/\/www.facebook.com\/tvlitoralrsoficial","article_published_time":"2025-04-21T19:28:42+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/04\/28102632_2124598_GDO.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o TV Litoral","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o TV Litoral","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/04\/21\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\/#article","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/04\/21\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\/"},"author":{"name":"Reda\u00e7\u00e3o TV Litoral","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a"},"headline":"Assembleia Legislativa adia sess\u00e3o solene de abertura das comemora\u00e7\u00f5es pelos 190 anos","datePublished":"2025-04-21T19:28:42+00:00","mainEntityOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/04\/21\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\/"},"wordCount":311,"commentCount":0,"publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/04\/21\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/04\/28102632_2124598_GDO.jpg","keywords":["assembleia legislativa","not\u00edcia","rio grande do sul"],"articleSection":["Rio Grande do Sul","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/04\/21\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/04\/21\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\/","url":"https:\/\/redelitoralrs.com\/index.php\/2025\/04\/21\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\/","name":"Assembleia Legislativa adia sess\u00e3o solene de abertura das comemora\u00e7\u00f5es pelos 190 anos - Rede Litoral RS","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/04\/21\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\/#primaryimage"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/04\/21\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/04\/28102632_2124598_GDO.jpg","datePublished":"2025-04-21T19:28:42+00:00","breadcrumb":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/04\/21\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/04\/21\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/04\/21\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\/#primaryimage","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/04\/28102632_2124598_GDO.jpg","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/04\/28102632_2124598_GDO.jpg","width":800,"height":533,"caption":"Foto: Lauro Alves\/Secom"},{"@type":"BreadcrumbList","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/04\/21\/assembleia-legislativa-inicia-celebracoes-pelos-190-anos-com-sessao-solene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/redelitoralrs.com\/"},{"@type":"ListItem","position":2,"name":"Assembleia Legislativa adia sess\u00e3o solene de abertura das comemora\u00e7\u00f5es pelos 190 anos"}]},{"@type":"WebSite","@id":"https:\/\/redelitoralrs.com\/#website","url":"https:\/\/redelitoralrs.com\/","name":"TV Litoral","description":"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.","publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redelitoralrs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redelitoralrs.com\/#organization","name":"TV Litoral","url":"https:\/\/redelitoralrs.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","width":454,"height":454,"caption":"TV Litoral"},"image":{"@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tvlitoralrsoficial","https:\/\/www.instagram.com\/tvlitoral.rs"]},{"@type":"Person","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a","name":"Reda\u00e7\u00e3o TV Litoral","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","url":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","caption":"Reda\u00e7\u00e3o TV Litoral"},"description":"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.","sameAs":["https:\/\/redelitoralrs.com","https:\/\/www.instagram.com\/redelitoralrs","https:\/\/www.youtube.com\/@redelitoralrs"],"url":"https:\/\/redelitoralrs.com\/index.php\/author\/redacaotvlitoral\/"}]}},"_links":{"self":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/9892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/comments?post=9892"}],"version-history":[{"count":3,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/9892\/revisions"}],"predecessor-version":[{"id":9940,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/9892\/revisions\/9940"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media\/9893"}],"wp:attachment":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media?parent=9892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/categories?post=9892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/tags?post=9892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}