{"id":8208,"date":"2025-03-20T17:49:04","date_gmt":"2025-03-20T20:49:04","guid":{"rendered":"https:\/\/redelitoralrs.com\/?p=8208"},"modified":"2025-03-20T18:00:03","modified_gmt":"2025-03-20T21:00:03","slug":"imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado","status":"publish","type":"post","link":"https:\/\/redelitoralrs.com\/index.php\/2025\/03\/20\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\/","title":{"rendered":"Imb\u00e9 recebe a 46\u00aa edi\u00e7\u00e3o do Rallye das Praias neste s\u00e1bado"},"content":{"rendered":"\n<p>A cidade de Imb\u00e9 ser\u00e1, pelo segundo ano consecutivo, o ponto de partida do Rallye das Praias, considerada a prova de regularidade mais tradicional do Brasil. <strong>A 46\u00aa edi\u00e7\u00e3o do evento ocorre neste s\u00e1bado (22) e integra a primeira etapa da VII Copa Ga\u00facha de Rallye de Regularidade Hist\u00f3rica &#8211; Trof\u00e9u Oscar Leke, al\u00e9m de contar com a competi\u00e7\u00e3o Rallye 4&#215;4 \u2013 Adventure.<\/strong> O evento leva o nome do piloto Luciano Santos e conta com apoio da Prefeitura de Imb\u00e9, por meio da Secretaria Municipal de Turismo (SETUR).<\/p>\n\n\n\n<p>Promovido pelo Clube Porto Alegre de Rallye, o evento tem a supervis\u00e3o da Federa\u00e7\u00e3o Brasileira de Ve\u00edculos Antigos (FBVA) e da Federa\u00e7\u00e3o Ga\u00facha de Automobilismo (FGA). <em>A competi\u00e7\u00e3o se desenrolar\u00e1 em um percurso aproximado de 250 km, atravessando diversas cidades do Litoral Norte, entre elas Tramanda\u00ed, Os\u00f3rio, Maquin\u00e9, Cap\u00e3o da Canoa, Arroio do Sal, Tr\u00eas Forquilhas e Itati.<\/em><\/p>\n\n\n\n<p>Na quinta-feira (20), o presidente do Clube Porto Alegre de Rallye, Fernando Bittencourt, esteve no Centro Administrativo de Imb\u00e9, onde se reuniu com o Prefeito Ique Vedovato, o Vice-Prefeito R\u00e9gis Cacetinho e o titular da SETUR, Adriano Pacheco, para tratar dos \u00faltimos detalhes do evento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Prova e categorias<\/h3>\n\n\n\n<p><em>A competi\u00e7\u00e3o contar\u00e1 com diversas categorias, incluindo Cl\u00e1ssicos I (ve\u00edculos fabricados at\u00e9 1970), Cl\u00e1ssicos II (1971 a 1995), APP (ve\u00edculos fabricados at\u00e9 2000) e Turismo (ve\u00edculos fabricados at\u00e9 2005). Tamb\u00e9m ser\u00e1 disputada a categoria Rallye 4&#215;4 Adventure, voltada exclusivamente para ve\u00edculos com tra\u00e7\u00e3o integral.<\/em><\/p>\n\n\n\n<p>As inscri\u00e7\u00f5es seguem abertas e podem ser realizadas por meio dos sites\u00a0<a>https:\/\/forms.gle\/rMZcXqXF6FK6GL1T9<\/a>\u00a0ou\u00a0<a>www.americasul4x4.com.br<\/a>. <em>Tamb\u00e9m ser\u00e3o aceitas inscri\u00e7\u00f5es no dia da prova, momentos antes da largada. O valor para participar \u00e9 de R$ 385,00, incluindo o seguro obrigat\u00f3rio. <\/em>Integrantes do Clube Porto Alegre de Rallye t\u00eam direito a desconto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Programa\u00e7\u00e3o e impacto local<\/h3>\n\n\n\n<p><strong>A largada do primeiro carro est\u00e1 marcada para as 10h na Pra\u00e7a Lourdes Rodrigues, no Centro de Imb\u00e9, pr\u00f3ximo \u00e0 orla. O t\u00e9rmino da prova est\u00e1 previsto para \u00e0s 17h, no mesmo local, seguido da solenidade de premia\u00e7\u00e3o.<\/strong><\/p>\n\n\n\n<p>Al\u00e9m da competi\u00e7\u00e3o, o evento promove uma campanha social de arrecada\u00e7\u00e3o de alimentos. <em>Cada dupla participante dever\u00e1 doar 5 kg de alimentos n\u00e3o perec\u00edveis, que ser\u00e3o destinados a fam\u00edlias em situa\u00e7\u00e3o de vulnerabilidade no munic\u00edpio.<\/em><\/p>\n\n\n\n<p>Para garantir a seguran\u00e7a e a transpar\u00eancia do Rallye das Praias, a organiza\u00e7\u00e3o fornecer\u00e1 um Seguro de Responsabilidade Civil, al\u00e9m de seguir os regulamentos estabelecidos pela FBVA e FGA. Mais informa\u00e7\u00f5es podem ser obtidas atrav\u00e9s do telefone (51) 99636-2626.<\/p>\n\n\n\n<div id=\"wp-block-themeisle-blocks-slider-ceb0d7ab\" class=\"wp-block-themeisle-blocks-slider glide\" data-per-view=\"1\" data-gap=\"0\" data-peek=\"0\" data-autoplay=\"true\" data-height=\"400px\" data-hide-arrows=\"false\"><div class=\"glide__track\" data-glide-el=\"track\"><div class=\"glide__slides\"><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/03\/Imbe-sedia-o-46o-Rallye-das-Praias-neste-sabado-Marcio-Sarda-1.jpg\" alt=\"\" title=\"\" data-id=\"8210\"\/><figcaption>Foto: Marcio Sarda<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/03\/Imbe-sedia-o-46o-Rallye-das-Praias-neste-sabado-Marcio-Sarda-2.jpg\" alt=\"\" title=\"\" data-id=\"8211\"\/><figcaption>Foto: Marcio Sarda<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/03\/Imbe-sedia-o-46o-Rallye-das-Praias-neste-sabado-Marcio-Sarda-3-scaled.jpg\" alt=\"\" title=\"\" data-id=\"8212\"\/><figcaption>Foto: Marcio Sarda<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/03\/Imbe-sedia-o-46o-Rallye-das-Praias-neste-sabado-Marcio-Sarda-4-scaled.jpg\" alt=\"\" title=\"\" data-id=\"8213\"\/><figcaption>Foto: Marcio Sarda<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/03\/Imbe-sedia-o-46o-Rallye-das-Praias-neste-sabado-Jose-Luiz-Filho.jpg\" alt=\"\" title=\"\" data-id=\"8209\"\/><figcaption>Foto: Jos\u00e9 Luiz Filho<\/figcaption><\/figure><\/div><\/div><div class=\"glide__bullets\" data-glide-el=\"controls[nav]\"><button class=\"glide__bullet\" data-glide-dir=\"=0\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=1\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=2\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=3\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=4\"><\/button><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A cidade de Imb\u00e9 ser\u00e1, pelo segundo ano consecutivo, o ponto de partida do Rallye das Praias, considerada a prova de regularidade mais tradicional do Brasil. A 46\u00aa edi\u00e7\u00e3o do evento ocorre neste s\u00e1bado (22) e integra a primeira etapa da VII Copa Ga\u00facha de Rallye de Regularidade Hist\u00f3rica &#8211; Trof\u00e9u Oscar Leke, al\u00e9m de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":8214,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[14,30,15],"tags":[289,290,103,257],"class_list":["post-8208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes","category-imbe","category-noticias","tag-esporte","tag-imbe-2","tag-litoral-norte","tag-noticia-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Imb\u00e9 recebe a 46\u00aa edi\u00e7\u00e3o do Rallye das Praias neste s\u00e1bado - Rede Litoral RS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redelitoralrs.com\/index.php\/2025\/03\/20\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Imb\u00e9 recebe a 46\u00aa edi\u00e7\u00e3o do Rallye das Praias neste s\u00e1bado - Rede Litoral RS\" \/>\n<meta property=\"og:description\" content=\"A cidade de Imb\u00e9 ser\u00e1, pelo segundo ano consecutivo, o ponto de partida do Rallye das Praias, considerada a prova de regularidade mais tradicional do Brasil. A 46\u00aa edi\u00e7\u00e3o do evento ocorre neste s\u00e1bado (22) e integra a primeira etapa da VII Copa Ga\u00facha de Rallye de Regularidade Hist\u00f3rica &#8211; Trof\u00e9u Oscar Leke, al\u00e9m de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redelitoralrs.com\/index.php\/2025\/03\/20\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\/\" \/>\n<meta property=\"og:site_name\" content=\"Rede Litoral RS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tvlitoralrsoficial\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-20T20:49:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-20T21:00:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/03\/Imbe-sedia-o-46o-Rallye-das-Praias-neste-sabado-Marcio-Sarda-5-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1711\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bruna Soares\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruna Soares\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/03\\\/20\\\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/03\\\/20\\\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\\\/\"},\"author\":{\"name\":\"Bruna Soares\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9b64a31a9ab963d5e7d10a2c1df63662\"},\"headline\":\"Imb\u00e9 recebe a 46\u00aa edi\u00e7\u00e3o do Rallye das Praias neste s\u00e1bado\",\"datePublished\":\"2025-03-20T20:49:04+00:00\",\"dateModified\":\"2025-03-20T21:00:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/03\\\/20\\\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\\\/\"},\"wordCount\":479,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/03\\\/20\\\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Imbe-sedia-o-46o-Rallye-das-Praias-neste-sabado-Marcio-Sarda-5-scaled.jpg\",\"keywords\":[\"esporte\",\"imbe\",\"litoral norte\",\"noticia\"],\"articleSection\":[\"Esportes\",\"Imb\u00e9\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/03\\\/20\\\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/03\\\/20\\\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/03\\\/20\\\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\\\/\",\"name\":\"Imb\u00e9 recebe a 46\u00aa edi\u00e7\u00e3o do Rallye das Praias neste s\u00e1bado - Rede Litoral RS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/03\\\/20\\\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/03\\\/20\\\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Imbe-sedia-o-46o-Rallye-das-Praias-neste-sabado-Marcio-Sarda-5-scaled.jpg\",\"datePublished\":\"2025-03-20T20:49:04+00:00\",\"dateModified\":\"2025-03-20T21:00:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/03\\\/20\\\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/03\\\/20\\\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/03\\\/20\\\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Imbe-sedia-o-46o-Rallye-das-Praias-neste-sabado-Marcio-Sarda-5-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Imbe-sedia-o-46o-Rallye-das-Praias-neste-sabado-Marcio-Sarda-5-scaled.jpg\",\"width\":2560,\"height\":1711,\"caption\":\"Foto: Marcio Sarda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/03\\\/20\\\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/redelitoralrs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Imb\u00e9 recebe a 46\u00aa edi\u00e7\u00e3o do Rallye das Praias neste s\u00e1bado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"name\":\"TV Litoral\",\"description\":\"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redelitoralrs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\",\"name\":\"TV Litoral\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"width\":454,\"height\":454,\"caption\":\"TV Litoral\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tvlitoralrsoficial\",\"https:\\\/\\\/www.instagram.com\\\/tvlitoral.rs\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9b64a31a9ab963d5e7d10a2c1df63662\",\"name\":\"Bruna Soares\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/f4bcd7653f65cbf6c8784d5426c4bb54.jpg?ver=1783614026\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/f4bcd7653f65cbf6c8784d5426c4bb54.jpg?ver=1783614026\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/f4bcd7653f65cbf6c8784d5426c4bb54.jpg?ver=1783614026\",\"caption\":\"Bruna Soares\"},\"description\":\"Rela\u00e7\u00f5es-P\u00fablicas (CONRERP4 RS\\\/SC 4053), apaixonada por comunica\u00e7\u00e3o e esportes, \u00e9 estudante de Jornalismo pela Unisinos (RS). Especialista em Preven\u00e7\u00e3o e Gerenciamento de Crises, estuda a Intelig\u00eancia Digital e os Novos Ambientes Comunicacionais; \u00e9 Jornalista de Futebol pela Universidade do Futebol (SP).\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/bruunasoarees\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/bruunasoarees\\\/\"],\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/author\\\/bruna-soares\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Imb\u00e9 recebe a 46\u00aa edi\u00e7\u00e3o do Rallye das Praias neste s\u00e1bado - Rede Litoral RS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redelitoralrs.com\/index.php\/2025\/03\/20\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\/","og_locale":"pt_BR","og_type":"article","og_title":"Imb\u00e9 recebe a 46\u00aa edi\u00e7\u00e3o do Rallye das Praias neste s\u00e1bado - Rede Litoral RS","og_description":"A cidade de Imb\u00e9 ser\u00e1, pelo segundo ano consecutivo, o ponto de partida do Rallye das Praias, considerada a prova de regularidade mais tradicional do Brasil. A 46\u00aa edi\u00e7\u00e3o do evento ocorre neste s\u00e1bado (22) e integra a primeira etapa da VII Copa Ga\u00facha de Rallye de Regularidade Hist\u00f3rica &#8211; Trof\u00e9u Oscar Leke, al\u00e9m de [&hellip;]","og_url":"https:\/\/redelitoralrs.com\/index.php\/2025\/03\/20\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\/","og_site_name":"Rede Litoral RS","article_publisher":"https:\/\/www.facebook.com\/tvlitoralrsoficial","article_published_time":"2025-03-20T20:49:04+00:00","article_modified_time":"2025-03-20T21:00:03+00:00","og_image":[{"width":2560,"height":1711,"url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/03\/Imbe-sedia-o-46o-Rallye-das-Praias-neste-sabado-Marcio-Sarda-5-scaled.jpg","type":"image\/jpeg"}],"author":"Bruna Soares","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Bruna Soares","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/03\/20\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\/#article","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/03\/20\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\/"},"author":{"name":"Bruna Soares","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9b64a31a9ab963d5e7d10a2c1df63662"},"headline":"Imb\u00e9 recebe a 46\u00aa edi\u00e7\u00e3o do Rallye das Praias neste s\u00e1bado","datePublished":"2025-03-20T20:49:04+00:00","dateModified":"2025-03-20T21:00:03+00:00","mainEntityOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/03\/20\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\/"},"wordCount":479,"commentCount":0,"publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/03\/20\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/03\/Imbe-sedia-o-46o-Rallye-das-Praias-neste-sabado-Marcio-Sarda-5-scaled.jpg","keywords":["esporte","imbe","litoral norte","noticia"],"articleSection":["Esportes","Imb\u00e9","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/03\/20\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/03\/20\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\/","url":"https:\/\/redelitoralrs.com\/index.php\/2025\/03\/20\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\/","name":"Imb\u00e9 recebe a 46\u00aa edi\u00e7\u00e3o do Rallye das Praias neste s\u00e1bado - Rede Litoral RS","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/03\/20\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\/#primaryimage"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/03\/20\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/03\/Imbe-sedia-o-46o-Rallye-das-Praias-neste-sabado-Marcio-Sarda-5-scaled.jpg","datePublished":"2025-03-20T20:49:04+00:00","dateModified":"2025-03-20T21:00:03+00:00","breadcrumb":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/03\/20\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/03\/20\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/03\/20\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\/#primaryimage","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/03\/Imbe-sedia-o-46o-Rallye-das-Praias-neste-sabado-Marcio-Sarda-5-scaled.jpg","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/03\/Imbe-sedia-o-46o-Rallye-das-Praias-neste-sabado-Marcio-Sarda-5-scaled.jpg","width":2560,"height":1711,"caption":"Foto: Marcio Sarda"},{"@type":"BreadcrumbList","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/03\/20\/imbe-recebe-a-46a-edicao-do-rallye-das-praias-neste-sabado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/redelitoralrs.com\/"},{"@type":"ListItem","position":2,"name":"Imb\u00e9 recebe a 46\u00aa edi\u00e7\u00e3o do Rallye das Praias neste s\u00e1bado"}]},{"@type":"WebSite","@id":"https:\/\/redelitoralrs.com\/#website","url":"https:\/\/redelitoralrs.com\/","name":"TV Litoral","description":"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.","publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redelitoralrs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redelitoralrs.com\/#organization","name":"TV Litoral","url":"https:\/\/redelitoralrs.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","width":454,"height":454,"caption":"TV Litoral"},"image":{"@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tvlitoralrsoficial","https:\/\/www.instagram.com\/tvlitoral.rs"]},{"@type":"Person","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9b64a31a9ab963d5e7d10a2c1df63662","name":"Bruna Soares","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/f4bcd7653f65cbf6c8784d5426c4bb54.jpg?ver=1783614026","url":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/f4bcd7653f65cbf6c8784d5426c4bb54.jpg?ver=1783614026","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/f4bcd7653f65cbf6c8784d5426c4bb54.jpg?ver=1783614026","caption":"Bruna Soares"},"description":"Rela\u00e7\u00f5es-P\u00fablicas (CONRERP4 RS\/SC 4053), apaixonada por comunica\u00e7\u00e3o e esportes, \u00e9 estudante de Jornalismo pela Unisinos (RS). Especialista em Preven\u00e7\u00e3o e Gerenciamento de Crises, estuda a Intelig\u00eancia Digital e os Novos Ambientes Comunicacionais; \u00e9 Jornalista de Futebol pela Universidade do Futebol (SP).","sameAs":["https:\/\/www.instagram.com\/bruunasoarees\/","https:\/\/www.linkedin.com\/in\/bruunasoarees\/"],"url":"https:\/\/redelitoralrs.com\/index.php\/author\/bruna-soares\/"}]}},"_links":{"self":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/8208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/comments?post=8208"}],"version-history":[{"count":2,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/8208\/revisions"}],"predecessor-version":[{"id":8217,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/8208\/revisions\/8217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media\/8214"}],"wp:attachment":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media?parent=8208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/categories?post=8208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/tags?post=8208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}