{"id":6522,"date":"2025-02-14T13:13:54","date_gmt":"2025-02-14T16:13:54","guid":{"rendered":"https:\/\/redelitoralrs.com\/?p=6522"},"modified":"2025-02-14T13:15:58","modified_gmt":"2025-02-14T16:15:58","slug":"incendio-no-beira-rio-e-controlado-sem-danos-graves","status":"publish","type":"post","link":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/14\/incendio-no-beira-rio-e-controlado-sem-danos-graves\/","title":{"rendered":"Inc\u00eandio no Beira-Rio \u00e9 controlado sem danos graves"},"content":{"rendered":"\n<p>Na manh\u00e3 desta sexta-feira (14), um inc\u00eandio atingiu a \u00e1rea de tribunas sul do Est\u00e1dio Beira-Rio, pr\u00f3ximo ao port\u00e3o 7 e ao Conselho Deliberativo do clube. O fogo teve in\u00edcio em uma \u00e1rea recentemente constru\u00edda para eventos e reuni\u00f5es, localizada acima do setor ocupado pela torcida Guarda Popular. O espa\u00e7o conta com uma estrutura de lazer, incluindo uma parrilla para churrasco, onde se acredita que as chamas tenham come\u00e7ado.<\/p>\n\n\n\n<p>Testemunhas que estavam no local pela manh\u00e3 relataram que o fogo foi rapidamente identificado, permitindo uma resposta eficaz dos bombeiros, que impediram sua propaga\u00e7\u00e3o para outras partes do est\u00e1dio. N\u00e3o houve v\u00edtimas e os danos estruturais foram considerados m\u00ednimos. Segundo os bombeiros que atenderam a ocorr\u00eancia, o incidente gerou mais fuma\u00e7a do que fogo.<\/p>\n\n\n\n<p>As causas ainda est\u00e3o sendo investigadas, mas a principal suspeita \u00e9 de que uma brasa residual de carv\u00e3o tenha provocado o inc\u00eandio, uma vez que no dia anterior houve uma confraterniza\u00e7\u00e3o no local.<\/p>\n\n\n\n<p>A administra\u00e7\u00e3o do clube afirmou que, devido aos danos limitados, o incidente n\u00e3o comprometer\u00e1 a partida contra o Monsoon, marcada para \u00e0s 16h30min deste s\u00e1bado, pela \u00faltima rodada da fase de grupos do Gauch\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"432\" data-id=\"6524\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/Design-sem-nome-3-2-768x432-1.jpg\" alt=\"\" class=\"wp-image-6524\" srcset=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/Design-sem-nome-3-2-768x432-1.jpg 768w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/Design-sem-nome-3-2-768x432-1-300x169.jpg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Foto: Divulga\u00e7\u00e3o CBMRS<\/figcaption><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Na manh\u00e3 desta sexta-feira (14), um inc\u00eandio atingiu a \u00e1rea de tribunas sul do Est\u00e1dio Beira-Rio, pr\u00f3ximo ao port\u00e3o 7 e ao Conselho Deliberativo do clube. O fogo teve in\u00edcio em uma \u00e1rea recentemente constru\u00edda para eventos e reuni\u00f5es, localizada acima do setor ocupado pela torcida Guarda Popular. O espa\u00e7o conta com uma estrutura de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":6523,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[50,15],"tags":[],"class_list":["post-6522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inter","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inc\u00eandio no Beira-Rio \u00e9 controlado sem danos graves - Rede Litoral RS<\/title>\n<meta name=\"description\" content=\"Na manh\u00e3 desta sexta-feira (14), um inc\u00eandio atingiu a \u00e1rea de tribunas sul do Est\u00e1dio Beira-Rio, pr\u00f3ximo ao port\u00e3o 7 e ao Conselho Deliberativo do clube. O fogo teve in\u00edcio em uma \u00e1rea recentemente constru\u00edda para eventos e reuni\u00f5es, localizada acima do setor ocupado pela torcida Guarda Popular. O espa\u00e7o conta com uma estrutura de lazer, incluindo uma parrilla para churrasco, onde se acredita que as chamas tenham come\u00e7ado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/14\/incendio-no-beira-rio-e-controlado-sem-danos-graves\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inc\u00eandio no Beira-Rio \u00e9 controlado sem danos graves - Rede Litoral RS\" \/>\n<meta property=\"og:description\" content=\"Na manh\u00e3 desta sexta-feira (14), um inc\u00eandio atingiu a \u00e1rea de tribunas sul do Est\u00e1dio Beira-Rio, pr\u00f3ximo ao port\u00e3o 7 e ao Conselho Deliberativo do clube. O fogo teve in\u00edcio em uma \u00e1rea recentemente constru\u00edda para eventos e reuni\u00f5es, localizada acima do setor ocupado pela torcida Guarda Popular. O espa\u00e7o conta com uma estrutura de lazer, incluindo uma parrilla para churrasco, onde se acredita que as chamas tenham come\u00e7ado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/14\/incendio-no-beira-rio-e-controlado-sem-danos-graves\/\" \/>\n<meta property=\"og:site_name\" content=\"Rede Litoral RS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tvlitoralrsoficial\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-14T16:13:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-14T16:15:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-14-at-08.57.16.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"899\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Bruna Soares\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruna Soares\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/14\\\/incendio-no-beira-rio-e-controlado-sem-danos-graves\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/14\\\/incendio-no-beira-rio-e-controlado-sem-danos-graves\\\/\"},\"author\":{\"name\":\"Bruna Soares\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9b64a31a9ab963d5e7d10a2c1df63662\"},\"headline\":\"Inc\u00eandio no Beira-Rio \u00e9 controlado sem danos graves\",\"datePublished\":\"2025-02-14T16:13:54+00:00\",\"dateModified\":\"2025-02-14T16:15:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/14\\\/incendio-no-beira-rio-e-controlado-sem-danos-graves\\\/\"},\"wordCount\":224,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/14\\\/incendio-no-beira-rio-e-controlado-sem-danos-graves\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/WhatsApp-Image-2025-02-14-at-08.57.16.webp\",\"articleSection\":[\"Inter\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/14\\\/incendio-no-beira-rio-e-controlado-sem-danos-graves\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/14\\\/incendio-no-beira-rio-e-controlado-sem-danos-graves\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/14\\\/incendio-no-beira-rio-e-controlado-sem-danos-graves\\\/\",\"name\":\"Inc\u00eandio no Beira-Rio \u00e9 controlado sem danos graves - Rede Litoral RS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/14\\\/incendio-no-beira-rio-e-controlado-sem-danos-graves\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/14\\\/incendio-no-beira-rio-e-controlado-sem-danos-graves\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/WhatsApp-Image-2025-02-14-at-08.57.16.webp\",\"datePublished\":\"2025-02-14T16:13:54+00:00\",\"dateModified\":\"2025-02-14T16:15:58+00:00\",\"description\":\"Na manh\u00e3 desta sexta-feira (14), um inc\u00eandio atingiu a \u00e1rea de tribunas sul do Est\u00e1dio Beira-Rio, pr\u00f3ximo ao port\u00e3o 7 e ao Conselho Deliberativo do clube. O fogo teve in\u00edcio em uma \u00e1rea recentemente constru\u00edda para eventos e reuni\u00f5es, localizada acima do setor ocupado pela torcida Guarda Popular. O espa\u00e7o conta com uma estrutura de lazer, incluindo uma parrilla para churrasco, onde se acredita que as chamas tenham come\u00e7ado.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/14\\\/incendio-no-beira-rio-e-controlado-sem-danos-graves\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/14\\\/incendio-no-beira-rio-e-controlado-sem-danos-graves\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/14\\\/incendio-no-beira-rio-e-controlado-sem-danos-graves\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/WhatsApp-Image-2025-02-14-at-08.57.16.webp\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/WhatsApp-Image-2025-02-14-at-08.57.16.webp\",\"width\":1600,\"height\":899,\"caption\":\"Foto: Divulga\u00e7\u00e3o CBMRS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/14\\\/incendio-no-beira-rio-e-controlado-sem-danos-graves\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/redelitoralrs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inc\u00eandio no Beira-Rio \u00e9 controlado sem danos graves\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"name\":\"TV Litoral\",\"description\":\"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redelitoralrs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\",\"name\":\"TV Litoral\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"width\":454,\"height\":454,\"caption\":\"TV Litoral\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tvlitoralrsoficial\",\"https:\\\/\\\/www.instagram.com\\\/tvlitoral.rs\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9b64a31a9ab963d5e7d10a2c1df63662\",\"name\":\"Bruna Soares\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/f4bcd7653f65cbf6c8784d5426c4bb54.jpg?ver=1783614026\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/f4bcd7653f65cbf6c8784d5426c4bb54.jpg?ver=1783614026\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/f4bcd7653f65cbf6c8784d5426c4bb54.jpg?ver=1783614026\",\"caption\":\"Bruna Soares\"},\"description\":\"Rela\u00e7\u00f5es-P\u00fablicas (CONRERP4 RS\\\/SC 4053), apaixonada por comunica\u00e7\u00e3o e esportes, \u00e9 estudante de Jornalismo pela Unisinos (RS). Especialista em Preven\u00e7\u00e3o e Gerenciamento de Crises, estuda a Intelig\u00eancia Digital e os Novos Ambientes Comunicacionais; \u00e9 Jornalista de Futebol pela Universidade do Futebol (SP).\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/bruunasoarees\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/bruunasoarees\\\/\"],\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/author\\\/bruna-soares\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inc\u00eandio no Beira-Rio \u00e9 controlado sem danos graves - Rede Litoral RS","description":"Na manh\u00e3 desta sexta-feira (14), um inc\u00eandio atingiu a \u00e1rea de tribunas sul do Est\u00e1dio Beira-Rio, pr\u00f3ximo ao port\u00e3o 7 e ao Conselho Deliberativo do clube. O fogo teve in\u00edcio em uma \u00e1rea recentemente constru\u00edda para eventos e reuni\u00f5es, localizada acima do setor ocupado pela torcida Guarda Popular. O espa\u00e7o conta com uma estrutura de lazer, incluindo uma parrilla para churrasco, onde se acredita que as chamas tenham come\u00e7ado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/14\/incendio-no-beira-rio-e-controlado-sem-danos-graves\/","og_locale":"pt_BR","og_type":"article","og_title":"Inc\u00eandio no Beira-Rio \u00e9 controlado sem danos graves - Rede Litoral RS","og_description":"Na manh\u00e3 desta sexta-feira (14), um inc\u00eandio atingiu a \u00e1rea de tribunas sul do Est\u00e1dio Beira-Rio, pr\u00f3ximo ao port\u00e3o 7 e ao Conselho Deliberativo do clube. O fogo teve in\u00edcio em uma \u00e1rea recentemente constru\u00edda para eventos e reuni\u00f5es, localizada acima do setor ocupado pela torcida Guarda Popular. O espa\u00e7o conta com uma estrutura de lazer, incluindo uma parrilla para churrasco, onde se acredita que as chamas tenham come\u00e7ado.","og_url":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/14\/incendio-no-beira-rio-e-controlado-sem-danos-graves\/","og_site_name":"Rede Litoral RS","article_publisher":"https:\/\/www.facebook.com\/tvlitoralrsoficial","article_published_time":"2025-02-14T16:13:54+00:00","article_modified_time":"2025-02-14T16:15:58+00:00","og_image":[{"width":1600,"height":899,"url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-14-at-08.57.16.webp","type":"image\/webp"}],"author":"Bruna Soares","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Bruna Soares","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/14\/incendio-no-beira-rio-e-controlado-sem-danos-graves\/#article","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/14\/incendio-no-beira-rio-e-controlado-sem-danos-graves\/"},"author":{"name":"Bruna Soares","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9b64a31a9ab963d5e7d10a2c1df63662"},"headline":"Inc\u00eandio no Beira-Rio \u00e9 controlado sem danos graves","datePublished":"2025-02-14T16:13:54+00:00","dateModified":"2025-02-14T16:15:58+00:00","mainEntityOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/14\/incendio-no-beira-rio-e-controlado-sem-danos-graves\/"},"wordCount":224,"commentCount":0,"publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/14\/incendio-no-beira-rio-e-controlado-sem-danos-graves\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-14-at-08.57.16.webp","articleSection":["Inter","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/02\/14\/incendio-no-beira-rio-e-controlado-sem-danos-graves\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/14\/incendio-no-beira-rio-e-controlado-sem-danos-graves\/","url":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/14\/incendio-no-beira-rio-e-controlado-sem-danos-graves\/","name":"Inc\u00eandio no Beira-Rio \u00e9 controlado sem danos graves - Rede Litoral RS","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/14\/incendio-no-beira-rio-e-controlado-sem-danos-graves\/#primaryimage"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/14\/incendio-no-beira-rio-e-controlado-sem-danos-graves\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-14-at-08.57.16.webp","datePublished":"2025-02-14T16:13:54+00:00","dateModified":"2025-02-14T16:15:58+00:00","description":"Na manh\u00e3 desta sexta-feira (14), um inc\u00eandio atingiu a \u00e1rea de tribunas sul do Est\u00e1dio Beira-Rio, pr\u00f3ximo ao port\u00e3o 7 e ao Conselho Deliberativo do clube. O fogo teve in\u00edcio em uma \u00e1rea recentemente constru\u00edda para eventos e reuni\u00f5es, localizada acima do setor ocupado pela torcida Guarda Popular. O espa\u00e7o conta com uma estrutura de lazer, incluindo uma parrilla para churrasco, onde se acredita que as chamas tenham come\u00e7ado.","breadcrumb":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/14\/incendio-no-beira-rio-e-controlado-sem-danos-graves\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/02\/14\/incendio-no-beira-rio-e-controlado-sem-danos-graves\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/14\/incendio-no-beira-rio-e-controlado-sem-danos-graves\/#primaryimage","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-14-at-08.57.16.webp","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-14-at-08.57.16.webp","width":1600,"height":899,"caption":"Foto: Divulga\u00e7\u00e3o CBMRS"},{"@type":"BreadcrumbList","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/14\/incendio-no-beira-rio-e-controlado-sem-danos-graves\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/redelitoralrs.com\/"},{"@type":"ListItem","position":2,"name":"Inc\u00eandio no Beira-Rio \u00e9 controlado sem danos graves"}]},{"@type":"WebSite","@id":"https:\/\/redelitoralrs.com\/#website","url":"https:\/\/redelitoralrs.com\/","name":"TV Litoral","description":"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.","publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redelitoralrs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redelitoralrs.com\/#organization","name":"TV Litoral","url":"https:\/\/redelitoralrs.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","width":454,"height":454,"caption":"TV Litoral"},"image":{"@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tvlitoralrsoficial","https:\/\/www.instagram.com\/tvlitoral.rs"]},{"@type":"Person","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9b64a31a9ab963d5e7d10a2c1df63662","name":"Bruna Soares","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/f4bcd7653f65cbf6c8784d5426c4bb54.jpg?ver=1783614026","url":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/f4bcd7653f65cbf6c8784d5426c4bb54.jpg?ver=1783614026","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/f4bcd7653f65cbf6c8784d5426c4bb54.jpg?ver=1783614026","caption":"Bruna Soares"},"description":"Rela\u00e7\u00f5es-P\u00fablicas (CONRERP4 RS\/SC 4053), apaixonada por comunica\u00e7\u00e3o e esportes, \u00e9 estudante de Jornalismo pela Unisinos (RS). Especialista em Preven\u00e7\u00e3o e Gerenciamento de Crises, estuda a Intelig\u00eancia Digital e os Novos Ambientes Comunicacionais; \u00e9 Jornalista de Futebol pela Universidade do Futebol (SP).","sameAs":["https:\/\/www.instagram.com\/bruunasoarees\/","https:\/\/www.linkedin.com\/in\/bruunasoarees\/"],"url":"https:\/\/redelitoralrs.com\/index.php\/author\/bruna-soares\/"}]}},"_links":{"self":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/6522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/comments?post=6522"}],"version-history":[{"count":1,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/6522\/revisions"}],"predecessor-version":[{"id":6525,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/6522\/revisions\/6525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media\/6523"}],"wp:attachment":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media?parent=6522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/categories?post=6522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/tags?post=6522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}