{"id":6110,"date":"2025-02-06T14:47:52","date_gmt":"2025-02-06T17:47:52","guid":{"rendered":"https:\/\/redelitoralrs.com\/?p=6110"},"modified":"2025-02-06T14:48:00","modified_gmt":"2025-02-06T17:48:00","slug":"mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai","status":"publish","type":"post","link":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\/","title":{"rendered":"MPF e MPRS solicitam anula\u00e7\u00e3o de licen\u00e7a para lan\u00e7amento de efluentes no Rio Tramanda\u00ed"},"content":{"rendered":"\n<p>O Minist\u00e9rio P\u00fablico Federal (MPF) e o Minist\u00e9rio P\u00fablico do Estado do Rio Grande do Sul (MPRS) ingressaram com uma a\u00e7\u00e3o civil p\u00fablica pedindo a anula\u00e7\u00e3o da licen\u00e7a pr\u00e9via que autoriza o lan\u00e7amento de efluentes tratados no Rio Tramanda\u00ed, no Litoral Norte ga\u00facho. A medida visa suspender o projeto que prev\u00ea o despejo de esgoto tratado proveniente dos munic\u00edpios de Xangri-l\u00e1 e Cap\u00e3o da Canoa no curso do rio.<\/p>\n\n\n\n<p>A a\u00e7\u00e3o acolhe um requerimento do Movimento Unificado em Defesa do Litoral Norte (Mov\/LN), apresentado em agosto de 2024, que solicitava a suspens\u00e3o imediata da constru\u00e7\u00e3o do emiss\u00e1rio lagunar de efluentes desses munic\u00edpios para despejo na Bacia Hidrogr\u00e1fica do Rio Tramanda\u00ed. Estudos preliminares realizados pela per\u00edcia t\u00e9cnica do MPF apontaram a falta de dados essenciais, gerando incertezas na calibra\u00e7\u00e3o dos modelos hidrodin\u00e2micos e de qualidade da \u00e1gua, o que compromete a confiabilidade da proposta. \ufffc<\/p>\n\n\n\n<p>Al\u00e9m da anula\u00e7\u00e3o da Licen\u00e7a Pr\u00e9via e de Instala\u00e7\u00e3o para Altera\u00e7\u00e3o (LPIA), o MPF e o MPRS solicitam que a Funda\u00e7\u00e3o Estadual de Prote\u00e7\u00e3o Ambiental Henrique Luiz Roessler (Fepam) realize uma nova an\u00e1lise do empreendimento proposto pela Companhia Riograndense de Saneamento (Corsan). Essa an\u00e1lise deve incluir a elabora\u00e7\u00e3o de um Estudo de Impacto Ambiental (EIA\/RIMA) e a realiza\u00e7\u00e3o de audi\u00eancias p\u00fablicas que permitam a participa\u00e7\u00e3o da popula\u00e7\u00e3o local, dos munic\u00edpios afetados, das comunidades ind\u00edgenas e das popula\u00e7\u00f5es ribeirinhas que dependem da pesca artesanal. \ufffc<\/p>\n\n\n\n<p>Em resposta, a Corsan afirmou que confia no licenciamento realizado pela Fepam e que a obra do emiss\u00e1rio, com 21 quil\u00f4metros de extens\u00e3o, iniciada no primeiro semestre do ano passado, est\u00e1 prevista para ser conclu\u00edda em 2025. A companhia garante que todo o esgoto ser\u00e1 tratado com 95% de efici\u00eancia antes de ser lan\u00e7ado no rio. \ufffc<\/p>\n\n\n\n<p>A quest\u00e3o tem gerado debates entre autoridades, especialistas e a comunidade local, que expressam preocupa\u00e7\u00f5es quanto aos poss\u00edveis impactos ambientais e \u00e0 preserva\u00e7\u00e3o dos recursos h\u00eddricos da regi\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"760\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-06-at-00.06.14-1024x760.jpeg\" alt=\"\" class=\"wp-image-6112\" srcset=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-06-at-00.06.14-1024x760.jpeg 1024w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-06-at-00.06.14-300x223.jpeg 300w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-06-at-00.06.14-768x570.jpeg 768w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-06-at-00.06.14.jpeg 1170w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio P\u00fablico Federal (MPF) e o Minist\u00e9rio P\u00fablico do Estado do Rio Grande do Sul (MPRS) ingressaram com uma a\u00e7\u00e3o civil p\u00fablica pedindo a anula\u00e7\u00e3o da licen\u00e7a pr\u00e9via que autoriza o lan\u00e7amento de efluentes tratados no Rio Tramanda\u00ed, no Litoral Norte ga\u00facho. A medida visa suspender o projeto que prev\u00ea o despejo de esgoto [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6111,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[20],"tags":[],"class_list":["post-6110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-litoral_norte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MPF e MPRS solicitam anula\u00e7\u00e3o de licen\u00e7a para lan\u00e7amento de efluentes no Rio Tramanda\u00ed<\/title>\n<meta name=\"description\" content=\"O Minist\u00e9rio P\u00fablico Federal (MPF) e o Minist\u00e9rio P\u00fablico do Estado do Rio Grande do Sul (MPRS) ingressaram com uma a\u00e7\u00e3o civil p\u00fablica pedindo a anula\u00e7\u00e3o da licen\u00e7a pr\u00e9via que autoriza o lan\u00e7amento de efluentes tratados no Rio Tramanda\u00ed, no Litoral Norte ga\u00facho. A medida visa suspender o projeto que prev\u00ea o despejo de esgoto tratado proveniente dos munic\u00edpios de Xangri-l\u00e1 e Cap\u00e3o da Canoa no curso do rio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MPF e MPRS solicitam anula\u00e7\u00e3o de licen\u00e7a para lan\u00e7amento de efluentes no Rio Tramanda\u00ed\" \/>\n<meta property=\"og:description\" content=\"O Minist\u00e9rio P\u00fablico Federal (MPF) e o Minist\u00e9rio P\u00fablico do Estado do Rio Grande do Sul (MPRS) ingressaram com uma a\u00e7\u00e3o civil p\u00fablica pedindo a anula\u00e7\u00e3o da licen\u00e7a pr\u00e9via que autoriza o lan\u00e7amento de efluentes tratados no Rio Tramanda\u00ed, no Litoral Norte ga\u00facho. A medida visa suspender o projeto que prev\u00ea o despejo de esgoto tratado proveniente dos munic\u00edpios de Xangri-l\u00e1 e Cap\u00e3o da Canoa no curso do rio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\/\" \/>\n<meta property=\"og:site_name\" content=\"Rede Litoral RS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tvlitoralrsoficial\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-06T17:47:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-06T17:48:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-06-at-00.06.14-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"669\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\"},\"headline\":\"MPF e MPRS solicitam anula\u00e7\u00e3o de licen\u00e7a para lan\u00e7amento de efluentes no Rio Tramanda\u00ed\",\"datePublished\":\"2025-02-06T17:47:52+00:00\",\"dateModified\":\"2025-02-06T17:48:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\\\/\"},\"wordCount\":378,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/WhatsApp-Image-2025-02-06-at-00.06.14-1.jpeg\",\"articleSection\":[\"Litoral Norte\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\\\/\",\"name\":\"MPF e MPRS solicitam anula\u00e7\u00e3o de licen\u00e7a para lan\u00e7amento de efluentes no Rio Tramanda\u00ed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/WhatsApp-Image-2025-02-06-at-00.06.14-1.jpeg\",\"datePublished\":\"2025-02-06T17:47:52+00:00\",\"dateModified\":\"2025-02-06T17:48:00+00:00\",\"description\":\"O Minist\u00e9rio P\u00fablico Federal (MPF) e o Minist\u00e9rio P\u00fablico do Estado do Rio Grande do Sul (MPRS) ingressaram com uma a\u00e7\u00e3o civil p\u00fablica pedindo a anula\u00e7\u00e3o da licen\u00e7a pr\u00e9via que autoriza o lan\u00e7amento de efluentes tratados no Rio Tramanda\u00ed, no Litoral Norte ga\u00facho. A medida visa suspender o projeto que prev\u00ea o despejo de esgoto tratado proveniente dos munic\u00edpios de Xangri-l\u00e1 e Cap\u00e3o da Canoa no curso do rio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/WhatsApp-Image-2025-02-06-at-00.06.14-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/WhatsApp-Image-2025-02-06-at-00.06.14-1.jpeg\",\"width\":1170,\"height\":669},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/redelitoralrs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MPF e MPRS solicitam anula\u00e7\u00e3o de licen\u00e7a para lan\u00e7amento de efluentes no Rio Tramanda\u00ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"name\":\"TV Litoral\",\"description\":\"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redelitoralrs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\",\"name\":\"TV Litoral\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"width\":454,\"height\":454,\"caption\":\"TV Litoral\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tvlitoralrsoficial\",\"https:\\\/\\\/www.instagram.com\\\/tvlitoral.rs\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\",\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"caption\":\"Reda\u00e7\u00e3o TV Litoral\"},\"description\":\"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.\",\"sameAs\":[\"https:\\\/\\\/redelitoralrs.com\",\"https:\\\/\\\/www.instagram.com\\\/redelitoralrs\",\"https:\\\/\\\/www.youtube.com\\\/@redelitoralrs\"],\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/author\\\/redacaotvlitoral\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MPF e MPRS solicitam anula\u00e7\u00e3o de licen\u00e7a para lan\u00e7amento de efluentes no Rio Tramanda\u00ed","description":"O Minist\u00e9rio P\u00fablico Federal (MPF) e o Minist\u00e9rio P\u00fablico do Estado do Rio Grande do Sul (MPRS) ingressaram com uma a\u00e7\u00e3o civil p\u00fablica pedindo a anula\u00e7\u00e3o da licen\u00e7a pr\u00e9via que autoriza o lan\u00e7amento de efluentes tratados no Rio Tramanda\u00ed, no Litoral Norte ga\u00facho. A medida visa suspender o projeto que prev\u00ea o despejo de esgoto tratado proveniente dos munic\u00edpios de Xangri-l\u00e1 e Cap\u00e3o da Canoa no curso do rio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\/","og_locale":"pt_BR","og_type":"article","og_title":"MPF e MPRS solicitam anula\u00e7\u00e3o de licen\u00e7a para lan\u00e7amento de efluentes no Rio Tramanda\u00ed","og_description":"O Minist\u00e9rio P\u00fablico Federal (MPF) e o Minist\u00e9rio P\u00fablico do Estado do Rio Grande do Sul (MPRS) ingressaram com uma a\u00e7\u00e3o civil p\u00fablica pedindo a anula\u00e7\u00e3o da licen\u00e7a pr\u00e9via que autoriza o lan\u00e7amento de efluentes tratados no Rio Tramanda\u00ed, no Litoral Norte ga\u00facho. A medida visa suspender o projeto que prev\u00ea o despejo de esgoto tratado proveniente dos munic\u00edpios de Xangri-l\u00e1 e Cap\u00e3o da Canoa no curso do rio.","og_url":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\/","og_site_name":"Rede Litoral RS","article_publisher":"https:\/\/www.facebook.com\/tvlitoralrsoficial","article_published_time":"2025-02-06T17:47:52+00:00","article_modified_time":"2025-02-06T17:48:00+00:00","og_image":[{"width":1170,"height":669,"url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-06-at-00.06.14-1.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o TV Litoral","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o TV Litoral","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\/#article","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\/"},"author":{"name":"Reda\u00e7\u00e3o TV Litoral","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a"},"headline":"MPF e MPRS solicitam anula\u00e7\u00e3o de licen\u00e7a para lan\u00e7amento de efluentes no Rio Tramanda\u00ed","datePublished":"2025-02-06T17:47:52+00:00","dateModified":"2025-02-06T17:48:00+00:00","mainEntityOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\/"},"wordCount":378,"commentCount":0,"publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-06-at-00.06.14-1.jpeg","articleSection":["Litoral Norte"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\/","url":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\/","name":"MPF e MPRS solicitam anula\u00e7\u00e3o de licen\u00e7a para lan\u00e7amento de efluentes no Rio Tramanda\u00ed","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\/#primaryimage"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-06-at-00.06.14-1.jpeg","datePublished":"2025-02-06T17:47:52+00:00","dateModified":"2025-02-06T17:48:00+00:00","description":"O Minist\u00e9rio P\u00fablico Federal (MPF) e o Minist\u00e9rio P\u00fablico do Estado do Rio Grande do Sul (MPRS) ingressaram com uma a\u00e7\u00e3o civil p\u00fablica pedindo a anula\u00e7\u00e3o da licen\u00e7a pr\u00e9via que autoriza o lan\u00e7amento de efluentes tratados no Rio Tramanda\u00ed, no Litoral Norte ga\u00facho. A medida visa suspender o projeto que prev\u00ea o despejo de esgoto tratado proveniente dos munic\u00edpios de Xangri-l\u00e1 e Cap\u00e3o da Canoa no curso do rio.","breadcrumb":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\/#primaryimage","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-06-at-00.06.14-1.jpeg","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-06-at-00.06.14-1.jpeg","width":1170,"height":669},{"@type":"BreadcrumbList","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/mpf-e-mprs-solicitam-anulacao-de-licenca-para-lancamento-de-efluentes-no-rio-tramandai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/redelitoralrs.com\/"},{"@type":"ListItem","position":2,"name":"MPF e MPRS solicitam anula\u00e7\u00e3o de licen\u00e7a para lan\u00e7amento de efluentes no Rio Tramanda\u00ed"}]},{"@type":"WebSite","@id":"https:\/\/redelitoralrs.com\/#website","url":"https:\/\/redelitoralrs.com\/","name":"TV Litoral","description":"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.","publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redelitoralrs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redelitoralrs.com\/#organization","name":"TV Litoral","url":"https:\/\/redelitoralrs.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","width":454,"height":454,"caption":"TV Litoral"},"image":{"@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tvlitoralrsoficial","https:\/\/www.instagram.com\/tvlitoral.rs"]},{"@type":"Person","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a","name":"Reda\u00e7\u00e3o TV Litoral","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","url":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","caption":"Reda\u00e7\u00e3o TV Litoral"},"description":"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.","sameAs":["https:\/\/redelitoralrs.com","https:\/\/www.instagram.com\/redelitoralrs","https:\/\/www.youtube.com\/@redelitoralrs"],"url":"https:\/\/redelitoralrs.com\/index.php\/author\/redacaotvlitoral\/"}]}},"_links":{"self":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/6110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/comments?post=6110"}],"version-history":[{"count":1,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/6110\/revisions"}],"predecessor-version":[{"id":6113,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/6110\/revisions\/6113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media\/6111"}],"wp:attachment":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media?parent=6110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/categories?post=6110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/tags?post=6110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}