{"id":6068,"date":"2025-02-06T12:30:00","date_gmt":"2025-02-06T15:30:00","guid":{"rendered":"https:\/\/redelitoralrs.com\/?p=6068"},"modified":"2025-02-05T17:57:39","modified_gmt":"2025-02-05T20:57:39","slug":"seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira","status":"publish","type":"post","link":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\/","title":{"rendered":"Seletiva Rainha do Sol 2025 acontece neste s\u00e1bado em Cidreira"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Quer brilhar na passarela e disputar pr\u00eamios de at\u00e9 R$ 10 mil na grande final? Ent\u00e3o n\u00e3o perca a seletiva gratuita do concurso Rainha do Sol 2025, que acontece neste s\u00e1bado, 8 de fevereiro, \u00e0s 15h, na Concha Ac\u00fastica de Cidreira.<\/p>\n\n\n\n<p>O concurso \u00e9 aberto para participantes de diversas idades, divididas em categorias:<br>\u2022 Brotinho (4 a 7 anos)<br>\u2022 Broto (8 a 11 anos)<br>\u2022 Teen (12 a 15 anos)<br>\u2022 Adulto (16 a 30 anos)<br>\u2022 Diva (31 a 49 anos)<\/p>\n\n\n\n<p>As inscri\u00e7\u00f5es j\u00e1 est\u00e3o abertas e s\u00e3o totalmente gratuitas!<\/p>\n\n\n\n<p>Os interessados podem solicitar a ficha de inscri\u00e7\u00e3o pelos n\u00fameros:<br>\ud83d\udcf1 (51) 99616-4293<br>\ud83d\udcf1 (51) 99006-1562<br>Ou retirar pessoalmente na Secretaria de Turismo, localizada junto \u00e0 Concha Ac\u00fastica.<\/p>\n\n\n\n<p>Essa \u00e9 uma oportunidade \u00fanica para mostrar seu talento, desfilar em grande estilo e concorrer a incr\u00edveis pr\u00eamios na final. Al\u00e9m disso, o evento promete ser uma experi\u00eancia inesquec\u00edvel, cheia de charme e glamour, para todos os participantes e espectadores.<\/p>\n\n\n\n<p>O concurso \u00e9 uma realiza\u00e7\u00e3o da Crit\u00e9rio Eventos com o apoio da Secretaria de Turismo e Desporto e da Prefeitura Municipal de Cidreira.<\/p>\n\n\n\n<p>Marque na agenda e venha participar deste grande evento que celebra a beleza, o carisma e o talento da nossa regi\u00e3o!<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"964\" height=\"1024\" data-id=\"6069\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/Imagem-do-WhatsApp-de-2025-02-05-as-17.49.48_b9ea42ff-964x1024.jpg\" alt=\"\" class=\"wp-image-6069\" srcset=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/Imagem-do-WhatsApp-de-2025-02-05-as-17.49.48_b9ea42ff-964x1024.jpg 964w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/Imagem-do-WhatsApp-de-2025-02-05-as-17.49.48_b9ea42ff-282x300.jpg 282w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/Imagem-do-WhatsApp-de-2025-02-05-as-17.49.48_b9ea42ff-768x816.jpg 768w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/Imagem-do-WhatsApp-de-2025-02-05-as-17.49.48_b9ea42ff.jpg 1170w\" sizes=\"(max-width: 964px) 100vw, 964px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Quer brilhar na passarela e disputar pr\u00eamios de at\u00e9 R$ 10 mil na grande final? Ent\u00e3o n\u00e3o perca a seletiva gratuita do concurso Rainha do Sol 2025, que acontece neste s\u00e1bado, 8 de fevereiro, \u00e0s 15h, na Concha Ac\u00fastica de Cidreira. O concurso \u00e9 aberto para participantes de diversas idades, divididas em categorias:\u2022 Brotinho (4 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6069,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[176,20,188,15],"tags":[],"class_list":["post-6068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidreira","category-litoral_norte","category-rio-grande-do-sul","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Seletiva Rainha do Sol 2025 acontece neste s\u00e1bado em Cidreira - Rede Litoral RS<\/title>\n<meta name=\"description\" content=\"Quer brilhar na passarela e disputar pr\u00eamios de at\u00e9 R$ 10 mil na grande final? Ent\u00e3o n\u00e3o perca a seletiva gratuita do concurso Rainha do Sol 2025, que acontece neste s\u00e1bado, 8 de fevereiro, \u00e0s 15h, na Concha Ac\u00fastica de Cidreira.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seletiva Rainha do Sol 2025 acontece neste s\u00e1bado em Cidreira - Rede Litoral RS\" \/>\n<meta property=\"og:description\" content=\"Quer brilhar na passarela e disputar pr\u00eamios de at\u00e9 R$ 10 mil na grande final? Ent\u00e3o n\u00e3o perca a seletiva gratuita do concurso Rainha do Sol 2025, que acontece neste s\u00e1bado, 8 de fevereiro, \u00e0s 15h, na Concha Ac\u00fastica de Cidreira.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\/\" \/>\n<meta property=\"og:site_name\" content=\"Rede Litoral RS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tvlitoralrsoficial\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-06T15:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/Imagem-do-WhatsApp-de-2025-02-05-as-17.49.48_b9ea42ff.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"1243\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\"},\"headline\":\"Seletiva Rainha do Sol 2025 acontece neste s\u00e1bado em Cidreira\",\"datePublished\":\"2025-02-06T15:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\\\/\"},\"wordCount\":207,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Imagem-do-WhatsApp-de-2025-02-05-as-17.49.48_b9ea42ff.jpg\",\"articleSection\":[\"Cidreira\",\"Litoral Norte\",\"Rio Grande do Sul\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\\\/\",\"name\":\"Seletiva Rainha do Sol 2025 acontece neste s\u00e1bado em Cidreira - Rede Litoral RS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Imagem-do-WhatsApp-de-2025-02-05-as-17.49.48_b9ea42ff.jpg\",\"datePublished\":\"2025-02-06T15:30:00+00:00\",\"description\":\"Quer brilhar na passarela e disputar pr\u00eamios de at\u00e9 R$ 10 mil na grande final? Ent\u00e3o n\u00e3o perca a seletiva gratuita do concurso Rainha do Sol 2025, que acontece neste s\u00e1bado, 8 de fevereiro, \u00e0s 15h, na Concha Ac\u00fastica de Cidreira.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Imagem-do-WhatsApp-de-2025-02-05-as-17.49.48_b9ea42ff.jpg\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Imagem-do-WhatsApp-de-2025-02-05-as-17.49.48_b9ea42ff.jpg\",\"width\":1170,\"height\":1243},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/02\\\/06\\\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/redelitoralrs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seletiva Rainha do Sol 2025 acontece neste s\u00e1bado em Cidreira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"name\":\"TV Litoral\",\"description\":\"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redelitoralrs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\",\"name\":\"TV Litoral\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"width\":454,\"height\":454,\"caption\":\"TV Litoral\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tvlitoralrsoficial\",\"https:\\\/\\\/www.instagram.com\\\/tvlitoral.rs\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\",\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"caption\":\"Reda\u00e7\u00e3o TV Litoral\"},\"description\":\"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.\",\"sameAs\":[\"https:\\\/\\\/redelitoralrs.com\",\"https:\\\/\\\/www.instagram.com\\\/redelitoralrs\",\"https:\\\/\\\/www.youtube.com\\\/@redelitoralrs\"],\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/author\\\/redacaotvlitoral\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seletiva Rainha do Sol 2025 acontece neste s\u00e1bado em Cidreira - Rede Litoral RS","description":"Quer brilhar na passarela e disputar pr\u00eamios de at\u00e9 R$ 10 mil na grande final? Ent\u00e3o n\u00e3o perca a seletiva gratuita do concurso Rainha do Sol 2025, que acontece neste s\u00e1bado, 8 de fevereiro, \u00e0s 15h, na Concha Ac\u00fastica de Cidreira.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\/","og_locale":"pt_BR","og_type":"article","og_title":"Seletiva Rainha do Sol 2025 acontece neste s\u00e1bado em Cidreira - Rede Litoral RS","og_description":"Quer brilhar na passarela e disputar pr\u00eamios de at\u00e9 R$ 10 mil na grande final? Ent\u00e3o n\u00e3o perca a seletiva gratuita do concurso Rainha do Sol 2025, que acontece neste s\u00e1bado, 8 de fevereiro, \u00e0s 15h, na Concha Ac\u00fastica de Cidreira.","og_url":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\/","og_site_name":"Rede Litoral RS","article_publisher":"https:\/\/www.facebook.com\/tvlitoralrsoficial","article_published_time":"2025-02-06T15:30:00+00:00","og_image":[{"width":1170,"height":1243,"url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/Imagem-do-WhatsApp-de-2025-02-05-as-17.49.48_b9ea42ff.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o TV Litoral","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o TV Litoral","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\/#article","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\/"},"author":{"name":"Reda\u00e7\u00e3o TV Litoral","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a"},"headline":"Seletiva Rainha do Sol 2025 acontece neste s\u00e1bado em Cidreira","datePublished":"2025-02-06T15:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\/"},"wordCount":207,"commentCount":0,"publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/Imagem-do-WhatsApp-de-2025-02-05-as-17.49.48_b9ea42ff.jpg","articleSection":["Cidreira","Litoral Norte","Rio Grande do Sul","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\/","url":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\/","name":"Seletiva Rainha do Sol 2025 acontece neste s\u00e1bado em Cidreira - Rede Litoral RS","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\/#primaryimage"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/Imagem-do-WhatsApp-de-2025-02-05-as-17.49.48_b9ea42ff.jpg","datePublished":"2025-02-06T15:30:00+00:00","description":"Quer brilhar na passarela e disputar pr\u00eamios de at\u00e9 R$ 10 mil na grande final? Ent\u00e3o n\u00e3o perca a seletiva gratuita do concurso Rainha do Sol 2025, que acontece neste s\u00e1bado, 8 de fevereiro, \u00e0s 15h, na Concha Ac\u00fastica de Cidreira.","breadcrumb":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\/#primaryimage","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/Imagem-do-WhatsApp-de-2025-02-05-as-17.49.48_b9ea42ff.jpg","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/02\/Imagem-do-WhatsApp-de-2025-02-05-as-17.49.48_b9ea42ff.jpg","width":1170,"height":1243},{"@type":"BreadcrumbList","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/02\/06\/seletiva-rainha-do-sol-2025-acontece-neste-sabado-em-cidreira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/redelitoralrs.com\/"},{"@type":"ListItem","position":2,"name":"Seletiva Rainha do Sol 2025 acontece neste s\u00e1bado em Cidreira"}]},{"@type":"WebSite","@id":"https:\/\/redelitoralrs.com\/#website","url":"https:\/\/redelitoralrs.com\/","name":"TV Litoral","description":"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.","publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redelitoralrs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redelitoralrs.com\/#organization","name":"TV Litoral","url":"https:\/\/redelitoralrs.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","width":454,"height":454,"caption":"TV Litoral"},"image":{"@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tvlitoralrsoficial","https:\/\/www.instagram.com\/tvlitoral.rs"]},{"@type":"Person","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a","name":"Reda\u00e7\u00e3o TV Litoral","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","url":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","caption":"Reda\u00e7\u00e3o TV Litoral"},"description":"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.","sameAs":["https:\/\/redelitoralrs.com","https:\/\/www.instagram.com\/redelitoralrs","https:\/\/www.youtube.com\/@redelitoralrs"],"url":"https:\/\/redelitoralrs.com\/index.php\/author\/redacaotvlitoral\/"}]}},"_links":{"self":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/6068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/comments?post=6068"}],"version-history":[{"count":2,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/6068\/revisions"}],"predecessor-version":[{"id":6103,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/6068\/revisions\/6103"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media\/6069"}],"wp:attachment":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media?parent=6068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/categories?post=6068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/tags?post=6068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}