{"id":22914,"date":"2026-02-23T10:09:00","date_gmt":"2026-02-23T13:09:00","guid":{"rendered":"https:\/\/redelitoralrs.com\/?p=22914"},"modified":"2026-02-22T23:12:05","modified_gmt":"2026-02-23T02:12:05","slug":"mulher-morre-apos-saida-de-pista-na-ers-040","status":"publish","type":"post","link":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/mulher-morre-apos-saida-de-pista-na-ers-040\/","title":{"rendered":"Mulher morre ap\u00f3s sa\u00edda de pista na ERS-040"},"content":{"rendered":"\n<p>Uma mulher de 29 anos morreu na madrugada deste domingo (22) ap\u00f3s o ve\u00edculo que conduzia sair da pista no km 94 da ERS-040, em Balne\u00e1rio Pinhal, no Litoral Norte do Rio Grande do Sul. O acidente ocorreu por volta das 4h06min.<\/p>\n\n\n\n<p>De acordo com o Comando Rodovi\u00e1rio da Brigada Militar, o Chevrolet Celta, com placas de Sapucaia do Sul, trafegava no sentido Capivari do Sul\u2013Litoral quando, por raz\u00f5es ainda desconhecidas, saiu da pista e colidiu contra uma \u00e1rvore \u00e0s margens da rodovia.<\/p>\n\n\n\n<p>Quando as equipes chegaram ao local, a condutora j\u00e1 estava sem vida. Conforme o Instituto-Geral de Per\u00edcias do Rio Grande do Sul, a v\u00edtima foi encontrada presa \u00e0s ferragens. O nome n\u00e3o foi divulgado oficialmente.<\/p>\n\n\n\n<p>N\u00e3o houve registro de outros ve\u00edculos envolvidos na ocorr\u00eancia, e a rodovia n\u00e3o precisou ser bloqueada durante o atendimento. As circunst\u00e2ncias do acidente ser\u00e3o apuradas pelas autoridades competentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma mulher de 29 anos morreu na madrugada deste domingo (22) ap\u00f3s o ve\u00edculo que conduzia sair da pista no km 94 da ERS-040, em Balne\u00e1rio Pinhal, no Litoral Norte do Rio Grande do Sul. O acidente ocorreu por volta das 4h06min. De acordo com o Comando Rodovi\u00e1rio da Brigada Militar, o Chevrolet Celta, com [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":22915,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[187,245,15],"tags":[],"class_list":["post-22914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-balneario-pinhal","category-transito","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mulher morre ap\u00f3s sa\u00edda de pista na ERS-040 - Rede Litoral RS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/mulher-morre-apos-saida-de-pista-na-ers-040\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mulher morre ap\u00f3s sa\u00edda de pista na ERS-040 - Rede Litoral RS\" \/>\n<meta property=\"og:description\" content=\"Uma mulher de 29 anos morreu na madrugada deste domingo (22) ap\u00f3s o ve\u00edculo que conduzia sair da pista no km 94 da ERS-040, em Balne\u00e1rio Pinhal, no Litoral Norte do Rio Grande do Sul. O acidente ocorreu por volta das 4h06min. De acordo com o Comando Rodovi\u00e1rio da Brigada Militar, o Chevrolet Celta, com [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/mulher-morre-apos-saida-de-pista-na-ers-040\/\" \/>\n<meta property=\"og:site_name\" content=\"Rede Litoral RS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tvlitoralrsoficial\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-23T13:09:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2026\/02\/OefcmsaR-acidente-balneario-pinhal-1145x768-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/mulher-morre-apos-saida-de-pista-na-ers-040\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/mulher-morre-apos-saida-de-pista-na-ers-040\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\"},\"headline\":\"Mulher morre ap\u00f3s sa\u00edda de pista na ERS-040\",\"datePublished\":\"2026-02-23T13:09:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/mulher-morre-apos-saida-de-pista-na-ers-040\\\/\"},\"wordCount\":169,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/mulher-morre-apos-saida-de-pista-na-ers-040\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/OefcmsaR-acidente-balneario-pinhal-1145x768-1.webp\",\"articleSection\":[\"Balne\u00e1rio Pinhal\",\"Tr\u00e2nsito\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/mulher-morre-apos-saida-de-pista-na-ers-040\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/mulher-morre-apos-saida-de-pista-na-ers-040\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/mulher-morre-apos-saida-de-pista-na-ers-040\\\/\",\"name\":\"Mulher morre ap\u00f3s sa\u00edda de pista na ERS-040 - Rede Litoral RS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/mulher-morre-apos-saida-de-pista-na-ers-040\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/mulher-morre-apos-saida-de-pista-na-ers-040\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/OefcmsaR-acidente-balneario-pinhal-1145x768-1.webp\",\"datePublished\":\"2026-02-23T13:09:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/mulher-morre-apos-saida-de-pista-na-ers-040\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/mulher-morre-apos-saida-de-pista-na-ers-040\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/mulher-morre-apos-saida-de-pista-na-ers-040\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/OefcmsaR-acidente-balneario-pinhal-1145x768-1.webp\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/OefcmsaR-acidente-balneario-pinhal-1145x768-1.webp\",\"width\":1145,\"height\":768,\"caption\":\"Foto: Reprodu\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/mulher-morre-apos-saida-de-pista-na-ers-040\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/redelitoralrs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mulher morre ap\u00f3s sa\u00edda de pista na ERS-040\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"name\":\"TV Litoral\",\"description\":\"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redelitoralrs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\",\"name\":\"TV Litoral\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"width\":454,\"height\":454,\"caption\":\"TV Litoral\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tvlitoralrsoficial\",\"https:\\\/\\\/www.instagram.com\\\/tvlitoral.rs\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\",\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"caption\":\"Reda\u00e7\u00e3o TV Litoral\"},\"description\":\"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.\",\"sameAs\":[\"https:\\\/\\\/redelitoralrs.com\",\"https:\\\/\\\/www.instagram.com\\\/redelitoralrs\",\"https:\\\/\\\/www.youtube.com\\\/@redelitoralrs\"],\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/author\\\/redacaotvlitoral\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mulher morre ap\u00f3s sa\u00edda de pista na ERS-040 - Rede Litoral RS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/mulher-morre-apos-saida-de-pista-na-ers-040\/","og_locale":"pt_BR","og_type":"article","og_title":"Mulher morre ap\u00f3s sa\u00edda de pista na ERS-040 - Rede Litoral RS","og_description":"Uma mulher de 29 anos morreu na madrugada deste domingo (22) ap\u00f3s o ve\u00edculo que conduzia sair da pista no km 94 da ERS-040, em Balne\u00e1rio Pinhal, no Litoral Norte do Rio Grande do Sul. O acidente ocorreu por volta das 4h06min. De acordo com o Comando Rodovi\u00e1rio da Brigada Militar, o Chevrolet Celta, com [&hellip;]","og_url":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/mulher-morre-apos-saida-de-pista-na-ers-040\/","og_site_name":"Rede Litoral RS","article_publisher":"https:\/\/www.facebook.com\/tvlitoralrsoficial","article_published_time":"2026-02-23T13:09:00+00:00","og_image":[{"width":1145,"height":768,"url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2026\/02\/OefcmsaR-acidente-balneario-pinhal-1145x768-1.webp","type":"image\/webp"}],"author":"Reda\u00e7\u00e3o TV Litoral","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o TV Litoral","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/mulher-morre-apos-saida-de-pista-na-ers-040\/#article","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/mulher-morre-apos-saida-de-pista-na-ers-040\/"},"author":{"name":"Reda\u00e7\u00e3o TV Litoral","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a"},"headline":"Mulher morre ap\u00f3s sa\u00edda de pista na ERS-040","datePublished":"2026-02-23T13:09:00+00:00","mainEntityOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/mulher-morre-apos-saida-de-pista-na-ers-040\/"},"wordCount":169,"commentCount":0,"publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/mulher-morre-apos-saida-de-pista-na-ers-040\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2026\/02\/OefcmsaR-acidente-balneario-pinhal-1145x768-1.webp","articleSection":["Balne\u00e1rio Pinhal","Tr\u00e2nsito","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/mulher-morre-apos-saida-de-pista-na-ers-040\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/mulher-morre-apos-saida-de-pista-na-ers-040\/","url":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/mulher-morre-apos-saida-de-pista-na-ers-040\/","name":"Mulher morre ap\u00f3s sa\u00edda de pista na ERS-040 - Rede Litoral RS","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/mulher-morre-apos-saida-de-pista-na-ers-040\/#primaryimage"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/mulher-morre-apos-saida-de-pista-na-ers-040\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2026\/02\/OefcmsaR-acidente-balneario-pinhal-1145x768-1.webp","datePublished":"2026-02-23T13:09:00+00:00","breadcrumb":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/mulher-morre-apos-saida-de-pista-na-ers-040\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/mulher-morre-apos-saida-de-pista-na-ers-040\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/mulher-morre-apos-saida-de-pista-na-ers-040\/#primaryimage","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2026\/02\/OefcmsaR-acidente-balneario-pinhal-1145x768-1.webp","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2026\/02\/OefcmsaR-acidente-balneario-pinhal-1145x768-1.webp","width":1145,"height":768,"caption":"Foto: Reprodu\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/mulher-morre-apos-saida-de-pista-na-ers-040\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/redelitoralrs.com\/"},{"@type":"ListItem","position":2,"name":"Mulher morre ap\u00f3s sa\u00edda de pista na ERS-040"}]},{"@type":"WebSite","@id":"https:\/\/redelitoralrs.com\/#website","url":"https:\/\/redelitoralrs.com\/","name":"TV Litoral","description":"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.","publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redelitoralrs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redelitoralrs.com\/#organization","name":"TV Litoral","url":"https:\/\/redelitoralrs.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","width":454,"height":454,"caption":"TV Litoral"},"image":{"@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tvlitoralrsoficial","https:\/\/www.instagram.com\/tvlitoral.rs"]},{"@type":"Person","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a","name":"Reda\u00e7\u00e3o TV Litoral","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","url":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","caption":"Reda\u00e7\u00e3o TV Litoral"},"description":"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.","sameAs":["https:\/\/redelitoralrs.com","https:\/\/www.instagram.com\/redelitoralrs","https:\/\/www.youtube.com\/@redelitoralrs"],"url":"https:\/\/redelitoralrs.com\/index.php\/author\/redacaotvlitoral\/"}]}},"_links":{"self":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/22914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/comments?post=22914"}],"version-history":[{"count":1,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/22914\/revisions"}],"predecessor-version":[{"id":22916,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/22914\/revisions\/22916"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media\/22915"}],"wp:attachment":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media?parent=22914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/categories?post=22914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/tags?post=22914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}