{"id":22905,"date":"2026-02-23T12:18:00","date_gmt":"2026-02-23T15:18:00","guid":{"rendered":"https:\/\/redelitoralrs.com\/?p=22905"},"modified":"2026-02-22T22:56:00","modified_gmt":"2026-02-23T01:56:00","slug":"itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco","status":"publish","type":"post","link":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\/","title":{"rendered":"Ita\u00fa confirma fechamento de ag\u00eancia no Litoral para 4 de mar\u00e7o"},"content":{"rendered":"\n<p>O&nbsp;Ita\u00fa Unibanco&nbsp;confirmou o encerramento das atividades de sua ag\u00eancia no munic\u00edpio de&nbsp;Os\u00f3rio. O fechamento est\u00e1 previsto para o dia 4 de mar\u00e7o e integra um processo de reestrutura\u00e7\u00e3o promovido pela institui\u00e7\u00e3o financeira, que ao longo do \u00faltimo ano tamb\u00e9m encerrou unidades em diferentes regi\u00f5es do pa\u00eds.<\/p>\n\n\n\n<p>A decis\u00e3o j\u00e1 havia sido cogitada anteriormente, com expectativa inicial de encerramento ainda no primeiro semestre do ano passado, mas acabou sendo postergada. Agora, a medida foi oficializada. At\u00e9 o momento, n\u00e3o houve divulga\u00e7\u00e3o p\u00fablica de um motivo espec\u00edfico para o fechamento da unidade.<\/p>\n\n\n\n<p>Diante do an\u00fancio, diretores do Sindicato dos Banc\u00e1rios do Litoral Norte do RS, juntamente com o representante do estado na Comiss\u00e3o de Organiza\u00e7\u00e3o dos Empregados (COE) do Ita\u00fa, Eduardo Munhoz, reuniram-se no dia 11 de fevereiro com o prefeito de Os\u00f3rio,\u00a0Romildo Bolzan J\u00fanior. O encontro teve como pauta o an\u00fancio do encerramento da ag\u00eancia local.<\/p>\n\n\n\n<p>A mobiliza\u00e7\u00e3o do movimento sindical busca apoio da Prefeitura para pressionar o banco a rever a decis\u00e3o. A entidade aponta poss\u00edveis impactos sociais e econ\u00f4micos decorrentes do fechamento, tanto para os trabalhadores da ag\u00eancia quanto para a popula\u00e7\u00e3o que depende do atendimento banc\u00e1rio presencial, especialmente idosos e pequenos comerciantes.<\/p>\n\n\n\n<p>Participaram da reuni\u00e3o os diretores sindicais Jeferson Cougo e Angelita Cezar, al\u00e9m da vereadora&nbsp;Professora Izabel.<\/p>\n\n\n\n<p>De acordo com informa\u00e7\u00f5es repassadas pelo representante sindical, ao entrar em contato com o setor de Rela\u00e7\u00f5es Institucionais do Ita\u00fa, foi informado que nenhum funcion\u00e1rio est\u00e1 autorizado a participar de reuni\u00f5es com o poder p\u00fablico ou conceder manifesta\u00e7\u00f5es \u00e0 imprensa em nome da institui\u00e7\u00e3o. Como alternativa, o banco disponibilizou um endere\u00e7o de e-mail para envio de of\u00edcio formal, por meio do qual podem ser solicitadas respostas oficiais.<\/p>\n\n\n\n<p>O Sindicato afirma que seguir\u00e1 buscando di\u00e1logo e cobrando maior transpar\u00eancia quanto aos crit\u00e9rios adotados para o fechamento da ag\u00eancia, al\u00e9m de acompanhar os desdobramentos do caso.<\/p>\n\n\n\n<p>Com o encerramento da unidade em Os\u00f3rio, no Litoral Norte do Rio Grande do Sul permanecer\u00e3o em funcionamento apenas as ag\u00eancias do Ita\u00fa localizadas em Tramanda\u00ed, Cap\u00e3o da Canoa e Torres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O&nbsp;Ita\u00fa Unibanco&nbsp;confirmou o encerramento das atividades de sua ag\u00eancia no munic\u00edpio de&nbsp;Os\u00f3rio. O fechamento est\u00e1 previsto para o dia 4 de mar\u00e7o e integra um processo de reestrutura\u00e7\u00e3o promovido pela institui\u00e7\u00e3o financeira, que ao longo do \u00faltimo ano tamb\u00e9m encerrou unidades em diferentes regi\u00f5es do pa\u00eds. A decis\u00e3o j\u00e1 havia sido cogitada anteriormente, com expectativa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":22906,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[172,15],"tags":[],"class_list":["post-22905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-osorio","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ita\u00fa confirma fechamento de ag\u00eancia no Litoral para 4 de mar\u00e7o - Rede Litoral RS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ita\u00fa confirma fechamento de ag\u00eancia no Litoral para 4 de mar\u00e7o - Rede Litoral RS\" \/>\n<meta property=\"og:description\" content=\"O&nbsp;Ita\u00fa Unibanco&nbsp;confirmou o encerramento das atividades de sua ag\u00eancia no munic\u00edpio de&nbsp;Os\u00f3rio. O fechamento est\u00e1 previsto para o dia 4 de mar\u00e7o e integra um processo de reestrutura\u00e7\u00e3o promovido pela institui\u00e7\u00e3o financeira, que ao longo do \u00faltimo ano tamb\u00e9m encerrou unidades em diferentes regi\u00f5es do pa\u00eds. A decis\u00e3o j\u00e1 havia sido cogitada anteriormente, com expectativa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\/\" \/>\n<meta property=\"og:site_name\" content=\"Rede Litoral RS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tvlitoralrsoficial\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-23T15:18:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2026\/02\/ITAU_210226.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1512\" \/>\n\t<meta property=\"og:image:height\" content=\"1422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\"},\"headline\":\"Ita\u00fa confirma fechamento de ag\u00eancia no Litoral para 4 de mar\u00e7o\",\"datePublished\":\"2026-02-23T15:18:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\\\/\"},\"wordCount\":401,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/ITAU_210226.jpeg\",\"articleSection\":[\"Os\u00f3rio\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\\\/\",\"name\":\"Ita\u00fa confirma fechamento de ag\u00eancia no Litoral para 4 de mar\u00e7o - Rede Litoral RS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/ITAU_210226.jpeg\",\"datePublished\":\"2026-02-23T15:18:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/ITAU_210226.jpeg\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/ITAU_210226.jpeg\",\"width\":1512,\"height\":1422,\"caption\":\"Foto: Reprodu\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2026\\\/02\\\/23\\\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/redelitoralrs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ita\u00fa confirma fechamento de ag\u00eancia no Litoral para 4 de mar\u00e7o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"name\":\"TV Litoral\",\"description\":\"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redelitoralrs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\",\"name\":\"TV Litoral\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"width\":454,\"height\":454,\"caption\":\"TV Litoral\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tvlitoralrsoficial\",\"https:\\\/\\\/www.instagram.com\\\/tvlitoral.rs\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\",\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"caption\":\"Reda\u00e7\u00e3o TV Litoral\"},\"description\":\"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.\",\"sameAs\":[\"https:\\\/\\\/redelitoralrs.com\",\"https:\\\/\\\/www.instagram.com\\\/redelitoralrs\",\"https:\\\/\\\/www.youtube.com\\\/@redelitoralrs\"],\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/author\\\/redacaotvlitoral\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ita\u00fa confirma fechamento de ag\u00eancia no Litoral para 4 de mar\u00e7o - Rede Litoral RS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\/","og_locale":"pt_BR","og_type":"article","og_title":"Ita\u00fa confirma fechamento de ag\u00eancia no Litoral para 4 de mar\u00e7o - Rede Litoral RS","og_description":"O&nbsp;Ita\u00fa Unibanco&nbsp;confirmou o encerramento das atividades de sua ag\u00eancia no munic\u00edpio de&nbsp;Os\u00f3rio. O fechamento est\u00e1 previsto para o dia 4 de mar\u00e7o e integra um processo de reestrutura\u00e7\u00e3o promovido pela institui\u00e7\u00e3o financeira, que ao longo do \u00faltimo ano tamb\u00e9m encerrou unidades em diferentes regi\u00f5es do pa\u00eds. A decis\u00e3o j\u00e1 havia sido cogitada anteriormente, com expectativa [&hellip;]","og_url":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\/","og_site_name":"Rede Litoral RS","article_publisher":"https:\/\/www.facebook.com\/tvlitoralrsoficial","article_published_time":"2026-02-23T15:18:00+00:00","og_image":[{"width":1512,"height":1422,"url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2026\/02\/ITAU_210226.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o TV Litoral","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o TV Litoral","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\/#article","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\/"},"author":{"name":"Reda\u00e7\u00e3o TV Litoral","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a"},"headline":"Ita\u00fa confirma fechamento de ag\u00eancia no Litoral para 4 de mar\u00e7o","datePublished":"2026-02-23T15:18:00+00:00","mainEntityOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\/"},"wordCount":401,"commentCount":0,"publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2026\/02\/ITAU_210226.jpeg","articleSection":["Os\u00f3rio","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\/","url":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\/","name":"Ita\u00fa confirma fechamento de ag\u00eancia no Litoral para 4 de mar\u00e7o - Rede Litoral RS","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\/#primaryimage"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2026\/02\/ITAU_210226.jpeg","datePublished":"2026-02-23T15:18:00+00:00","breadcrumb":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\/#primaryimage","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2026\/02\/ITAU_210226.jpeg","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2026\/02\/ITAU_210226.jpeg","width":1512,"height":1422,"caption":"Foto: Reprodu\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/redelitoralrs.com\/index.php\/2026\/02\/23\/itau-confirma-fechamento-de-agencia-no-litoral-para-4-de-marco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/redelitoralrs.com\/"},{"@type":"ListItem","position":2,"name":"Ita\u00fa confirma fechamento de ag\u00eancia no Litoral para 4 de mar\u00e7o"}]},{"@type":"WebSite","@id":"https:\/\/redelitoralrs.com\/#website","url":"https:\/\/redelitoralrs.com\/","name":"TV Litoral","description":"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.","publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redelitoralrs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redelitoralrs.com\/#organization","name":"TV Litoral","url":"https:\/\/redelitoralrs.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","width":454,"height":454,"caption":"TV Litoral"},"image":{"@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tvlitoralrsoficial","https:\/\/www.instagram.com\/tvlitoral.rs"]},{"@type":"Person","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a","name":"Reda\u00e7\u00e3o TV Litoral","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","url":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","caption":"Reda\u00e7\u00e3o TV Litoral"},"description":"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.","sameAs":["https:\/\/redelitoralrs.com","https:\/\/www.instagram.com\/redelitoralrs","https:\/\/www.youtube.com\/@redelitoralrs"],"url":"https:\/\/redelitoralrs.com\/index.php\/author\/redacaotvlitoral\/"}]}},"_links":{"self":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/22905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/comments?post=22905"}],"version-history":[{"count":1,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/22905\/revisions"}],"predecessor-version":[{"id":22907,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/22905\/revisions\/22907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media\/22906"}],"wp:attachment":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media?parent=22905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/categories?post=22905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/tags?post=22905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}