{"id":18283,"date":"2025-10-21T13:04:34","date_gmt":"2025-10-21T16:04:34","guid":{"rendered":"https:\/\/redelitoralrs.com\/?p=18283"},"modified":"2025-10-21T13:04:35","modified_gmt":"2025-10-21T16:04:35","slug":"policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro","status":"publish","type":"post","link":"https:\/\/redelitoralrs.com\/index.php\/2025\/10\/21\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\/","title":{"rendered":"Pol\u00edcia Civil desarticula grupo criminoso em opera\u00e7\u00e3o contra tr\u00e1fico e lavagem de dinheiro"},"content":{"rendered":"\n<p>A <strong>Pol\u00edcia Civil<\/strong> deflagrou, nesta ter\u00e7a-feira (21), a <strong>Opera\u00e7\u00e3o Solitarium<\/strong>, com foco no combate a uma organiza\u00e7\u00e3o criminosa envolvida em <strong>tr\u00e1fico de drogas, lavagem de dinheiro e amea\u00e7as a policial civil<\/strong>. A a\u00e7\u00e3o foi coordenada pelo <strong>Posto Policial de Quint\u00e3o<\/strong>, vinculado \u00e0 <strong>23\u00aa Delegacia Regional do Interior (23\u00aa DPRI)<\/strong>, e cumpriu ordens judiciais em munic\u00edpios do <strong>Litoral Norte<\/strong> e da <strong>Regi\u00e3o Metropolitana<\/strong>.<\/p>\n\n\n\n<p>Ao todo, foram <strong>39 mandados de busca e apreens\u00e3o<\/strong>, <strong>32 mandados de pris\u00e3o<\/strong> e <strong>oito ordens de sequestro de bens<\/strong> em <strong>Palmares do Sul<\/strong>, <strong>Tramanda\u00ed<\/strong>, <strong>Balne\u00e1rio Pinhal<\/strong>, <strong>Alvorada<\/strong> e <strong>Viam\u00e3o<\/strong>.<\/p>\n\n\n\n<p>Durante a ofensiva, <strong>14 pessoas foram presas temporariamente<\/strong>, <strong>uma em flagrante<\/strong> por tr\u00e1fico e associa\u00e7\u00e3o ao tr\u00e1fico, e outras <strong>sete que j\u00e1 estavam recolhidas<\/strong> ao sistema prisional tiveram nova responsabiliza\u00e7\u00e3o criminal, totalizando <strong>22 pris\u00f5es<\/strong>. Foram apreendidos <strong>celulares, drogas e documentos<\/strong> que servir\u00e3o de base para a continuidade das investiga\u00e7\u00f5es.<\/p>\n\n\n\n<p>A opera\u00e7\u00e3o tamb\u00e9m realizou a <strong>transfer\u00eancia da lideran\u00e7a local do grupo criminoso<\/strong> para um pres\u00eddio de seguran\u00e7a m\u00e1xima. O detento estava custodiado na <strong>Penitenci\u00e1ria Modulada de Os\u00f3rio<\/strong> e, segundo as investiga\u00e7\u00f5es, mantinha controle sobre as atividades il\u00edcitas mesmo de dentro da pris\u00e3o.<\/p>\n\n\n\n<p>As apura\u00e7\u00f5es apontaram que o grupo mantinha uma <strong>rede estruturada de tr\u00e1fico de entorpecentes<\/strong>, com atua\u00e7\u00e3o predominante no <strong>Litoral Norte<\/strong> e ramifica\u00e7\u00f5es em outros munic\u00edpios do Estado. Para ocultar e movimentar os valores provenientes do crime, os investigados utilizavam <strong>empresas de fachada, im\u00f3veis e contas banc\u00e1rias em nome de terceiros<\/strong>, caracterizando um esquema de <strong>lavagem de dinheiro<\/strong>.<\/p>\n\n\n\n<p>Durante a investiga\u00e7\u00e3o, a Pol\u00edcia Civil tamb\u00e9m identificou <strong>amea\u00e7as de morte contra um policial civil<\/strong>, que havia participado de a\u00e7\u00f5es anteriores contra o grupo. O servidor foi monitorado pelos criminosos em aplicativos de mensagens.<\/p>\n\n\n\n<p>Os mandados foram cumpridos em <strong>resid\u00eancias, pousadas, com\u00e9rcios e unidades prisionais<\/strong>, incluindo o <strong>Pres\u00eddio Estadual de Taquara<\/strong> e a <strong>Penitenci\u00e1ria Modulada de Os\u00f3rio<\/strong>.<\/p>\n\n\n\n<p>A Opera\u00e7\u00e3o Solitarium contou com o apoio de diversas unidades da Pol\u00edcia Civil e mobilizou <strong>cerca de 200 agentes<\/strong>, refor\u00e7ando o compromisso da institui\u00e7\u00e3o com o <strong>enfrentamento ao crime organizado<\/strong> e a <strong>prote\u00e7\u00e3o de seus servidores<\/strong>.<\/p>\n\n\n\n<div id=\"wp-block-themeisle-blocks-slider-bd8455b6\" class=\"wp-block-themeisle-blocks-slider glide\" data-per-view=\"1\" data-gap=\"0\" data-peek=\"0\" data-autoplay=\"true\" data-height=\"400px\" data-hide-arrows=\"false\"><div class=\"glide__track\" data-glide-el=\"track\"><div class=\"glide__slides\"><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/10\/21094351_559904_GDO.jpg\" alt=\"\" title=\"\" data-id=\"18286\"\/><figcaption>Foto: DCS\/PCRS<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/10\/21094524_559926_GDO.jpg\" alt=\"\" title=\"\" data-id=\"18285\"\/><figcaption>Foto: DCS\/PCRS<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/10\/21094530_559948_GDO.jpeg\" alt=\"\" title=\"\" data-id=\"18284\"\/><figcaption>Foto: DCS\/PCRS<\/figcaption><\/figure><\/div><\/div><div class=\"glide__bullets\" data-glide-el=\"controls[nav]\"><button class=\"glide__bullet\" data-glide-dir=\"=0\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=1\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=2\"><\/button><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Civil deflagrou, nesta ter\u00e7a-feira (21), a Opera\u00e7\u00e3o Solitarium, com foco no combate a uma organiza\u00e7\u00e3o criminosa envolvida em tr\u00e1fico de drogas, lavagem de dinheiro e amea\u00e7as a policial civil. A a\u00e7\u00e3o foi coordenada pelo Posto Policial de Quint\u00e3o, vinculado \u00e0 23\u00aa Delegacia Regional do Interior (23\u00aa DPRI), e cumpriu ordens judiciais em munic\u00edpios [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18287,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[20,240,15],"tags":[103,92,112,2540,1636,128,343],"class_list":["post-18283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-litoral_norte","category-palmares-do-sul","category-noticias","tag-litoral-norte","tag-noticia","tag-palmares-do-sul","tag-pinhal","tag-quintao-2","tag-rio-grande-do-sul","tag-tramandai-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edcia Civil desarticula grupo criminoso em opera\u00e7\u00e3o contra tr\u00e1fico e lavagem de dinheiro - Rede Litoral RS<\/title>\n<meta name=\"description\" content=\"A Pol\u00edcia Civil deflagrou, nesta ter\u00e7a-feira (21), a Opera\u00e7\u00e3o Solitarium, com foco no combate a uma organiza\u00e7\u00e3o criminosa envolvida em tr\u00e1fico de drogas, lavagem de dinheiro e amea\u00e7as a policial civil. A a\u00e7\u00e3o foi coordenada pelo Posto Policial de Quint\u00e3o, vinculado \u00e0 23\u00aa Delegacia Regional do Interior (23\u00aa DPRI), e cumpriu ordens judiciais em munic\u00edpios do Litoral Norte e da Regi\u00e3o Metropolitana.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redelitoralrs.com\/index.php\/2025\/10\/21\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edcia Civil desarticula grupo criminoso em opera\u00e7\u00e3o contra tr\u00e1fico e lavagem de dinheiro - Rede Litoral RS\" \/>\n<meta property=\"og:description\" content=\"A Pol\u00edcia Civil deflagrou, nesta ter\u00e7a-feira (21), a Opera\u00e7\u00e3o Solitarium, com foco no combate a uma organiza\u00e7\u00e3o criminosa envolvida em tr\u00e1fico de drogas, lavagem de dinheiro e amea\u00e7as a policial civil. A a\u00e7\u00e3o foi coordenada pelo Posto Policial de Quint\u00e3o, vinculado \u00e0 23\u00aa Delegacia Regional do Interior (23\u00aa DPRI), e cumpriu ordens judiciais em munic\u00edpios do Litoral Norte e da Regi\u00e3o Metropolitana.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redelitoralrs.com\/index.php\/2025\/10\/21\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\/\" \/>\n<meta property=\"og:site_name\" content=\"Rede Litoral RS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tvlitoralrsoficial\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-21T16:04:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-21T16:04:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/10\/5500123_4f3ec94196e21db.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/10\\\/21\\\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/10\\\/21\\\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\"},\"headline\":\"Pol\u00edcia Civil desarticula grupo criminoso em opera\u00e7\u00e3o contra tr\u00e1fico e lavagem de dinheiro\",\"datePublished\":\"2025-10-21T16:04:34+00:00\",\"dateModified\":\"2025-10-21T16:04:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/10\\\/21\\\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\\\/\"},\"wordCount\":404,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/10\\\/21\\\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/5500123_4f3ec94196e21db.webp\",\"keywords\":[\"litoral norte\",\"not\u00edcia\",\"palmares do sul\",\"pinhal\",\"quint\u00e3o\",\"rio grande do sul\",\"tramandai\"],\"articleSection\":[\"Litoral Norte\",\"Palmares do Sul\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/10\\\/21\\\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/10\\\/21\\\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/10\\\/21\\\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\\\/\",\"name\":\"Pol\u00edcia Civil desarticula grupo criminoso em opera\u00e7\u00e3o contra tr\u00e1fico e lavagem de dinheiro - Rede Litoral RS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/10\\\/21\\\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/10\\\/21\\\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/5500123_4f3ec94196e21db.webp\",\"datePublished\":\"2025-10-21T16:04:34+00:00\",\"dateModified\":\"2025-10-21T16:04:35+00:00\",\"description\":\"A Pol\u00edcia Civil deflagrou, nesta ter\u00e7a-feira (21), a Opera\u00e7\u00e3o Solitarium, com foco no combate a uma organiza\u00e7\u00e3o criminosa envolvida em tr\u00e1fico de drogas, lavagem de dinheiro e amea\u00e7as a policial civil. A a\u00e7\u00e3o foi coordenada pelo Posto Policial de Quint\u00e3o, vinculado \u00e0 23\u00aa Delegacia Regional do Interior (23\u00aa DPRI), e cumpriu ordens judiciais em munic\u00edpios do Litoral Norte e da Regi\u00e3o Metropolitana.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/10\\\/21\\\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/10\\\/21\\\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/10\\\/21\\\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/5500123_4f3ec94196e21db.webp\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/5500123_4f3ec94196e21db.webp\",\"width\":700,\"height\":466,\"caption\":\"Foto: DCS\\\/PCRS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/10\\\/21\\\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/redelitoralrs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edcia Civil desarticula grupo criminoso em opera\u00e7\u00e3o contra tr\u00e1fico e lavagem de dinheiro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"name\":\"TV Litoral\",\"description\":\"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redelitoralrs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\",\"name\":\"TV Litoral\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"width\":454,\"height\":454,\"caption\":\"TV Litoral\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tvlitoralrsoficial\",\"https:\\\/\\\/www.instagram.com\\\/tvlitoral.rs\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\",\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"caption\":\"Reda\u00e7\u00e3o TV Litoral\"},\"description\":\"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.\",\"sameAs\":[\"https:\\\/\\\/redelitoralrs.com\",\"https:\\\/\\\/www.instagram.com\\\/redelitoralrs\",\"https:\\\/\\\/www.youtube.com\\\/@redelitoralrs\"],\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/author\\\/redacaotvlitoral\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edcia Civil desarticula grupo criminoso em opera\u00e7\u00e3o contra tr\u00e1fico e lavagem de dinheiro - Rede Litoral RS","description":"A Pol\u00edcia Civil deflagrou, nesta ter\u00e7a-feira (21), a Opera\u00e7\u00e3o Solitarium, com foco no combate a uma organiza\u00e7\u00e3o criminosa envolvida em tr\u00e1fico de drogas, lavagem de dinheiro e amea\u00e7as a policial civil. A a\u00e7\u00e3o foi coordenada pelo Posto Policial de Quint\u00e3o, vinculado \u00e0 23\u00aa Delegacia Regional do Interior (23\u00aa DPRI), e cumpriu ordens judiciais em munic\u00edpios do Litoral Norte e da Regi\u00e3o Metropolitana.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redelitoralrs.com\/index.php\/2025\/10\/21\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\/","og_locale":"pt_BR","og_type":"article","og_title":"Pol\u00edcia Civil desarticula grupo criminoso em opera\u00e7\u00e3o contra tr\u00e1fico e lavagem de dinheiro - Rede Litoral RS","og_description":"A Pol\u00edcia Civil deflagrou, nesta ter\u00e7a-feira (21), a Opera\u00e7\u00e3o Solitarium, com foco no combate a uma organiza\u00e7\u00e3o criminosa envolvida em tr\u00e1fico de drogas, lavagem de dinheiro e amea\u00e7as a policial civil. A a\u00e7\u00e3o foi coordenada pelo Posto Policial de Quint\u00e3o, vinculado \u00e0 23\u00aa Delegacia Regional do Interior (23\u00aa DPRI), e cumpriu ordens judiciais em munic\u00edpios do Litoral Norte e da Regi\u00e3o Metropolitana.","og_url":"https:\/\/redelitoralrs.com\/index.php\/2025\/10\/21\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\/","og_site_name":"Rede Litoral RS","article_publisher":"https:\/\/www.facebook.com\/tvlitoralrsoficial","article_published_time":"2025-10-21T16:04:34+00:00","article_modified_time":"2025-10-21T16:04:35+00:00","og_image":[{"width":700,"height":466,"url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/10\/5500123_4f3ec94196e21db.webp","type":"image\/webp"}],"author":"Reda\u00e7\u00e3o TV Litoral","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o TV Litoral","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/10\/21\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\/#article","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/10\/21\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\/"},"author":{"name":"Reda\u00e7\u00e3o TV Litoral","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a"},"headline":"Pol\u00edcia Civil desarticula grupo criminoso em opera\u00e7\u00e3o contra tr\u00e1fico e lavagem de dinheiro","datePublished":"2025-10-21T16:04:34+00:00","dateModified":"2025-10-21T16:04:35+00:00","mainEntityOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/10\/21\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\/"},"wordCount":404,"commentCount":0,"publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/10\/21\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/10\/5500123_4f3ec94196e21db.webp","keywords":["litoral norte","not\u00edcia","palmares do sul","pinhal","quint\u00e3o","rio grande do sul","tramandai"],"articleSection":["Litoral Norte","Palmares do Sul","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/10\/21\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/10\/21\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\/","url":"https:\/\/redelitoralrs.com\/index.php\/2025\/10\/21\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\/","name":"Pol\u00edcia Civil desarticula grupo criminoso em opera\u00e7\u00e3o contra tr\u00e1fico e lavagem de dinheiro - Rede Litoral RS","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/10\/21\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\/#primaryimage"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/10\/21\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/10\/5500123_4f3ec94196e21db.webp","datePublished":"2025-10-21T16:04:34+00:00","dateModified":"2025-10-21T16:04:35+00:00","description":"A Pol\u00edcia Civil deflagrou, nesta ter\u00e7a-feira (21), a Opera\u00e7\u00e3o Solitarium, com foco no combate a uma organiza\u00e7\u00e3o criminosa envolvida em tr\u00e1fico de drogas, lavagem de dinheiro e amea\u00e7as a policial civil. A a\u00e7\u00e3o foi coordenada pelo Posto Policial de Quint\u00e3o, vinculado \u00e0 23\u00aa Delegacia Regional do Interior (23\u00aa DPRI), e cumpriu ordens judiciais em munic\u00edpios do Litoral Norte e da Regi\u00e3o Metropolitana.","breadcrumb":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/10\/21\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/10\/21\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/10\/21\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\/#primaryimage","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/10\/5500123_4f3ec94196e21db.webp","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/10\/5500123_4f3ec94196e21db.webp","width":700,"height":466,"caption":"Foto: DCS\/PCRS"},{"@type":"BreadcrumbList","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/10\/21\/policia-civil-desarticula-grupo-criminoso-em-operacao-contra-trafico-e-lavagem-de-dinheiro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/redelitoralrs.com\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edcia Civil desarticula grupo criminoso em opera\u00e7\u00e3o contra tr\u00e1fico e lavagem de dinheiro"}]},{"@type":"WebSite","@id":"https:\/\/redelitoralrs.com\/#website","url":"https:\/\/redelitoralrs.com\/","name":"TV Litoral","description":"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.","publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redelitoralrs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redelitoralrs.com\/#organization","name":"TV Litoral","url":"https:\/\/redelitoralrs.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","width":454,"height":454,"caption":"TV Litoral"},"image":{"@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tvlitoralrsoficial","https:\/\/www.instagram.com\/tvlitoral.rs"]},{"@type":"Person","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a","name":"Reda\u00e7\u00e3o TV Litoral","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","url":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","caption":"Reda\u00e7\u00e3o TV Litoral"},"description":"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.","sameAs":["https:\/\/redelitoralrs.com","https:\/\/www.instagram.com\/redelitoralrs","https:\/\/www.youtube.com\/@redelitoralrs"],"url":"https:\/\/redelitoralrs.com\/index.php\/author\/redacaotvlitoral\/"}]}},"_links":{"self":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/18283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/comments?post=18283"}],"version-history":[{"count":1,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/18283\/revisions"}],"predecessor-version":[{"id":18288,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/18283\/revisions\/18288"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media\/18287"}],"wp:attachment":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media?parent=18283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/categories?post=18283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/tags?post=18283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}