{"id":17060,"date":"2025-09-26T17:57:00","date_gmt":"2025-09-26T20:57:00","guid":{"rendered":"https:\/\/redelitoralrs.com\/?p=17060"},"modified":"2025-09-26T19:36:24","modified_gmt":"2025-09-26T22:36:24","slug":"humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel","status":"publish","type":"post","link":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\/","title":{"rendered":"Humorista Cris Pereira \u00e9 condenado a mais de 18 anos de pris\u00e3o por estupro de vulner\u00e1vel"},"content":{"rendered":"\n<p>O humorista ga\u00facho <strong>Cris Pereira<\/strong>, conhecido pelo personagem <em>Jorge da Borracharia<\/em> no programa <em>A Pra\u00e7a \u00e9 Nossa<\/em>, foi condenado a <strong>18 anos, quatro meses e 15 dias de pris\u00e3o em regime fechado<\/strong> pelo crime de estupro de vulner\u00e1vel. O caso, ocorrido em 2021, envolve uma crian\u00e7a de tr\u00eas anos e tramita em segredo de Justi\u00e7a.<\/p>\n\n\n\n<p>A decis\u00e3o foi proferida em <strong>segunda inst\u00e2ncia<\/strong> pela 7\u00aa C\u00e2mara Criminal do Tribunal de Justi\u00e7a do Rio Grande do Sul (TJ-RS), em sess\u00e3o realizada na quinta-feira (25). Pereira havia sido <strong>absolvido em primeira inst\u00e2ncia<\/strong>, em julgamento realizado na comarca de Est\u00e2ncia Velha.<\/p>\n\n\n\n<p>Segundo o advogado Rodrigo Severino, assistente de acusa\u00e7\u00e3o no processo, os desembargadores consideraram <strong>per\u00edcias e an\u00e1lises cl\u00ednicas<\/strong> para reverter a decis\u00e3o anterior.<\/p>\n\n\n\n<p>A <strong>defesa do humorista<\/strong>, representada pelo advogado Edson Cunha, afirmou em nota que a condena\u00e7\u00e3o &#8220;contrariou as provas periciais produzidas em ju\u00edzo&#8221; e destacou que ainda n\u00e3o houve publica\u00e7\u00e3o do ac\u00f3rd\u00e3o. O advogado tamb\u00e9m refor\u00e7ou que ser\u00e3o adotadas medidas em inst\u00e2ncias superiores, sustentando a tese de inoc\u00eancia do r\u00e9u.<\/p>\n\n\n\n<p>O processo segue em sigilo, em respeito ao Estatuto da Crian\u00e7a e do Adolescente (ECA).<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O humorista ga\u00facho Cris Pereira, conhecido pelo personagem Jorge da Borracharia no programa A Pra\u00e7a \u00e9 Nossa, foi condenado a 18 anos, quatro meses e 15 dias de pris\u00e3o em regime fechado pelo crime de estupro de vulner\u00e1vel. O caso, ocorrido em 2021, envolve uma crian\u00e7a de tr\u00eas anos e tramita em segredo de Justi\u00e7a. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17061,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[188,15],"tags":[2120,2121,103,92,128],"class_list":["post-17060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rio-grande-do-sul","category-noticias","tag-cris-pereira","tag-estupro-de-vulneravel","tag-litoral-norte","tag-noticia","tag-rio-grande-do-sul"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Humorista Cris Pereira \u00e9 condenado a mais de 18 anos de pris\u00e3o por estupro de vulner\u00e1vel - Rede Litoral RS<\/title>\n<meta name=\"description\" content=\"O humorista ga\u00facho Cris Pereira, conhecido pelo personagem Jorge da Borracharia no programa A Pra\u00e7a \u00e9 Nossa, foi condenado a 18 anos, quatro meses e 15 dias de pris\u00e3o em regime fechado pelo crime de estupro de vulner\u00e1vel. O caso, ocorrido em 2021, envolve uma crian\u00e7a de tr\u00eas anos e tramita em segredo de Justi\u00e7a.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Humorista Cris Pereira \u00e9 condenado a mais de 18 anos de pris\u00e3o por estupro de vulner\u00e1vel - Rede Litoral RS\" \/>\n<meta property=\"og:description\" content=\"O humorista ga\u00facho Cris Pereira, conhecido pelo personagem Jorge da Borracharia no programa A Pra\u00e7a \u00e9 Nossa, foi condenado a 18 anos, quatro meses e 15 dias de pris\u00e3o em regime fechado pelo crime de estupro de vulner\u00e1vel. O caso, ocorrido em 2021, envolve uma crian\u00e7a de tr\u00eas anos e tramita em segredo de Justi\u00e7a.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\/\" \/>\n<meta property=\"og:site_name\" content=\"Rede Litoral RS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tvlitoralrsoficial\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-26T20:57:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-26T22:36:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/CrisPereiraPontoShow2015_0131-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1704\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\"},\"headline\":\"Humorista Cris Pereira \u00e9 condenado a mais de 18 anos de pris\u00e3o por estupro de vulner\u00e1vel\",\"datePublished\":\"2025-09-26T20:57:00+00:00\",\"dateModified\":\"2025-09-26T22:36:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\\\/\"},\"wordCount\":225,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/CrisPereiraPontoShow2015_0131-scaled.jpg\",\"keywords\":[\"cris pereira\",\"estupro de vulner\u00e1vel\",\"litoral norte\",\"not\u00edcia\",\"rio grande do sul\"],\"articleSection\":[\"Rio Grande do Sul\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\\\/\",\"name\":\"Humorista Cris Pereira \u00e9 condenado a mais de 18 anos de pris\u00e3o por estupro de vulner\u00e1vel - Rede Litoral RS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/CrisPereiraPontoShow2015_0131-scaled.jpg\",\"datePublished\":\"2025-09-26T20:57:00+00:00\",\"dateModified\":\"2025-09-26T22:36:24+00:00\",\"description\":\"O humorista ga\u00facho Cris Pereira, conhecido pelo personagem Jorge da Borracharia no programa A Pra\u00e7a \u00e9 Nossa, foi condenado a 18 anos, quatro meses e 15 dias de pris\u00e3o em regime fechado pelo crime de estupro de vulner\u00e1vel. O caso, ocorrido em 2021, envolve uma crian\u00e7a de tr\u00eas anos e tramita em segredo de Justi\u00e7a.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/CrisPereiraPontoShow2015_0131-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/CrisPereiraPontoShow2015_0131-scaled.jpg\",\"width\":2560,\"height\":1704,\"caption\":\"Foto: Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/redelitoralrs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Humorista Cris Pereira \u00e9 condenado a mais de 18 anos de pris\u00e3o por estupro de vulner\u00e1vel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"name\":\"TV Litoral\",\"description\":\"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redelitoralrs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\",\"name\":\"TV Litoral\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"width\":454,\"height\":454,\"caption\":\"TV Litoral\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tvlitoralrsoficial\",\"https:\\\/\\\/www.instagram.com\\\/tvlitoral.rs\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\",\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"caption\":\"Reda\u00e7\u00e3o TV Litoral\"},\"description\":\"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.\",\"sameAs\":[\"https:\\\/\\\/redelitoralrs.com\",\"https:\\\/\\\/www.instagram.com\\\/redelitoralrs\",\"https:\\\/\\\/www.youtube.com\\\/@redelitoralrs\"],\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/author\\\/redacaotvlitoral\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Humorista Cris Pereira \u00e9 condenado a mais de 18 anos de pris\u00e3o por estupro de vulner\u00e1vel - Rede Litoral RS","description":"O humorista ga\u00facho Cris Pereira, conhecido pelo personagem Jorge da Borracharia no programa A Pra\u00e7a \u00e9 Nossa, foi condenado a 18 anos, quatro meses e 15 dias de pris\u00e3o em regime fechado pelo crime de estupro de vulner\u00e1vel. O caso, ocorrido em 2021, envolve uma crian\u00e7a de tr\u00eas anos e tramita em segredo de Justi\u00e7a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\/","og_locale":"pt_BR","og_type":"article","og_title":"Humorista Cris Pereira \u00e9 condenado a mais de 18 anos de pris\u00e3o por estupro de vulner\u00e1vel - Rede Litoral RS","og_description":"O humorista ga\u00facho Cris Pereira, conhecido pelo personagem Jorge da Borracharia no programa A Pra\u00e7a \u00e9 Nossa, foi condenado a 18 anos, quatro meses e 15 dias de pris\u00e3o em regime fechado pelo crime de estupro de vulner\u00e1vel. O caso, ocorrido em 2021, envolve uma crian\u00e7a de tr\u00eas anos e tramita em segredo de Justi\u00e7a.","og_url":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\/","og_site_name":"Rede Litoral RS","article_publisher":"https:\/\/www.facebook.com\/tvlitoralrsoficial","article_published_time":"2025-09-26T20:57:00+00:00","article_modified_time":"2025-09-26T22:36:24+00:00","og_image":[{"width":2560,"height":1704,"url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/CrisPereiraPontoShow2015_0131-scaled.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o TV Litoral","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o TV Litoral","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\/#article","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\/"},"author":{"name":"Reda\u00e7\u00e3o TV Litoral","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a"},"headline":"Humorista Cris Pereira \u00e9 condenado a mais de 18 anos de pris\u00e3o por estupro de vulner\u00e1vel","datePublished":"2025-09-26T20:57:00+00:00","dateModified":"2025-09-26T22:36:24+00:00","mainEntityOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\/"},"wordCount":225,"commentCount":0,"publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/CrisPereiraPontoShow2015_0131-scaled.jpg","keywords":["cris pereira","estupro de vulner\u00e1vel","litoral norte","not\u00edcia","rio grande do sul"],"articleSection":["Rio Grande do Sul","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\/","url":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\/","name":"Humorista Cris Pereira \u00e9 condenado a mais de 18 anos de pris\u00e3o por estupro de vulner\u00e1vel - Rede Litoral RS","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\/#primaryimage"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/CrisPereiraPontoShow2015_0131-scaled.jpg","datePublished":"2025-09-26T20:57:00+00:00","dateModified":"2025-09-26T22:36:24+00:00","description":"O humorista ga\u00facho Cris Pereira, conhecido pelo personagem Jorge da Borracharia no programa A Pra\u00e7a \u00e9 Nossa, foi condenado a 18 anos, quatro meses e 15 dias de pris\u00e3o em regime fechado pelo crime de estupro de vulner\u00e1vel. O caso, ocorrido em 2021, envolve uma crian\u00e7a de tr\u00eas anos e tramita em segredo de Justi\u00e7a.","breadcrumb":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\/#primaryimage","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/CrisPereiraPontoShow2015_0131-scaled.jpg","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/CrisPereiraPontoShow2015_0131-scaled.jpg","width":2560,"height":1704,"caption":"Foto: Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/humorista-cris-pereira-e-condenado-a-mais-de-18-anos-de-prisao-por-estupro-de-vulneravel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/redelitoralrs.com\/"},{"@type":"ListItem","position":2,"name":"Humorista Cris Pereira \u00e9 condenado a mais de 18 anos de pris\u00e3o por estupro de vulner\u00e1vel"}]},{"@type":"WebSite","@id":"https:\/\/redelitoralrs.com\/#website","url":"https:\/\/redelitoralrs.com\/","name":"TV Litoral","description":"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.","publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redelitoralrs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redelitoralrs.com\/#organization","name":"TV Litoral","url":"https:\/\/redelitoralrs.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","width":454,"height":454,"caption":"TV Litoral"},"image":{"@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tvlitoralrsoficial","https:\/\/www.instagram.com\/tvlitoral.rs"]},{"@type":"Person","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a","name":"Reda\u00e7\u00e3o TV Litoral","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","url":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","caption":"Reda\u00e7\u00e3o TV Litoral"},"description":"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.","sameAs":["https:\/\/redelitoralrs.com","https:\/\/www.instagram.com\/redelitoralrs","https:\/\/www.youtube.com\/@redelitoralrs"],"url":"https:\/\/redelitoralrs.com\/index.php\/author\/redacaotvlitoral\/"}]}},"_links":{"self":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/17060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/comments?post=17060"}],"version-history":[{"count":2,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/17060\/revisions"}],"predecessor-version":[{"id":17063,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/17060\/revisions\/17063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media\/17061"}],"wp:attachment":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media?parent=17060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/categories?post=17060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/tags?post=17060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}