{"id":17055,"date":"2025-09-26T16:24:25","date_gmt":"2025-09-26T19:24:25","guid":{"rendered":"https:\/\/redelitoralrs.com\/?p=17055"},"modified":"2025-09-26T16:24:26","modified_gmt":"2025-09-26T19:24:26","slug":"bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte","status":"publish","type":"post","link":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\/","title":{"rendered":"BM prende tr\u00eas e apreende adolescente por tr\u00e1fico no Litoral Norte"},"content":{"rendered":"\n<p>A Brigada Militar realizou, nesta quinta-feira (25), tr\u00eas a\u00e7\u00f5es distintas que resultaram em <strong>tr\u00eas pris\u00f5es e na apreens\u00e3o de um adolescente<\/strong> por tr\u00e1fico de drogas em Cidreira, Balne\u00e1rio Pinhal e Palmares do Sul.<\/p>\n\n\n\n<p>Em <strong>Cidreira<\/strong>, um homem de 26 anos e um adolescente de 17 foram detidos ap\u00f3s tentarem fugir da abordagem policial. Com eles, foram apreendidas <strong>60 pedras de crack<\/strong>, por\u00e7\u00f5es de maconha e dinheiro.<\/p>\n\n\n\n<p>Em <strong>Balne\u00e1rio Pinhal<\/strong>, uma mulher de 24 anos foi presa em flagrante com <strong>129 por\u00e7\u00f5es de maconha<\/strong>, coca\u00edna, balan\u00e7a de precis\u00e3o e materiais para embalar droga, ap\u00f3s den\u00fancia de tr\u00e1fico no bairro Magist\u00e9rio.<\/p>\n\n\n\n<p>J\u00e1 em <strong>Palmares do Sul<\/strong>, um homem de 23 anos, com hist\u00f3rico criminal, foi preso ap\u00f3s ser localizado com <strong>mandado de pris\u00e3o em aberto<\/strong> por tr\u00e1fico de drogas.<\/p>\n\n\n\n<p>As a\u00e7\u00f5es foram conduzidas por equipes da <strong>For\u00e7a T\u00e1tica do 8\u00ba BPM<\/strong>, refor\u00e7ando o combate ao tr\u00e1fico na regi\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"17058\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-26-at-15.08.33-1024x768.jpeg\" alt=\"\" class=\"wp-image-17058\" srcset=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-26-at-15.08.33-1024x768.jpeg 1024w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-26-at-15.08.33-300x225.jpeg 300w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-26-at-15.08.33-768x576.jpeg 768w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-26-at-15.08.33-1536x1152.jpeg 1536w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-26-at-15.08.33.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Divulga\u00e7\u00e3o\/8BPM<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"17057\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-26-at-15.08.32-576x1024.jpeg\" alt=\"\" class=\"wp-image-17057\" srcset=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-26-at-15.08.32-576x1024.jpeg 576w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-26-at-15.08.32-169x300.jpeg 169w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-26-at-15.08.32-768x1365.jpeg 768w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-26-at-15.08.32.jpeg 828w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><figcaption class=\"wp-element-caption\">Foto: Divulga\u00e7\u00e3o\/8BPM<\/figcaption><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A Brigada Militar realizou, nesta quinta-feira (25), tr\u00eas a\u00e7\u00f5es distintas que resultaram em tr\u00eas pris\u00f5es e na apreens\u00e3o de um adolescente por tr\u00e1fico de drogas em Cidreira, Balne\u00e1rio Pinhal e Palmares do Sul. Em Cidreira, um homem de 26 anos e um adolescente de 17 foram detidos ap\u00f3s tentarem fugir da abordagem policial. Com eles, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17056,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[20,15],"tags":[103,92,1816,128],"class_list":["post-17055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-litoral_norte","category-noticias","tag-litoral-norte","tag-noticia","tag-prisoes","tag-rio-grande-do-sul"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BM prende tr\u00eas e apreende adolescente por tr\u00e1fico no Litoral Norte - Rede Litoral RS<\/title>\n<meta name=\"description\" content=\"A Brigada Militar realizou, nesta quinta-feira (25), tr\u00eas a\u00e7\u00f5es distintas que resultaram em tr\u00eas pris\u00f5es e na apreens\u00e3o de um adolescente por tr\u00e1fico de drogas em Cidreira, Balne\u00e1rio Pinhal e Palmares do Sul.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BM prende tr\u00eas e apreende adolescente por tr\u00e1fico no Litoral Norte - Rede Litoral RS\" \/>\n<meta property=\"og:description\" content=\"A Brigada Militar realizou, nesta quinta-feira (25), tr\u00eas a\u00e7\u00f5es distintas que resultaram em tr\u00eas pris\u00f5es e na apreens\u00e3o de um adolescente por tr\u00e1fico de drogas em Cidreira, Balne\u00e1rio Pinhal e Palmares do Sul.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\/\" \/>\n<meta property=\"og:site_name\" content=\"Rede Litoral RS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tvlitoralrsoficial\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-26T19:24:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-26T19:24:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-26-at-15.08.31.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\"},\"headline\":\"BM prende tr\u00eas e apreende adolescente por tr\u00e1fico no Litoral Norte\",\"datePublished\":\"2025-09-26T19:24:25+00:00\",\"dateModified\":\"2025-09-26T19:24:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\\\/\"},\"wordCount\":187,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/WhatsApp-Image-2025-09-26-at-15.08.31.jpeg\",\"keywords\":[\"litoral norte\",\"not\u00edcia\",\"pris\u00f5es\",\"rio grande do sul\"],\"articleSection\":[\"Litoral Norte\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\\\/\",\"name\":\"BM prende tr\u00eas e apreende adolescente por tr\u00e1fico no Litoral Norte - Rede Litoral RS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/WhatsApp-Image-2025-09-26-at-15.08.31.jpeg\",\"datePublished\":\"2025-09-26T19:24:25+00:00\",\"dateModified\":\"2025-09-26T19:24:26+00:00\",\"description\":\"A Brigada Militar realizou, nesta quinta-feira (25), tr\u00eas a\u00e7\u00f5es distintas que resultaram em tr\u00eas pris\u00f5es e na apreens\u00e3o de um adolescente por tr\u00e1fico de drogas em Cidreira, Balne\u00e1rio Pinhal e Palmares do Sul.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/WhatsApp-Image-2025-09-26-at-15.08.31.jpeg\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/WhatsApp-Image-2025-09-26-at-15.08.31.jpeg\",\"width\":1200,\"height\":1600,\"caption\":\"Foto: Divulga\u00e7\u00e3o\\\/8BPM\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/redelitoralrs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BM prende tr\u00eas e apreende adolescente por tr\u00e1fico no Litoral Norte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"name\":\"TV Litoral\",\"description\":\"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redelitoralrs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\",\"name\":\"TV Litoral\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"width\":454,\"height\":454,\"caption\":\"TV Litoral\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tvlitoralrsoficial\",\"https:\\\/\\\/www.instagram.com\\\/tvlitoral.rs\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\",\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"caption\":\"Reda\u00e7\u00e3o TV Litoral\"},\"description\":\"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.\",\"sameAs\":[\"https:\\\/\\\/redelitoralrs.com\",\"https:\\\/\\\/www.instagram.com\\\/redelitoralrs\",\"https:\\\/\\\/www.youtube.com\\\/@redelitoralrs\"],\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/author\\\/redacaotvlitoral\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BM prende tr\u00eas e apreende adolescente por tr\u00e1fico no Litoral Norte - Rede Litoral RS","description":"A Brigada Militar realizou, nesta quinta-feira (25), tr\u00eas a\u00e7\u00f5es distintas que resultaram em tr\u00eas pris\u00f5es e na apreens\u00e3o de um adolescente por tr\u00e1fico de drogas em Cidreira, Balne\u00e1rio Pinhal e Palmares do Sul.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\/","og_locale":"pt_BR","og_type":"article","og_title":"BM prende tr\u00eas e apreende adolescente por tr\u00e1fico no Litoral Norte - Rede Litoral RS","og_description":"A Brigada Militar realizou, nesta quinta-feira (25), tr\u00eas a\u00e7\u00f5es distintas que resultaram em tr\u00eas pris\u00f5es e na apreens\u00e3o de um adolescente por tr\u00e1fico de drogas em Cidreira, Balne\u00e1rio Pinhal e Palmares do Sul.","og_url":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\/","og_site_name":"Rede Litoral RS","article_publisher":"https:\/\/www.facebook.com\/tvlitoralrsoficial","article_published_time":"2025-09-26T19:24:25+00:00","article_modified_time":"2025-09-26T19:24:26+00:00","og_image":[{"width":1200,"height":1600,"url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-26-at-15.08.31.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o TV Litoral","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o TV Litoral","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\/#article","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\/"},"author":{"name":"Reda\u00e7\u00e3o TV Litoral","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a"},"headline":"BM prende tr\u00eas e apreende adolescente por tr\u00e1fico no Litoral Norte","datePublished":"2025-09-26T19:24:25+00:00","dateModified":"2025-09-26T19:24:26+00:00","mainEntityOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\/"},"wordCount":187,"commentCount":0,"publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-26-at-15.08.31.jpeg","keywords":["litoral norte","not\u00edcia","pris\u00f5es","rio grande do sul"],"articleSection":["Litoral Norte","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\/","url":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\/","name":"BM prende tr\u00eas e apreende adolescente por tr\u00e1fico no Litoral Norte - Rede Litoral RS","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\/#primaryimage"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-26-at-15.08.31.jpeg","datePublished":"2025-09-26T19:24:25+00:00","dateModified":"2025-09-26T19:24:26+00:00","description":"A Brigada Militar realizou, nesta quinta-feira (25), tr\u00eas a\u00e7\u00f5es distintas que resultaram em tr\u00eas pris\u00f5es e na apreens\u00e3o de um adolescente por tr\u00e1fico de drogas em Cidreira, Balne\u00e1rio Pinhal e Palmares do Sul.","breadcrumb":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\/#primaryimage","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-26-at-15.08.31.jpeg","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-26-at-15.08.31.jpeg","width":1200,"height":1600,"caption":"Foto: Divulga\u00e7\u00e3o\/8BPM"},{"@type":"BreadcrumbList","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-tres-e-apreende-adolescente-por-trafico-no-litoral-norte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/redelitoralrs.com\/"},{"@type":"ListItem","position":2,"name":"BM prende tr\u00eas e apreende adolescente por tr\u00e1fico no Litoral Norte"}]},{"@type":"WebSite","@id":"https:\/\/redelitoralrs.com\/#website","url":"https:\/\/redelitoralrs.com\/","name":"TV Litoral","description":"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.","publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redelitoralrs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redelitoralrs.com\/#organization","name":"TV Litoral","url":"https:\/\/redelitoralrs.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","width":454,"height":454,"caption":"TV Litoral"},"image":{"@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tvlitoralrsoficial","https:\/\/www.instagram.com\/tvlitoral.rs"]},{"@type":"Person","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a","name":"Reda\u00e7\u00e3o TV Litoral","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","url":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","caption":"Reda\u00e7\u00e3o TV Litoral"},"description":"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.","sameAs":["https:\/\/redelitoralrs.com","https:\/\/www.instagram.com\/redelitoralrs","https:\/\/www.youtube.com\/@redelitoralrs"],"url":"https:\/\/redelitoralrs.com\/index.php\/author\/redacaotvlitoral\/"}]}},"_links":{"self":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/17055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/comments?post=17055"}],"version-history":[{"count":1,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/17055\/revisions"}],"predecessor-version":[{"id":17059,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/17055\/revisions\/17059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media\/17056"}],"wp:attachment":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media?parent=17055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/categories?post=17055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/tags?post=17055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}