{"id":17008,"date":"2025-09-26T12:13:42","date_gmt":"2025-09-26T15:13:42","guid":{"rendered":"https:\/\/redelitoralrs.com\/?p=17008"},"modified":"2025-09-26T12:13:42","modified_gmt":"2025-09-26T15:13:42","slug":"bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul","status":"publish","type":"post","link":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\/","title":{"rendered":"BM prende foragido condenado a 19 anos por roubo em Palmares do Sul"},"content":{"rendered":"\n<p>A Brigada Militar prendeu, na noite de quarta-feira (24), um homem de 31 anos que estava foragido da Justi\u00e7a em Balne\u00e1rio Quint\u00e3o, distrito de Palmares do Sul. Contra ele, havia dois mandados de pris\u00e3o em aberto, somando 19 anos de condena\u00e7\u00e3o em regime fechado.<\/p>\n\n\n\n<p>A a\u00e7\u00e3o foi realizada por uma equipe da For\u00e7a T\u00e1tica do 8\u00ba Batalh\u00e3o de Pol\u00edcia Militar (8\u00ba BPM). Durante a abordagem, a consulta ao sistema policial confirmou as ordens judiciais expedidas contra o suspeito.<\/p>\n\n\n\n<p>As condena\u00e7\u00f5es referem-se ao crime de roubo, previsto no artigo 157 do C\u00f3digo Penal, que estabelece pena de reclus\u00e3o para quem subtrai bem alheio mediante grave amea\u00e7a ou viol\u00eancia \u00e0 pessoa.<\/p>\n\n\n\n<p>Ap\u00f3s a pris\u00e3o, o homem foi encaminhado ao sistema prisional para cumprimento da pena.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Brigada Militar prendeu, na noite de quarta-feira (24), um homem de 31 anos que estava foragido da Justi\u00e7a em Balne\u00e1rio Quint\u00e3o, distrito de Palmares do Sul. Contra ele, havia dois mandados de pris\u00e3o em aberto, somando 19 anos de condena\u00e7\u00e3o em regime fechado. A a\u00e7\u00e3o foi realizada por uma equipe da For\u00e7a T\u00e1tica do [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17009,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[240,98,15],"tags":[103,92,112,102,128],"class_list":["post-17008","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-palmares-do-sul","category-policia","category-noticias","tag-litoral-norte","tag-noticia","tag-palmares-do-sul","tag-policia","tag-rio-grande-do-sul"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BM prende foragido condenado a 19 anos por roubo em Palmares do Sul - Rede Litoral RS<\/title>\n<meta name=\"description\" content=\"A Brigada Militar prendeu, na noite de quarta-feira (24), um homem de 31 anos que estava foragido da Justi\u00e7a em Balne\u00e1rio Quint\u00e3o, distrito de Palmares do Sul. Contra ele, havia dois mandados de pris\u00e3o em aberto, somando 19 anos de condena\u00e7\u00e3o em regime fechado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BM prende foragido condenado a 19 anos por roubo em Palmares do Sul - Rede Litoral RS\" \/>\n<meta property=\"og:description\" content=\"A Brigada Militar prendeu, na noite de quarta-feira (24), um homem de 31 anos que estava foragido da Justi\u00e7a em Balne\u00e1rio Quint\u00e3o, distrito de Palmares do Sul. Contra ele, havia dois mandados de pris\u00e3o em aberto, somando 19 anos de condena\u00e7\u00e3o em regime fechado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\/\" \/>\n<meta property=\"og:site_name\" content=\"Rede Litoral RS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tvlitoralrsoficial\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-26T15:13:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/Imagem-do-WhatsApp-de-2025-09-25-as-09.08.49_bda467f4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\"},\"headline\":\"BM prende foragido condenado a 19 anos por roubo em Palmares do Sul\",\"datePublished\":\"2025-09-26T15:13:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\\\/\"},\"wordCount\":145,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Imagem-do-WhatsApp-de-2025-09-25-as-09.08.49_bda467f4.jpg\",\"keywords\":[\"litoral norte\",\"not\u00edcia\",\"palmares do sul\",\"pol\u00edcia\",\"rio grande do sul\"],\"articleSection\":[\"Palmares do Sul\",\"Pol\u00edcia\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\\\/\",\"name\":\"BM prende foragido condenado a 19 anos por roubo em Palmares do Sul - Rede Litoral RS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Imagem-do-WhatsApp-de-2025-09-25-as-09.08.49_bda467f4.jpg\",\"datePublished\":\"2025-09-26T15:13:42+00:00\",\"description\":\"A Brigada Militar prendeu, na noite de quarta-feira (24), um homem de 31 anos que estava foragido da Justi\u00e7a em Balne\u00e1rio Quint\u00e3o, distrito de Palmares do Sul. Contra ele, havia dois mandados de pris\u00e3o em aberto, somando 19 anos de condena\u00e7\u00e3o em regime fechado.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Imagem-do-WhatsApp-de-2025-09-25-as-09.08.49_bda467f4.jpg\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Imagem-do-WhatsApp-de-2025-09-25-as-09.08.49_bda467f4.jpg\",\"width\":1200,\"height\":1600,\"caption\":\"Foto: Soldado\u00a0PM\u00a0Rezende\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/26\\\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/redelitoralrs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BM prende foragido condenado a 19 anos por roubo em Palmares do Sul\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"name\":\"TV Litoral\",\"description\":\"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redelitoralrs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\",\"name\":\"TV Litoral\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"width\":454,\"height\":454,\"caption\":\"TV Litoral\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tvlitoralrsoficial\",\"https:\\\/\\\/www.instagram.com\\\/tvlitoral.rs\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\",\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"caption\":\"Reda\u00e7\u00e3o TV Litoral\"},\"description\":\"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.\",\"sameAs\":[\"https:\\\/\\\/redelitoralrs.com\",\"https:\\\/\\\/www.instagram.com\\\/redelitoralrs\",\"https:\\\/\\\/www.youtube.com\\\/@redelitoralrs\"],\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/author\\\/redacaotvlitoral\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BM prende foragido condenado a 19 anos por roubo em Palmares do Sul - Rede Litoral RS","description":"A Brigada Militar prendeu, na noite de quarta-feira (24), um homem de 31 anos que estava foragido da Justi\u00e7a em Balne\u00e1rio Quint\u00e3o, distrito de Palmares do Sul. Contra ele, havia dois mandados de pris\u00e3o em aberto, somando 19 anos de condena\u00e7\u00e3o em regime fechado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\/","og_locale":"pt_BR","og_type":"article","og_title":"BM prende foragido condenado a 19 anos por roubo em Palmares do Sul - Rede Litoral RS","og_description":"A Brigada Militar prendeu, na noite de quarta-feira (24), um homem de 31 anos que estava foragido da Justi\u00e7a em Balne\u00e1rio Quint\u00e3o, distrito de Palmares do Sul. Contra ele, havia dois mandados de pris\u00e3o em aberto, somando 19 anos de condena\u00e7\u00e3o em regime fechado.","og_url":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\/","og_site_name":"Rede Litoral RS","article_publisher":"https:\/\/www.facebook.com\/tvlitoralrsoficial","article_published_time":"2025-09-26T15:13:42+00:00","og_image":[{"width":1200,"height":1600,"url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/Imagem-do-WhatsApp-de-2025-09-25-as-09.08.49_bda467f4.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o TV Litoral","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o TV Litoral","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\/#article","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\/"},"author":{"name":"Reda\u00e7\u00e3o TV Litoral","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a"},"headline":"BM prende foragido condenado a 19 anos por roubo em Palmares do Sul","datePublished":"2025-09-26T15:13:42+00:00","mainEntityOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\/"},"wordCount":145,"commentCount":0,"publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/Imagem-do-WhatsApp-de-2025-09-25-as-09.08.49_bda467f4.jpg","keywords":["litoral norte","not\u00edcia","palmares do sul","pol\u00edcia","rio grande do sul"],"articleSection":["Palmares do Sul","Pol\u00edcia","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\/","url":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\/","name":"BM prende foragido condenado a 19 anos por roubo em Palmares do Sul - Rede Litoral RS","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\/#primaryimage"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/Imagem-do-WhatsApp-de-2025-09-25-as-09.08.49_bda467f4.jpg","datePublished":"2025-09-26T15:13:42+00:00","description":"A Brigada Militar prendeu, na noite de quarta-feira (24), um homem de 31 anos que estava foragido da Justi\u00e7a em Balne\u00e1rio Quint\u00e3o, distrito de Palmares do Sul. Contra ele, havia dois mandados de pris\u00e3o em aberto, somando 19 anos de condena\u00e7\u00e3o em regime fechado.","breadcrumb":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\/#primaryimage","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/Imagem-do-WhatsApp-de-2025-09-25-as-09.08.49_bda467f4.jpg","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/Imagem-do-WhatsApp-de-2025-09-25-as-09.08.49_bda467f4.jpg","width":1200,"height":1600,"caption":"Foto: Soldado\u00a0PM\u00a0Rezende"},{"@type":"BreadcrumbList","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/26\/bm-prende-foragido-condenado-a-19-anos-por-roubo-em-palmares-do-sul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/redelitoralrs.com\/"},{"@type":"ListItem","position":2,"name":"BM prende foragido condenado a 19 anos por roubo em Palmares do Sul"}]},{"@type":"WebSite","@id":"https:\/\/redelitoralrs.com\/#website","url":"https:\/\/redelitoralrs.com\/","name":"TV Litoral","description":"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.","publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redelitoralrs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redelitoralrs.com\/#organization","name":"TV Litoral","url":"https:\/\/redelitoralrs.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","width":454,"height":454,"caption":"TV Litoral"},"image":{"@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tvlitoralrsoficial","https:\/\/www.instagram.com\/tvlitoral.rs"]},{"@type":"Person","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a","name":"Reda\u00e7\u00e3o TV Litoral","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","url":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","caption":"Reda\u00e7\u00e3o TV Litoral"},"description":"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.","sameAs":["https:\/\/redelitoralrs.com","https:\/\/www.instagram.com\/redelitoralrs","https:\/\/www.youtube.com\/@redelitoralrs"],"url":"https:\/\/redelitoralrs.com\/index.php\/author\/redacaotvlitoral\/"}]}},"_links":{"self":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/17008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/comments?post=17008"}],"version-history":[{"count":1,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/17008\/revisions"}],"predecessor-version":[{"id":17010,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/17008\/revisions\/17010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media\/17009"}],"wp:attachment":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media?parent=17008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/categories?post=17008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/tags?post=17008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}