{"id":16700,"date":"2025-09-19T12:16:51","date_gmt":"2025-09-19T15:16:51","guid":{"rendered":"https:\/\/redelitoralrs.com\/?p=16700"},"modified":"2025-09-19T12:17:28","modified_gmt":"2025-09-19T15:17:28","slug":"governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil","status":"publish","type":"post","link":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/19\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\/","title":{"rendered":"Governo do RS entrega viaturas e equipamentos para refor\u00e7ar seguran\u00e7a e Defesa Civil"},"content":{"rendered":"\n<p>O governo do Estado entregou, nesta quinta-feira (18), <strong>264 viaturas e equipamentos<\/strong> para a Brigada Militar, Pol\u00edcia Civil, Corpo de Bombeiros Militar, Instituto-Geral de Per\u00edcias e Defesa Civil. O investimento ultrapassa <strong>R$ 87 milh\u00f5es<\/strong> e busca ampliar a capacidade de atua\u00e7\u00e3o das for\u00e7as de seguran\u00e7a e das estruturas de resposta a emerg\u00eancias clim\u00e1ticas.<\/p>\n\n\n\n<p>O ato ocorreu em frente ao Pal\u00e1cio Piratini, em Porto Alegre, e marcou mais uma etapa do programa de aparelhamento da seguran\u00e7a p\u00fablica. Os recursos vieram de diferentes fundos estaduais e conv\u00eanios, entre eles o Plano Rio Grande, o Fundo Estadual de Seguran\u00e7a P\u00fablica e o Programa de Incentivo ao Aparelhamento da Seguran\u00e7a P\u00fablica (Piseg).<\/p>\n\n\n\n<p>Entre os itens entregues est\u00e3o SUVs, camionetes, motocicletas, caminh\u00e3o-ba\u00fa, embarca\u00e7\u00f5es, guinchos, al\u00e9m de kits periciais e equipamentos de radiocomunica\u00e7\u00e3o. O refor\u00e7o beneficiar\u00e1 <strong>68 munic\u00edpios e dez coordenadorias regionais da Defesa Civil<\/strong>, fortalecendo tanto o enfrentamento da criminalidade quanto a resposta a situa\u00e7\u00f5es de desastre.<\/p>\n\n\n\n<p>Nos \u00faltimos anos, os n\u00fameros das corpora\u00e7\u00f5es cresceram. A Pol\u00edcia Civil, por exemplo, ampliou o efetivo de 4.976 para 5.503 agentes desde 2018 e passou de 2.222 para 2.777 viaturas. O Corpo de Bombeiros aumentou de 73 para 193 embarca\u00e7\u00f5es no mesmo per\u00edodo, al\u00e9m de quase dobrar a frota de ve\u00edculos.<\/p>\n\n\n\n<p>Segundo dados oficiais, os investimentos t\u00eam refletido em indicadores de criminalidade em queda. O Estado registra redu\u00e7\u00e3o de quase 90% nos roubos de ve\u00edculos, queda pr\u00f3xima a 80% nos roubos a pedestres e diminui\u00e7\u00e3o pela metade nos casos de homic\u00eddios, consolidando os menores \u00edndices da s\u00e9rie hist\u00f3rica.<\/p>\n\n\n\n<p>Essa \u00e9 a terceira grande entrega de recursos para a seguran\u00e7a p\u00fablica em 2025. Em maio, foram R$ 140 milh\u00f5es aplicados em ve\u00edculos, tecnologias e armamentos. Em julho, outros R$ 36 milh\u00f5es foram destinados \u00e0 Brigada Militar.<\/p>\n\n\n\n<div id=\"wp-block-themeisle-blocks-slider-d679096b\" class=\"wp-block-themeisle-blocks-slider glide\" data-per-view=\"1\" data-gap=\"0\" data-peek=\"0\" data-autoplay=\"true\" data-height=\"400px\" data-hide-arrows=\"false\"><div class=\"glide__track\" data-glide-el=\"track\"><div class=\"glide__slides\"><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/18170848_2213697_GDO.jpeg\" alt=\"\" title=\"\" data-id=\"16705\"\/><figcaption>Foto: Jo\u00e3o Pedro Rodrigues\/Secom<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/18171319_2213716_GDO.jpeg\" alt=\"\" title=\"\" data-id=\"16704\"\/><figcaption>Foto: Vitor Rosa\/Secom<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/18171634_2213768_GDO.jpeg\" alt=\"\" title=\"\" data-id=\"16703\"\/><figcaption>Foto: Vitor Rosa\/Secom<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/18171914_2213798_GDO.jpeg\" alt=\"\" title=\"\" data-id=\"16702\"\/><figcaption>Foto: Vitor Rosa\/Secom<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/18172038_2213817_GDO.jpeg\" alt=\"\" title=\"\" data-id=\"16701\"\/><figcaption>Foto: Jo\u00e3o Pedro Rodrigues\/Secom<\/figcaption><\/figure><\/div><\/div><div class=\"glide__bullets\" data-glide-el=\"controls[nav]\"><button class=\"glide__bullet\" data-glide-dir=\"=0\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=1\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=2\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=3\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=4\"><\/button><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O governo do Estado entregou, nesta quinta-feira (18), 264 viaturas e equipamentos para a Brigada Militar, Pol\u00edcia Civil, Corpo de Bombeiros Militar, Instituto-Geral de Per\u00edcias e Defesa Civil. O investimento ultrapassa R$ 87 milh\u00f5es e busca ampliar a capacidade de atua\u00e7\u00e3o das for\u00e7as de seguran\u00e7a e das estruturas de resposta a emerg\u00eancias clim\u00e1ticas. O ato [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":16706,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[188,15],"tags":[819,2007,513,103,92,102,128,1013],"class_list":["post-16700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rio-grande-do-sul","category-noticias","tag-eduardo-leite","tag-gov-rs","tag-governo-do-estado","tag-litoral-norte","tag-noticia","tag-policia","tag-rio-grande-do-sul","tag-seguranca-publica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governo do RS entrega viaturas e equipamentos para refor\u00e7ar seguran\u00e7a e Defesa Civil - Rede Litoral RS<\/title>\n<meta name=\"description\" content=\"O governo do Estado entregou, nesta quinta-feira (18), 264 viaturas e equipamentos para a Brigada Militar, Pol\u00edcia Civil, Corpo de Bombeiros Militar, Instituto-Geral de Per\u00edcias e Defesa Civil. O investimento ultrapassa R$ 87 milh\u00f5es e busca ampliar a capacidade de atua\u00e7\u00e3o das for\u00e7as de seguran\u00e7a e das estruturas de resposta a emerg\u00eancias clim\u00e1ticas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/19\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo do RS entrega viaturas e equipamentos para refor\u00e7ar seguran\u00e7a e Defesa Civil - Rede Litoral RS\" \/>\n<meta property=\"og:description\" content=\"O governo do Estado entregou, nesta quinta-feira (18), 264 viaturas e equipamentos para a Brigada Militar, Pol\u00edcia Civil, Corpo de Bombeiros Militar, Instituto-Geral de Per\u00edcias e Defesa Civil. O investimento ultrapassa R$ 87 milh\u00f5es e busca ampliar a capacidade de atua\u00e7\u00e3o das for\u00e7as de seguran\u00e7a e das estruturas de resposta a emerg\u00eancias clim\u00e1ticas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/19\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\/\" \/>\n<meta property=\"og:site_name\" content=\"Rede Litoral RS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tvlitoralrsoficial\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-19T15:16:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-19T15:17:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/18170413_2213678_GD.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"945\" \/>\n\t<meta property=\"og:image:height\" content=\"532\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/19\\\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/19\\\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\"},\"headline\":\"Governo do RS entrega viaturas e equipamentos para refor\u00e7ar seguran\u00e7a e Defesa Civil\",\"datePublished\":\"2025-09-19T15:16:51+00:00\",\"dateModified\":\"2025-09-19T15:17:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/19\\\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\\\/\"},\"wordCount\":352,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/19\\\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/18170413_2213678_GD.jpeg\",\"keywords\":[\"eduardo leite\",\"gov rs\",\"governo do estado\",\"litoral norte\",\"not\u00edcia\",\"pol\u00edcia\",\"rio grande do sul\",\"seguran\u00e7a p\u00fablica\"],\"articleSection\":[\"Rio Grande do Sul\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/19\\\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/19\\\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/19\\\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\\\/\",\"name\":\"Governo do RS entrega viaturas e equipamentos para refor\u00e7ar seguran\u00e7a e Defesa Civil - Rede Litoral RS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/19\\\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/19\\\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/18170413_2213678_GD.jpeg\",\"datePublished\":\"2025-09-19T15:16:51+00:00\",\"dateModified\":\"2025-09-19T15:17:28+00:00\",\"description\":\"O governo do Estado entregou, nesta quinta-feira (18), 264 viaturas e equipamentos para a Brigada Militar, Pol\u00edcia Civil, Corpo de Bombeiros Militar, Instituto-Geral de Per\u00edcias e Defesa Civil. O investimento ultrapassa R$ 87 milh\u00f5es e busca ampliar a capacidade de atua\u00e7\u00e3o das for\u00e7as de seguran\u00e7a e das estruturas de resposta a emerg\u00eancias clim\u00e1ticas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/19\\\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/19\\\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/19\\\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/18170413_2213678_GD.jpeg\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/18170413_2213678_GD.jpeg\",\"width\":945,\"height\":532,\"caption\":\"Foto: Jo\u00e3o Pedro Rodrigues\\\/Secom\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/19\\\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/redelitoralrs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governo do RS entrega viaturas e equipamentos para refor\u00e7ar seguran\u00e7a e Defesa Civil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"name\":\"TV Litoral\",\"description\":\"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redelitoralrs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\",\"name\":\"TV Litoral\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"width\":454,\"height\":454,\"caption\":\"TV Litoral\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tvlitoralrsoficial\",\"https:\\\/\\\/www.instagram.com\\\/tvlitoral.rs\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\",\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"caption\":\"Reda\u00e7\u00e3o TV Litoral\"},\"description\":\"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.\",\"sameAs\":[\"https:\\\/\\\/redelitoralrs.com\",\"https:\\\/\\\/www.instagram.com\\\/redelitoralrs\",\"https:\\\/\\\/www.youtube.com\\\/@redelitoralrs\"],\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/author\\\/redacaotvlitoral\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo do RS entrega viaturas e equipamentos para refor\u00e7ar seguran\u00e7a e Defesa Civil - Rede Litoral RS","description":"O governo do Estado entregou, nesta quinta-feira (18), 264 viaturas e equipamentos para a Brigada Militar, Pol\u00edcia Civil, Corpo de Bombeiros Militar, Instituto-Geral de Per\u00edcias e Defesa Civil. O investimento ultrapassa R$ 87 milh\u00f5es e busca ampliar a capacidade de atua\u00e7\u00e3o das for\u00e7as de seguran\u00e7a e das estruturas de resposta a emerg\u00eancias clim\u00e1ticas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/19\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\/","og_locale":"pt_BR","og_type":"article","og_title":"Governo do RS entrega viaturas e equipamentos para refor\u00e7ar seguran\u00e7a e Defesa Civil - Rede Litoral RS","og_description":"O governo do Estado entregou, nesta quinta-feira (18), 264 viaturas e equipamentos para a Brigada Militar, Pol\u00edcia Civil, Corpo de Bombeiros Militar, Instituto-Geral de Per\u00edcias e Defesa Civil. O investimento ultrapassa R$ 87 milh\u00f5es e busca ampliar a capacidade de atua\u00e7\u00e3o das for\u00e7as de seguran\u00e7a e das estruturas de resposta a emerg\u00eancias clim\u00e1ticas.","og_url":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/19\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\/","og_site_name":"Rede Litoral RS","article_publisher":"https:\/\/www.facebook.com\/tvlitoralrsoficial","article_published_time":"2025-09-19T15:16:51+00:00","article_modified_time":"2025-09-19T15:17:28+00:00","og_image":[{"width":945,"height":532,"url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/18170413_2213678_GD.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o TV Litoral","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o TV Litoral","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/19\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\/#article","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/19\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\/"},"author":{"name":"Reda\u00e7\u00e3o TV Litoral","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a"},"headline":"Governo do RS entrega viaturas e equipamentos para refor\u00e7ar seguran\u00e7a e Defesa Civil","datePublished":"2025-09-19T15:16:51+00:00","dateModified":"2025-09-19T15:17:28+00:00","mainEntityOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/19\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\/"},"wordCount":352,"commentCount":0,"publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/19\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/18170413_2213678_GD.jpeg","keywords":["eduardo leite","gov rs","governo do estado","litoral norte","not\u00edcia","pol\u00edcia","rio grande do sul","seguran\u00e7a p\u00fablica"],"articleSection":["Rio Grande do Sul","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/09\/19\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/19\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\/","url":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/19\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\/","name":"Governo do RS entrega viaturas e equipamentos para refor\u00e7ar seguran\u00e7a e Defesa Civil - Rede Litoral RS","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/19\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\/#primaryimage"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/19\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/18170413_2213678_GD.jpeg","datePublished":"2025-09-19T15:16:51+00:00","dateModified":"2025-09-19T15:17:28+00:00","description":"O governo do Estado entregou, nesta quinta-feira (18), 264 viaturas e equipamentos para a Brigada Militar, Pol\u00edcia Civil, Corpo de Bombeiros Militar, Instituto-Geral de Per\u00edcias e Defesa Civil. O investimento ultrapassa R$ 87 milh\u00f5es e busca ampliar a capacidade de atua\u00e7\u00e3o das for\u00e7as de seguran\u00e7a e das estruturas de resposta a emerg\u00eancias clim\u00e1ticas.","breadcrumb":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/19\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/09\/19\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/19\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\/#primaryimage","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/18170413_2213678_GD.jpeg","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/18170413_2213678_GD.jpeg","width":945,"height":532,"caption":"Foto: Jo\u00e3o Pedro Rodrigues\/Secom"},{"@type":"BreadcrumbList","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/19\/governo-do-rs-entrega-viaturas-e-equipamentos-para-reforcar-seguranca-e-defesa-civil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/redelitoralrs.com\/"},{"@type":"ListItem","position":2,"name":"Governo do RS entrega viaturas e equipamentos para refor\u00e7ar seguran\u00e7a e Defesa Civil"}]},{"@type":"WebSite","@id":"https:\/\/redelitoralrs.com\/#website","url":"https:\/\/redelitoralrs.com\/","name":"TV Litoral","description":"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.","publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redelitoralrs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redelitoralrs.com\/#organization","name":"TV Litoral","url":"https:\/\/redelitoralrs.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","width":454,"height":454,"caption":"TV Litoral"},"image":{"@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tvlitoralrsoficial","https:\/\/www.instagram.com\/tvlitoral.rs"]},{"@type":"Person","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a","name":"Reda\u00e7\u00e3o TV Litoral","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","url":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","caption":"Reda\u00e7\u00e3o TV Litoral"},"description":"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.","sameAs":["https:\/\/redelitoralrs.com","https:\/\/www.instagram.com\/redelitoralrs","https:\/\/www.youtube.com\/@redelitoralrs"],"url":"https:\/\/redelitoralrs.com\/index.php\/author\/redacaotvlitoral\/"}]}},"_links":{"self":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/16700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/comments?post=16700"}],"version-history":[{"count":1,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/16700\/revisions"}],"predecessor-version":[{"id":16707,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/16700\/revisions\/16707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media\/16706"}],"wp:attachment":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media?parent=16700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/categories?post=16700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/tags?post=16700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}