{"id":15802,"date":"2025-09-02T11:18:57","date_gmt":"2025-09-02T14:18:57","guid":{"rendered":"https:\/\/redelitoralrs.com\/?p=15802"},"modified":"2025-09-02T11:18:58","modified_gmt":"2025-09-02T14:18:58","slug":"justica-suspende-empreendimento-em-area-de-preservacao-ambiental","status":"publish","type":"post","link":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/02\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\/","title":{"rendered":"Justi\u00e7a suspende empreendimento em \u00e1rea de preserva\u00e7\u00e3o ambiental"},"content":{"rendered":"\n<p>A Justi\u00e7a Federal determinou a suspens\u00e3o de um loteamento em \u00e1rea de preserva\u00e7\u00e3o permanente (APP) no munic\u00edpio de Arroio do Sal, no Litoral Norte ga\u00facho. A decis\u00e3o, assinada pela ju\u00edza Rafaela Santos Martins da Rosa, da 9\u00aa Vara Federal de Porto Alegre, foi publicada em 22 de agosto.<\/p>\n\n\n\n<p>A a\u00e7\u00e3o foi movida pelo Minist\u00e9rio P\u00fablico Federal (MPF), que apontou a instala\u00e7\u00e3o de um empreendimento imobili\u00e1rio em \u00e1rea de dunas, com abertura de ruas e retirada de vegeta\u00e7\u00e3o nativa, sem a devida licen\u00e7a ambiental. O \u00f3rg\u00e3o tamb\u00e9m pediu a suspens\u00e3o da comercializa\u00e7\u00e3o dos lotes, a proibi\u00e7\u00e3o de interven\u00e7\u00f5es sobre im\u00f3veis em \u00e1reas arqueol\u00f3gicas e o cancelamento da licen\u00e7a de instala\u00e7\u00e3o concedida pela prefeitura.<\/p>\n\n\n\n<p>Durante a investiga\u00e7\u00e3o, uma vistoria da Guarni\u00e7\u00e3o de Policiamento Ambiental do Estado constatou que o loteamento j\u00e1 estava em andamento. O Instituto do Patrim\u00f4nio Hist\u00f3rico e Art\u00edstico Nacional (Iphan) identificou dois s\u00edtios arqueol\u00f3gicos pr\u00f3ximos ao local, sem comprova\u00e7\u00e3o de danos, mas destacou a necessidade de delimitar a \u00e1rea de preserva\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Decis\u00e3o judicial<\/h3>\n\n\n\n<p>Na senten\u00e7a, a magistrada determinou que a empresa respons\u00e1vel, seu s\u00f3cio e o munic\u00edpio devem se abster de realizar qualquer interven\u00e7\u00e3o at\u00e9 que sejam obtidas as licen\u00e7as ambientais exigidas pelo Ibama e pelo Iphan. Isso inclui a paralisa\u00e7\u00e3o de obras de abertura de vias e a proibi\u00e7\u00e3o da venda de lotes.<\/p>\n\n\n\n<p>A prefeitura, que havia autorizado a abertura de quatro ruas, tamb\u00e9m fica impedida de conceder novas licen\u00e7as relacionadas ao empreendimento sem a apresenta\u00e7\u00e3o da documenta\u00e7\u00e3o ambiental adequada.<\/p>\n\n\n\n<p>O pedido de indeniza\u00e7\u00e3o por danos coletivos n\u00e3o foi aceito, j\u00e1 que n\u00e3o houve comprova\u00e7\u00e3o de preju\u00edzo aos s\u00edtios arqueol\u00f3gicos.<\/p>\n\n\n\n<p>A decis\u00e3o \u00e9 de primeira inst\u00e2ncia e cabe recurso ao Tribunal Regional Federal da 4\u00aa Regi\u00e3o (TRF4).<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Justi\u00e7a Federal determinou a suspens\u00e3o de um loteamento em \u00e1rea de preserva\u00e7\u00e3o permanente (APP) no munic\u00edpio de Arroio do Sal, no Litoral Norte ga\u00facho. A decis\u00e3o, assinada pela ju\u00edza Rafaela Santos Martins da Rosa, da 9\u00aa Vara Federal de Porto Alegre, foi publicada em 22 de agosto. A a\u00e7\u00e3o foi movida pelo Minist\u00e9rio P\u00fablico [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":15803,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[29,15],"tags":[174,103,1783,92,1782,128],"class_list":["post-15802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arroio-do-sal","category-noticias","tag-arroio-do-sal","tag-litoral-norte","tag-loteamento","tag-noticia","tag-preservacao-ambiental","tag-rio-grande-do-sul"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Justi\u00e7a suspende empreendimento em \u00e1rea de preserva\u00e7\u00e3o ambiental - Rede Litoral RS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/02\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Justi\u00e7a suspende empreendimento em \u00e1rea de preserva\u00e7\u00e3o ambiental - Rede Litoral RS\" \/>\n<meta property=\"og:description\" content=\"A Justi\u00e7a Federal determinou a suspens\u00e3o de um loteamento em \u00e1rea de preserva\u00e7\u00e3o permanente (APP) no munic\u00edpio de Arroio do Sal, no Litoral Norte ga\u00facho. A decis\u00e3o, assinada pela ju\u00edza Rafaela Santos Martins da Rosa, da 9\u00aa Vara Federal de Porto Alegre, foi publicada em 22 de agosto. A a\u00e7\u00e3o foi movida pelo Minist\u00e9rio P\u00fablico [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/02\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\/\" \/>\n<meta property=\"og:site_name\" content=\"Rede Litoral RS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tvlitoralrsoficial\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-02T14:18:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-02T14:18:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/tha85_empreendimento-em-area-de-preservacao.png\" \/>\n\t<meta property=\"og:image:width\" content=\"569\" \/>\n\t<meta property=\"og:image:height\" content=\"335\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/02\\\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/02\\\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\"},\"headline\":\"Justi\u00e7a suspende empreendimento em \u00e1rea de preserva\u00e7\u00e3o ambiental\",\"datePublished\":\"2025-09-02T14:18:57+00:00\",\"dateModified\":\"2025-09-02T14:18:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/02\\\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\\\/\"},\"wordCount\":342,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/02\\\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/tha85_empreendimento-em-area-de-preservacao.png\",\"keywords\":[\"Arroio do Sal\",\"litoral norte\",\"loteamento\",\"not\u00edcia\",\"preserva\u00e7\u00e3o ambiental\",\"rio grande do sul\"],\"articleSection\":[\"Arroio do Sal\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/02\\\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/02\\\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/02\\\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\\\/\",\"name\":\"Justi\u00e7a suspende empreendimento em \u00e1rea de preserva\u00e7\u00e3o ambiental - Rede Litoral RS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/02\\\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/02\\\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/tha85_empreendimento-em-area-de-preservacao.png\",\"datePublished\":\"2025-09-02T14:18:57+00:00\",\"dateModified\":\"2025-09-02T14:18:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/02\\\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/02\\\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/02\\\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/tha85_empreendimento-em-area-de-preservacao.png\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/tha85_empreendimento-em-area-de-preservacao.png\",\"width\":569,\"height\":335,\"caption\":\"Foto: Divulga\u00e7\u00e3o\\\/TRF\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/09\\\/02\\\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/redelitoralrs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Justi\u00e7a suspende empreendimento em \u00e1rea de preserva\u00e7\u00e3o ambiental\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"name\":\"TV Litoral\",\"description\":\"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redelitoralrs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\",\"name\":\"TV Litoral\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"width\":454,\"height\":454,\"caption\":\"TV Litoral\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tvlitoralrsoficial\",\"https:\\\/\\\/www.instagram.com\\\/tvlitoral.rs\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\",\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"caption\":\"Reda\u00e7\u00e3o TV Litoral\"},\"description\":\"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.\",\"sameAs\":[\"https:\\\/\\\/redelitoralrs.com\",\"https:\\\/\\\/www.instagram.com\\\/redelitoralrs\",\"https:\\\/\\\/www.youtube.com\\\/@redelitoralrs\"],\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/author\\\/redacaotvlitoral\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Justi\u00e7a suspende empreendimento em \u00e1rea de preserva\u00e7\u00e3o ambiental - Rede Litoral RS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/02\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\/","og_locale":"pt_BR","og_type":"article","og_title":"Justi\u00e7a suspende empreendimento em \u00e1rea de preserva\u00e7\u00e3o ambiental - Rede Litoral RS","og_description":"A Justi\u00e7a Federal determinou a suspens\u00e3o de um loteamento em \u00e1rea de preserva\u00e7\u00e3o permanente (APP) no munic\u00edpio de Arroio do Sal, no Litoral Norte ga\u00facho. A decis\u00e3o, assinada pela ju\u00edza Rafaela Santos Martins da Rosa, da 9\u00aa Vara Federal de Porto Alegre, foi publicada em 22 de agosto. A a\u00e7\u00e3o foi movida pelo Minist\u00e9rio P\u00fablico [&hellip;]","og_url":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/02\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\/","og_site_name":"Rede Litoral RS","article_publisher":"https:\/\/www.facebook.com\/tvlitoralrsoficial","article_published_time":"2025-09-02T14:18:57+00:00","article_modified_time":"2025-09-02T14:18:58+00:00","og_image":[{"width":569,"height":335,"url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/tha85_empreendimento-em-area-de-preservacao.png","type":"image\/png"}],"author":"Reda\u00e7\u00e3o TV Litoral","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o TV Litoral","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/02\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\/#article","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/02\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\/"},"author":{"name":"Reda\u00e7\u00e3o TV Litoral","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a"},"headline":"Justi\u00e7a suspende empreendimento em \u00e1rea de preserva\u00e7\u00e3o ambiental","datePublished":"2025-09-02T14:18:57+00:00","dateModified":"2025-09-02T14:18:58+00:00","mainEntityOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/02\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\/"},"wordCount":342,"commentCount":0,"publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/02\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/tha85_empreendimento-em-area-de-preservacao.png","keywords":["Arroio do Sal","litoral norte","loteamento","not\u00edcia","preserva\u00e7\u00e3o ambiental","rio grande do sul"],"articleSection":["Arroio do Sal","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/09\/02\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/02\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\/","url":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/02\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\/","name":"Justi\u00e7a suspende empreendimento em \u00e1rea de preserva\u00e7\u00e3o ambiental - Rede Litoral RS","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/02\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\/#primaryimage"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/02\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/tha85_empreendimento-em-area-de-preservacao.png","datePublished":"2025-09-02T14:18:57+00:00","dateModified":"2025-09-02T14:18:58+00:00","breadcrumb":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/02\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/09\/02\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/02\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\/#primaryimage","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/tha85_empreendimento-em-area-de-preservacao.png","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/09\/tha85_empreendimento-em-area-de-preservacao.png","width":569,"height":335,"caption":"Foto: Divulga\u00e7\u00e3o\/TRF"},{"@type":"BreadcrumbList","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/09\/02\/justica-suspende-empreendimento-em-area-de-preservacao-ambiental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/redelitoralrs.com\/"},{"@type":"ListItem","position":2,"name":"Justi\u00e7a suspende empreendimento em \u00e1rea de preserva\u00e7\u00e3o ambiental"}]},{"@type":"WebSite","@id":"https:\/\/redelitoralrs.com\/#website","url":"https:\/\/redelitoralrs.com\/","name":"TV Litoral","description":"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.","publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redelitoralrs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redelitoralrs.com\/#organization","name":"TV Litoral","url":"https:\/\/redelitoralrs.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","width":454,"height":454,"caption":"TV Litoral"},"image":{"@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tvlitoralrsoficial","https:\/\/www.instagram.com\/tvlitoral.rs"]},{"@type":"Person","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a","name":"Reda\u00e7\u00e3o TV Litoral","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","url":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","caption":"Reda\u00e7\u00e3o TV Litoral"},"description":"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.","sameAs":["https:\/\/redelitoralrs.com","https:\/\/www.instagram.com\/redelitoralrs","https:\/\/www.youtube.com\/@redelitoralrs"],"url":"https:\/\/redelitoralrs.com\/index.php\/author\/redacaotvlitoral\/"}]}},"_links":{"self":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/15802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/comments?post=15802"}],"version-history":[{"count":1,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/15802\/revisions"}],"predecessor-version":[{"id":15804,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/15802\/revisions\/15804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media\/15803"}],"wp:attachment":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media?parent=15802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/categories?post=15802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/tags?post=15802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}