{"id":15565,"date":"2025-08-28T14:50:12","date_gmt":"2025-08-28T17:50:12","guid":{"rendered":"https:\/\/redelitoralrs.com\/?p=15565"},"modified":"2025-08-28T14:50:40","modified_gmt":"2025-08-28T17:50:40","slug":"escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024","status":"publish","type":"post","link":"https:\/\/redelitoralrs.com\/index.php\/2025\/08\/28\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\/","title":{"rendered":"Escola de Os\u00f3rio est\u00e1 entre as melhores do pa\u00eds no Enem 2024"},"content":{"rendered":"\n<p>O Rio Grande do Sul se destacou no Exame Nacional do Ensino M\u00e9dio (Enem) 2024, com o maior n\u00famero de escolas estaduais entre as 50 melhores notas do pa\u00eds em institui\u00e7\u00f5es de acesso universal \u2014 aquelas sem processo seletivo. Entre as 12 escolas ga\u00fachas presentes na lista, est\u00e1 a Escola Estadual Ildefonso Sim\u00f5es Lopes, de Os\u00f3rio, representando o Litoral Norte no ranking de excel\u00eancia.<\/p>\n\n\n\n<p>O destaque estadual ficou com a Escola Estadual Guilherme Exner, de Presidente Lucena, que obteve a maior nota m\u00e9dia do pa\u00eds entre escolas p\u00fablicas sem sele\u00e7\u00e3o, com 632,8 pontos. Considerando todas as escolas estaduais, incluindo as que realizam sele\u00e7\u00e3o, o Col\u00e9gio Tiradentes de Iju\u00ed liderou o ranking nacional.<\/p>\n\n\n\n<p>Outras escolas ga\u00fachas que figuram entre as melhores incluem Dante Grossi (Garibaldi), 25 de Maio (Imigrante), Ant\u00f4nio Stella (Ibiraiaras), 20 de Setembro (Cai\u00e7ara), Costa e Silva (\u00c1urea), 10 de Setembro (Dois Irm\u00e3os), Fernando Ferrari (Campo Bom), S\u00e3o Pio X (Farroupilha), Dion\u00edsio Lothario Chassot (Tapera) e Jo\u00e3o XXIII (Campina das Miss\u00f5es).<\/p>\n\n\n\n<p>Segundo o Instituto Nacional de Estudos e Pesquisas Educacionais An\u00edsio Teixeira (Inep), 70.429 estudantes concluintes do Ensino M\u00e9dio em escolas p\u00fablicas ga\u00fachas participaram do Enem 2024, equivalente a 89% do total de formandos \u2014 quase tr\u00eas vezes mais que os 26 mil inscritos em 2023. Apesar do aumento de participantes, a Rede Estadual do RS manteve a segunda maior m\u00e9dia de desempenho entre estados do pa\u00eds.<\/p>\n\n\n\n<p>O resultado reflete a\u00e7\u00f5es da Secretaria Estadual da Educa\u00e7\u00e3o (Seduc), que implementou a campanha \u201cVamo pra Cima\u201d, levando caravanas a todas as 30 Coordenadorias Regionais de Educa\u00e7\u00e3o, distribuindo materiais did\u00e1ticos, promovendo aul\u00f5es online e garantindo kits de alimenta\u00e7\u00e3o e aux\u00edlio-transporte nos dias de prova.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Rio Grande do Sul se destacou no Exame Nacional do Ensino M\u00e9dio (Enem) 2024, com o maior n\u00famero de escolas estaduais entre as 50 melhores notas do pa\u00eds em institui\u00e7\u00f5es de acesso universal \u2014 aquelas sem processo seletivo. Entre as 12 escolas ga\u00fachas presentes na lista, est\u00e1 a Escola Estadual Ildefonso Sim\u00f5es Lopes, de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":15566,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[228,172,15],"tags":[139,1744,103,92,256,128],"class_list":["post-15565","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","category-osorio","category-noticias","tag-educacao","tag-escola-rural","tag-litoral-norte","tag-noticia","tag-osorio-2","tag-rio-grande-do-sul"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Escola de Os\u00f3rio est\u00e1 entre as melhores do pa\u00eds no Enem 2024 - Rede Litoral RS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redelitoralrs.com\/index.php\/2025\/08\/28\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Escola de Os\u00f3rio est\u00e1 entre as melhores do pa\u00eds no Enem 2024 - Rede Litoral RS\" \/>\n<meta property=\"og:description\" content=\"O Rio Grande do Sul se destacou no Exame Nacional do Ensino M\u00e9dio (Enem) 2024, com o maior n\u00famero de escolas estaduais entre as 50 melhores notas do pa\u00eds em institui\u00e7\u00f5es de acesso universal \u2014 aquelas sem processo seletivo. Entre as 12 escolas ga\u00fachas presentes na lista, est\u00e1 a Escola Estadual Ildefonso Sim\u00f5es Lopes, de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redelitoralrs.com\/index.php\/2025\/08\/28\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Rede Litoral RS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tvlitoralrsoficial\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-28T17:50:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-28T17:50:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/08\/04094211_246753_GD.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/08\\\/28\\\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/08\\\/28\\\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\"},\"headline\":\"Escola de Os\u00f3rio est\u00e1 entre as melhores do pa\u00eds no Enem 2024\",\"datePublished\":\"2025-08-28T17:50:12+00:00\",\"dateModified\":\"2025-08-28T17:50:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/08\\\/28\\\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\\\/\"},\"wordCount\":306,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/08\\\/28\\\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/04094211_246753_GD.jpg\",\"keywords\":[\"educa\u00e7\u00e3o\",\"escola rural\",\"litoral norte\",\"not\u00edcia\",\"osorio\",\"rio grande do sul\"],\"articleSection\":[\"Educa\u00e7\u00e3o\",\"Os\u00f3rio\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/08\\\/28\\\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/08\\\/28\\\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/08\\\/28\\\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\\\/\",\"name\":\"Escola de Os\u00f3rio est\u00e1 entre as melhores do pa\u00eds no Enem 2024 - Rede Litoral RS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/08\\\/28\\\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/08\\\/28\\\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/04094211_246753_GD.jpg\",\"datePublished\":\"2025-08-28T17:50:12+00:00\",\"dateModified\":\"2025-08-28T17:50:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/08\\\/28\\\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/08\\\/28\\\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/08\\\/28\\\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/04094211_246753_GD.jpg\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/04094211_246753_GD.jpg\",\"width\":800,\"height\":450,\"caption\":\"Foto: Ag\u00eancia Preview\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/08\\\/28\\\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/redelitoralrs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Escola de Os\u00f3rio est\u00e1 entre as melhores do pa\u00eds no Enem 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"name\":\"TV Litoral\",\"description\":\"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redelitoralrs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\",\"name\":\"TV Litoral\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"width\":454,\"height\":454,\"caption\":\"TV Litoral\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tvlitoralrsoficial\",\"https:\\\/\\\/www.instagram.com\\\/tvlitoral.rs\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\",\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"caption\":\"Reda\u00e7\u00e3o TV Litoral\"},\"description\":\"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.\",\"sameAs\":[\"https:\\\/\\\/redelitoralrs.com\",\"https:\\\/\\\/www.instagram.com\\\/redelitoralrs\",\"https:\\\/\\\/www.youtube.com\\\/@redelitoralrs\"],\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/author\\\/redacaotvlitoral\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Escola de Os\u00f3rio est\u00e1 entre as melhores do pa\u00eds no Enem 2024 - Rede Litoral RS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redelitoralrs.com\/index.php\/2025\/08\/28\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\/","og_locale":"pt_BR","og_type":"article","og_title":"Escola de Os\u00f3rio est\u00e1 entre as melhores do pa\u00eds no Enem 2024 - Rede Litoral RS","og_description":"O Rio Grande do Sul se destacou no Exame Nacional do Ensino M\u00e9dio (Enem) 2024, com o maior n\u00famero de escolas estaduais entre as 50 melhores notas do pa\u00eds em institui\u00e7\u00f5es de acesso universal \u2014 aquelas sem processo seletivo. Entre as 12 escolas ga\u00fachas presentes na lista, est\u00e1 a Escola Estadual Ildefonso Sim\u00f5es Lopes, de [&hellip;]","og_url":"https:\/\/redelitoralrs.com\/index.php\/2025\/08\/28\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\/","og_site_name":"Rede Litoral RS","article_publisher":"https:\/\/www.facebook.com\/tvlitoralrsoficial","article_published_time":"2025-08-28T17:50:12+00:00","article_modified_time":"2025-08-28T17:50:40+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/08\/04094211_246753_GD.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o TV Litoral","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o TV Litoral","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/08\/28\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\/#article","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/08\/28\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\/"},"author":{"name":"Reda\u00e7\u00e3o TV Litoral","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a"},"headline":"Escola de Os\u00f3rio est\u00e1 entre as melhores do pa\u00eds no Enem 2024","datePublished":"2025-08-28T17:50:12+00:00","dateModified":"2025-08-28T17:50:40+00:00","mainEntityOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/08\/28\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\/"},"wordCount":306,"commentCount":0,"publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/08\/28\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/08\/04094211_246753_GD.jpg","keywords":["educa\u00e7\u00e3o","escola rural","litoral norte","not\u00edcia","osorio","rio grande do sul"],"articleSection":["Educa\u00e7\u00e3o","Os\u00f3rio","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/08\/28\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/08\/28\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\/","url":"https:\/\/redelitoralrs.com\/index.php\/2025\/08\/28\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\/","name":"Escola de Os\u00f3rio est\u00e1 entre as melhores do pa\u00eds no Enem 2024 - Rede Litoral RS","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/08\/28\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\/#primaryimage"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/08\/28\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/08\/04094211_246753_GD.jpg","datePublished":"2025-08-28T17:50:12+00:00","dateModified":"2025-08-28T17:50:40+00:00","breadcrumb":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/08\/28\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/08\/28\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/08\/28\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\/#primaryimage","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/08\/04094211_246753_GD.jpg","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/08\/04094211_246753_GD.jpg","width":800,"height":450,"caption":"Foto: Ag\u00eancia Preview"},{"@type":"BreadcrumbList","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/08\/28\/escola-de-osorio-esta-entre-as-melhores-do-pais-no-enem-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/redelitoralrs.com\/"},{"@type":"ListItem","position":2,"name":"Escola de Os\u00f3rio est\u00e1 entre as melhores do pa\u00eds no Enem 2024"}]},{"@type":"WebSite","@id":"https:\/\/redelitoralrs.com\/#website","url":"https:\/\/redelitoralrs.com\/","name":"TV Litoral","description":"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.","publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redelitoralrs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redelitoralrs.com\/#organization","name":"TV Litoral","url":"https:\/\/redelitoralrs.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","width":454,"height":454,"caption":"TV Litoral"},"image":{"@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tvlitoralrsoficial","https:\/\/www.instagram.com\/tvlitoral.rs"]},{"@type":"Person","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a","name":"Reda\u00e7\u00e3o TV Litoral","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","url":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","caption":"Reda\u00e7\u00e3o TV Litoral"},"description":"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.","sameAs":["https:\/\/redelitoralrs.com","https:\/\/www.instagram.com\/redelitoralrs","https:\/\/www.youtube.com\/@redelitoralrs"],"url":"https:\/\/redelitoralrs.com\/index.php\/author\/redacaotvlitoral\/"}]}},"_links":{"self":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/15565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/comments?post=15565"}],"version-history":[{"count":1,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/15565\/revisions"}],"predecessor-version":[{"id":15567,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/15565\/revisions\/15567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media\/15566"}],"wp:attachment":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media?parent=15565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/categories?post=15565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/tags?post=15565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}