{"id":13806,"date":"2025-07-21T14:29:37","date_gmt":"2025-07-21T17:29:37","guid":{"rendered":"https:\/\/redelitoralrs.com\/?p=13806"},"modified":"2025-07-21T14:29:38","modified_gmt":"2025-07-21T17:29:38","slug":"festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia","status":"publish","type":"post","link":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\/","title":{"rendered":"Festival de Inverno movimenta Cap\u00e3o da Canoa no fim de semana de estreia"},"content":{"rendered":"\n<p>Cap\u00e3o da Canoa deu in\u00edcio ao seu 1\u00ba Festival de Inverno com uma programa\u00e7\u00e3o que promete aquecer a cidade mesmo na esta\u00e7\u00e3o mais fria do ano. A abertura oficial ocorreu na noite da \u00faltima sexta-feira (18), na Casa de Cultura \u00c9rico Ver\u00edssimo, com a presen\u00e7a de autoridades, atra\u00e7\u00f5es culturais e p\u00fablico que prestigiou o in\u00edcio do evento. A Rede Litoral acompanhou a solenidade e tamb\u00e9m esteve presente nas primeiras atividades da programa\u00e7\u00e3o.<\/p>\n\n\n\n<p>No s\u00e1bado (19) e domingo (20), o destaque ficou por conta dos carrinhos a vela do Wind Car, que chamaram a aten\u00e7\u00e3o na beira-mar com demonstra\u00e7\u00f5es e competi\u00e7\u00f5es. A iniciativa proporcionou ao p\u00fablico a experi\u00eancia de &#8220;velejar&#8221; sobre as areias da cidade. A beira-mar tamb\u00e9m foi palco para aulas de skate voltadas ao p\u00fablico infantil e para o animado Dia Geek, que reuniu f\u00e3s de anime e cosplay em um festival para todas as idades.<\/p>\n\n\n\n<p>Com atividades culturais, esportivas e gastron\u00f4micas, o Festival segue at\u00e9 o dia 3 de agosto. O pr\u00f3ximo fim de semana promete atrair novamente a comunidade e visitantes com o Festival da Cerveja e do Chope Artesanal, entre os dias 25 e 27, na Pra\u00e7a Jos\u00e9 Agostinelli. Est\u00e3o previstas ainda apresenta\u00e7\u00f5es de bandas e fanfarras, encontro de motociclistas, aulas de dan\u00e7a e, encerrando a programa\u00e7\u00e3o, a 1\u00aa Maratona de Cap\u00e3o da Canoa, com largada no Parque N\u00e1utico, no dia 3.<\/p>\n\n\n\n<p>A Rede Litoral seguir\u00e1 acompanhando e trazendo todos os detalhes desta programa\u00e7\u00e3o que valoriza a cultura local e movimenta o turismo mesmo fora da alta temporada.<\/p>\n\n\n\n<div id=\"wp-block-themeisle-blocks-slider-ac590cf7\" class=\"wp-block-themeisle-blocks-slider glide\" data-per-view=\"1\" data-gap=\"0\" data-peek=\"0\" data-autoplay=\"true\" data-height=\"1000px\" data-hide-arrows=\"false\"><div class=\"glide__track\" data-glide-el=\"track\"><div class=\"glide__slides\"><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/SaveClip.App_522372456_18231540166294227_5762542421507469132_n.jpg\" alt=\"\" title=\"\" data-id=\"13819\"\/><figcaption>Foto: Imprensa\/PMCC<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/SaveClip.App_522219046_18231540082294227_140625421436448523_n.jpg\" alt=\"\" title=\"\" data-id=\"13818\"\/><figcaption>Foto: Imprensa\/PMCC<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/SaveClip.App_522076500_18231540118294227_5362680233782499597_n.jpg\" alt=\"\" title=\"\" data-id=\"13817\"\/><figcaption>Foto: Imprensa\/PMCC<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/SaveClip.App_521956600_18231540193294227_2523483544337630797_n.jpg\" alt=\"\" title=\"\" data-id=\"13816\"\/><figcaption>Foto: Imprensa\/PMCC<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/SaveClip.App_521771513_18231540022294227_1493453139164537209_n.jpg\" alt=\"\" title=\"\" data-id=\"13815\"\/><figcaption>Foto: Imprensa\/PMCC<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/SaveClip.App_521435971_18231540055294227_3687279994025808385_n.jpg\" alt=\"\" title=\"\" data-id=\"13813\"\/><figcaption>Foto: Imprensa\/PMCC<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/SaveClip.App_521432141_18231540100294227_3538845793637530217_n.jpg\" alt=\"\" title=\"\" data-id=\"13812\"\/><figcaption>Foto: Imprensa\/PMCC<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/SaveClip.App_521432140_18231540091294227_5743617001176249312_n.jpg\" alt=\"\" title=\"\" data-id=\"13811\"\/><figcaption>Foto: Imprensa\/PMCC<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/SaveClip.App_520819857_18231540031294227_8599299827722389964_n.jpg\" alt=\"\" title=\"\" data-id=\"13810\"\/><figcaption>Foto: Imprensa\/PMCC<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/SaveClip.App_520779772_18231540127294227_6868497216606204515_n.jpg\" alt=\"\" title=\"\" data-id=\"13809\"\/><figcaption>Foto: Imprensa\/PMCC<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/SaveClip.App_520717570_18231540064294227_8912260591632620228_n.jpg\" alt=\"\" title=\"\" data-id=\"13808\"\/><figcaption>Foto: Imprensa\/PMCC<\/figcaption><\/figure><\/div><div class=\"wp-block-themeisle-blocks-slider-item-wrapper glide__slide\" tabindex=\"0\"><figure><img decoding=\"async\" class=\"wp-block-themeisle-blocks-slider-item\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/SaveClip.App_520709939_18231540073294227_6271066287981030817_n.jpg\" alt=\"\" title=\"\" data-id=\"13807\"\/><figcaption>Foto: Imprensa\/PMCC<\/figcaption><\/figure><\/div><\/div><div class=\"glide__bullets\" data-glide-el=\"controls[nav]\"><button class=\"glide__bullet\" data-glide-dir=\"=0\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=1\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=2\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=3\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=4\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=5\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=6\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=7\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=8\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=9\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=10\"><\/button><button class=\"glide__bullet\" data-glide-dir=\"=11\"><\/button><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cap\u00e3o da Canoa deu in\u00edcio ao seu 1\u00ba Festival de Inverno com uma programa\u00e7\u00e3o que promete aquecer a cidade mesmo na esta\u00e7\u00e3o mais fria do ano. A abertura oficial ocorreu na noite da \u00faltima sexta-feira (18), na Casa de Cultura \u00c9rico Ver\u00edssimo, com a presen\u00e7a de autoridades, atra\u00e7\u00f5es culturais e p\u00fablico que prestigiou o in\u00edcio [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13814,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[24,15],"tags":[274,1352,103,92,128],"class_list":["post-13806","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-capao-da-canoa","category-noticias","tag-capao-da-canoa-2","tag-gastronomia","tag-litoral-norte","tag-noticia","tag-rio-grande-do-sul"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Festival de Inverno movimenta Cap\u00e3o da Canoa no fim de semana de estreia - Rede Litoral RS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festival de Inverno movimenta Cap\u00e3o da Canoa no fim de semana de estreia - Rede Litoral RS\" \/>\n<meta property=\"og:description\" content=\"Cap\u00e3o da Canoa deu in\u00edcio ao seu 1\u00ba Festival de Inverno com uma programa\u00e7\u00e3o que promete aquecer a cidade mesmo na esta\u00e7\u00e3o mais fria do ano. A abertura oficial ocorreu na noite da \u00faltima sexta-feira (18), na Casa de Cultura \u00c9rico Ver\u00edssimo, com a presen\u00e7a de autoridades, atra\u00e7\u00f5es culturais e p\u00fablico que prestigiou o in\u00edcio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\/\" \/>\n<meta property=\"og:site_name\" content=\"Rede Litoral RS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tvlitoralrsoficial\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-21T17:29:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-21T17:29:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/SaveClip.App_521655098_18231540046294227_82819119122250637_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\"},\"headline\":\"Festival de Inverno movimenta Cap\u00e3o da Canoa no fim de semana de estreia\",\"datePublished\":\"2025-07-21T17:29:37+00:00\",\"dateModified\":\"2025-07-21T17:29:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\\\/\"},\"wordCount\":323,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/SaveClip.App_521655098_18231540046294227_82819119122250637_n.jpg\",\"keywords\":[\"capao da canoa\",\"gastronomia\",\"litoral norte\",\"not\u00edcia\",\"rio grande do sul\"],\"articleSection\":[\"Cap\u00e3o da Canoa\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\\\/\",\"name\":\"Festival de Inverno movimenta Cap\u00e3o da Canoa no fim de semana de estreia - Rede Litoral RS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/SaveClip.App_521655098_18231540046294227_82819119122250637_n.jpg\",\"datePublished\":\"2025-07-21T17:29:37+00:00\",\"dateModified\":\"2025-07-21T17:29:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/SaveClip.App_521655098_18231540046294227_82819119122250637_n.jpg\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/SaveClip.App_521655098_18231540046294227_82819119122250637_n.jpg\",\"width\":1080,\"height\":1430,\"caption\":\"Foto: Imprensa\\\/PMCC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/redelitoralrs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festival de Inverno movimenta Cap\u00e3o da Canoa no fim de semana de estreia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"name\":\"TV Litoral\",\"description\":\"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redelitoralrs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\",\"name\":\"TV Litoral\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"width\":454,\"height\":454,\"caption\":\"TV Litoral\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tvlitoralrsoficial\",\"https:\\\/\\\/www.instagram.com\\\/tvlitoral.rs\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\",\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"caption\":\"Reda\u00e7\u00e3o TV Litoral\"},\"description\":\"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.\",\"sameAs\":[\"https:\\\/\\\/redelitoralrs.com\",\"https:\\\/\\\/www.instagram.com\\\/redelitoralrs\",\"https:\\\/\\\/www.youtube.com\\\/@redelitoralrs\"],\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/author\\\/redacaotvlitoral\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festival de Inverno movimenta Cap\u00e3o da Canoa no fim de semana de estreia - Rede Litoral RS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\/","og_locale":"pt_BR","og_type":"article","og_title":"Festival de Inverno movimenta Cap\u00e3o da Canoa no fim de semana de estreia - Rede Litoral RS","og_description":"Cap\u00e3o da Canoa deu in\u00edcio ao seu 1\u00ba Festival de Inverno com uma programa\u00e7\u00e3o que promete aquecer a cidade mesmo na esta\u00e7\u00e3o mais fria do ano. A abertura oficial ocorreu na noite da \u00faltima sexta-feira (18), na Casa de Cultura \u00c9rico Ver\u00edssimo, com a presen\u00e7a de autoridades, atra\u00e7\u00f5es culturais e p\u00fablico que prestigiou o in\u00edcio [&hellip;]","og_url":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\/","og_site_name":"Rede Litoral RS","article_publisher":"https:\/\/www.facebook.com\/tvlitoralrsoficial","article_published_time":"2025-07-21T17:29:37+00:00","article_modified_time":"2025-07-21T17:29:38+00:00","og_image":[{"width":1080,"height":1430,"url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/SaveClip.App_521655098_18231540046294227_82819119122250637_n.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o TV Litoral","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o TV Litoral","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\/#article","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\/"},"author":{"name":"Reda\u00e7\u00e3o TV Litoral","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a"},"headline":"Festival de Inverno movimenta Cap\u00e3o da Canoa no fim de semana de estreia","datePublished":"2025-07-21T17:29:37+00:00","dateModified":"2025-07-21T17:29:38+00:00","mainEntityOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\/"},"wordCount":323,"commentCount":0,"publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/SaveClip.App_521655098_18231540046294227_82819119122250637_n.jpg","keywords":["capao da canoa","gastronomia","litoral norte","not\u00edcia","rio grande do sul"],"articleSection":["Cap\u00e3o da Canoa","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\/","url":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\/","name":"Festival de Inverno movimenta Cap\u00e3o da Canoa no fim de semana de estreia - Rede Litoral RS","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\/#primaryimage"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/SaveClip.App_521655098_18231540046294227_82819119122250637_n.jpg","datePublished":"2025-07-21T17:29:37+00:00","dateModified":"2025-07-21T17:29:38+00:00","breadcrumb":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\/#primaryimage","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/SaveClip.App_521655098_18231540046294227_82819119122250637_n.jpg","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/SaveClip.App_521655098_18231540046294227_82819119122250637_n.jpg","width":1080,"height":1430,"caption":"Foto: Imprensa\/PMCC"},{"@type":"BreadcrumbList","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/festival-de-inverno-movimenta-capao-da-canoa-no-fim-de-semana-de-estreia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/redelitoralrs.com\/"},{"@type":"ListItem","position":2,"name":"Festival de Inverno movimenta Cap\u00e3o da Canoa no fim de semana de estreia"}]},{"@type":"WebSite","@id":"https:\/\/redelitoralrs.com\/#website","url":"https:\/\/redelitoralrs.com\/","name":"TV Litoral","description":"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.","publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redelitoralrs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redelitoralrs.com\/#organization","name":"TV Litoral","url":"https:\/\/redelitoralrs.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","width":454,"height":454,"caption":"TV Litoral"},"image":{"@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tvlitoralrsoficial","https:\/\/www.instagram.com\/tvlitoral.rs"]},{"@type":"Person","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a","name":"Reda\u00e7\u00e3o TV Litoral","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","url":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","caption":"Reda\u00e7\u00e3o TV Litoral"},"description":"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.","sameAs":["https:\/\/redelitoralrs.com","https:\/\/www.instagram.com\/redelitoralrs","https:\/\/www.youtube.com\/@redelitoralrs"],"url":"https:\/\/redelitoralrs.com\/index.php\/author\/redacaotvlitoral\/"}]}},"_links":{"self":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/13806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/comments?post=13806"}],"version-history":[{"count":1,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/13806\/revisions"}],"predecessor-version":[{"id":13820,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/13806\/revisions\/13820"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media\/13814"}],"wp:attachment":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media?parent=13806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/categories?post=13806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/tags?post=13806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}