{"id":13764,"date":"2025-07-21T12:04:08","date_gmt":"2025-07-21T15:04:08","guid":{"rendered":"https:\/\/redelitoralrs.com\/?p=13764"},"modified":"2025-07-21T12:21:10","modified_gmt":"2025-07-21T15:21:10","slug":"dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai","status":"publish","type":"post","link":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\/","title":{"rendered":"Dubdogz encerra com sucesso shows nacionais da 33\u00aa Festa Nacional do Peixe em Tramanda\u00ed"},"content":{"rendered":"\n<p>A 33\u00aa Festa Nacional do Peixe teve um encerramento memor\u00e1vel na programa\u00e7\u00e3o de atra\u00e7\u00f5es nacionais. O duo Dubdogz, formado pelos irm\u00e3os g\u00eameos Marcos e Lucas Ruback Schmidt, subiu ao palco da Arena de Shows na noite de s\u00e1bado (19) e comandou uma apresenta\u00e7\u00e3o vibrante que se estendeu at\u00e9 a madrugada deste domingo (20), em Tramanda\u00ed.<\/p>\n\n\n\n<p>Reconhecidos como um dos maiores nomes da m\u00fasica eletr\u00f4nica no Brasil, os artistas levaram uma multid\u00e3o ao del\u00edrio com um set repleto de faixas autorais e remixes de hits da m\u00fasica brasileira e internacional. A performance contou com estrutura de alto n\u00edvel, incluindo um mega tel\u00e3o e efeitos visuais que tornaram a experi\u00eancia ainda mais envolvente.<\/p>\n\n\n\n<p><em>O show marcou n\u00e3o apenas o encerramento da agenda de artistas nacionais do evento, mas tamb\u00e9m a despedida da dupla do Brasil antes de embarcar para apresenta\u00e7\u00f5es no Tomorrowland, considerado o maior festival de m\u00fasica eletr\u00f4nica do mundo, realizado na cidade de Boom, na B\u00e9lgica.<\/em><\/p>\n\n\n\n<p>Com muita energia, luzes e som de qualidade, a noite foi considerada um dos pontos altos desta edi\u00e7\u00e3o da Festa do Peixe, deixando a organiza\u00e7\u00e3o com a sensa\u00e7\u00e3o de dever cumprido e o p\u00fablico com gostinho de \u201cquero mais\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A 33\u00aa Festa Nacional do Peixe teve um encerramento memor\u00e1vel na programa\u00e7\u00e3o de atra\u00e7\u00f5es nacionais. O duo Dubdogz, formado pelos irm\u00e3os g\u00eameos Marcos e Lucas Ruback Schmidt, subiu ao palco da Arena de Shows na noite de s\u00e1bado (19) e comandou uma apresenta\u00e7\u00e3o vibrante que se estendeu at\u00e9 a madrugada deste domingo (20), em Tramanda\u00ed. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13765,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[25,15],"tags":[1341,532,103,1342,92,128,343],"class_list":["post-13764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tramandai","category-noticias","tag-dubdogz","tag-festa-do-peixe","tag-litoral-norte","tag-musica-eletronica","tag-noticia","tag-rio-grande-do-sul","tag-tramandai-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dubdogz encerra com sucesso shows nacionais da 33\u00aa Festa Nacional do Peixe em Tramanda\u00ed - Rede Litoral RS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dubdogz encerra com sucesso shows nacionais da 33\u00aa Festa Nacional do Peixe em Tramanda\u00ed - Rede Litoral RS\" \/>\n<meta property=\"og:description\" content=\"A 33\u00aa Festa Nacional do Peixe teve um encerramento memor\u00e1vel na programa\u00e7\u00e3o de atra\u00e7\u00f5es nacionais. O duo Dubdogz, formado pelos irm\u00e3os g\u00eameos Marcos e Lucas Ruback Schmidt, subiu ao palco da Arena de Shows na noite de s\u00e1bado (19) e comandou uma apresenta\u00e7\u00e3o vibrante que se estendeu at\u00e9 a madrugada deste domingo (20), em Tramanda\u00ed. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\/\" \/>\n<meta property=\"og:site_name\" content=\"Rede Litoral RS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tvlitoralrsoficial\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-21T15:04:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-21T15:21:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/Captura-de-Tela-2025-07-21-as-11.58.27-1024x614.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"614\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\"},\"headline\":\"Dubdogz encerra com sucesso shows nacionais da 33\u00aa Festa Nacional do Peixe em Tramanda\u00ed\",\"datePublished\":\"2025-07-21T15:04:08+00:00\",\"dateModified\":\"2025-07-21T15:21:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\\\/\"},\"wordCount\":230,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Captura-de-Tela-2025-07-21-as-11.58.27.png\",\"keywords\":[\"dubdogz\",\"festa do peixe\",\"litoral norte\",\"musica eletronica\",\"not\u00edcia\",\"rio grande do sul\",\"tramandai\"],\"articleSection\":[\"Tramanda\u00ed\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\\\/\",\"name\":\"Dubdogz encerra com sucesso shows nacionais da 33\u00aa Festa Nacional do Peixe em Tramanda\u00ed - Rede Litoral RS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Captura-de-Tela-2025-07-21-as-11.58.27.png\",\"datePublished\":\"2025-07-21T15:04:08+00:00\",\"dateModified\":\"2025-07-21T15:21:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Captura-de-Tela-2025-07-21-as-11.58.27.png\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Captura-de-Tela-2025-07-21-as-11.58.27.png\",\"width\":1572,\"height\":942,\"caption\":\"Foto: Reprodu\u00e7\u00e3o\\\/Ticiano Kessler - Litoral na Rede\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/07\\\/21\\\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/redelitoralrs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dubdogz encerra com sucesso shows nacionais da 33\u00aa Festa Nacional do Peixe em Tramanda\u00ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"name\":\"TV Litoral\",\"description\":\"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redelitoralrs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\",\"name\":\"TV Litoral\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"width\":454,\"height\":454,\"caption\":\"TV Litoral\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tvlitoralrsoficial\",\"https:\\\/\\\/www.instagram.com\\\/tvlitoral.rs\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\",\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"caption\":\"Reda\u00e7\u00e3o TV Litoral\"},\"description\":\"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.\",\"sameAs\":[\"https:\\\/\\\/redelitoralrs.com\",\"https:\\\/\\\/www.instagram.com\\\/redelitoralrs\",\"https:\\\/\\\/www.youtube.com\\\/@redelitoralrs\"],\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/author\\\/redacaotvlitoral\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dubdogz encerra com sucesso shows nacionais da 33\u00aa Festa Nacional do Peixe em Tramanda\u00ed - Rede Litoral RS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\/","og_locale":"pt_BR","og_type":"article","og_title":"Dubdogz encerra com sucesso shows nacionais da 33\u00aa Festa Nacional do Peixe em Tramanda\u00ed - Rede Litoral RS","og_description":"A 33\u00aa Festa Nacional do Peixe teve um encerramento memor\u00e1vel na programa\u00e7\u00e3o de atra\u00e7\u00f5es nacionais. O duo Dubdogz, formado pelos irm\u00e3os g\u00eameos Marcos e Lucas Ruback Schmidt, subiu ao palco da Arena de Shows na noite de s\u00e1bado (19) e comandou uma apresenta\u00e7\u00e3o vibrante que se estendeu at\u00e9 a madrugada deste domingo (20), em Tramanda\u00ed. [&hellip;]","og_url":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\/","og_site_name":"Rede Litoral RS","article_publisher":"https:\/\/www.facebook.com\/tvlitoralrsoficial","article_published_time":"2025-07-21T15:04:08+00:00","article_modified_time":"2025-07-21T15:21:10+00:00","og_image":[{"width":1024,"height":614,"url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/Captura-de-Tela-2025-07-21-as-11.58.27-1024x614.png","type":"image\/png"}],"author":"Reda\u00e7\u00e3o TV Litoral","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o TV Litoral","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\/#article","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\/"},"author":{"name":"Reda\u00e7\u00e3o TV Litoral","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a"},"headline":"Dubdogz encerra com sucesso shows nacionais da 33\u00aa Festa Nacional do Peixe em Tramanda\u00ed","datePublished":"2025-07-21T15:04:08+00:00","dateModified":"2025-07-21T15:21:10+00:00","mainEntityOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\/"},"wordCount":230,"commentCount":0,"publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/Captura-de-Tela-2025-07-21-as-11.58.27.png","keywords":["dubdogz","festa do peixe","litoral norte","musica eletronica","not\u00edcia","rio grande do sul","tramandai"],"articleSection":["Tramanda\u00ed","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\/","url":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\/","name":"Dubdogz encerra com sucesso shows nacionais da 33\u00aa Festa Nacional do Peixe em Tramanda\u00ed - Rede Litoral RS","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\/#primaryimage"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/Captura-de-Tela-2025-07-21-as-11.58.27.png","datePublished":"2025-07-21T15:04:08+00:00","dateModified":"2025-07-21T15:21:10+00:00","breadcrumb":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\/#primaryimage","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/Captura-de-Tela-2025-07-21-as-11.58.27.png","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/07\/Captura-de-Tela-2025-07-21-as-11.58.27.png","width":1572,"height":942,"caption":"Foto: Reprodu\u00e7\u00e3o\/Ticiano Kessler - Litoral na Rede"},{"@type":"BreadcrumbList","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/07\/21\/dubdogz-encerra-com-sucesso-shows-nacionais-da-33a-festa-nacional-do-peixe-em-tramandai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/redelitoralrs.com\/"},{"@type":"ListItem","position":2,"name":"Dubdogz encerra com sucesso shows nacionais da 33\u00aa Festa Nacional do Peixe em Tramanda\u00ed"}]},{"@type":"WebSite","@id":"https:\/\/redelitoralrs.com\/#website","url":"https:\/\/redelitoralrs.com\/","name":"TV Litoral","description":"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.","publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redelitoralrs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redelitoralrs.com\/#organization","name":"TV Litoral","url":"https:\/\/redelitoralrs.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","width":454,"height":454,"caption":"TV Litoral"},"image":{"@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tvlitoralrsoficial","https:\/\/www.instagram.com\/tvlitoral.rs"]},{"@type":"Person","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a","name":"Reda\u00e7\u00e3o TV Litoral","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","url":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","caption":"Reda\u00e7\u00e3o TV Litoral"},"description":"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.","sameAs":["https:\/\/redelitoralrs.com","https:\/\/www.instagram.com\/redelitoralrs","https:\/\/www.youtube.com\/@redelitoralrs"],"url":"https:\/\/redelitoralrs.com\/index.php\/author\/redacaotvlitoral\/"}]}},"_links":{"self":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/13764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/comments?post=13764"}],"version-history":[{"count":1,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/13764\/revisions"}],"predecessor-version":[{"id":13766,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/13764\/revisions\/13766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media\/13765"}],"wp:attachment":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media?parent=13764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/categories?post=13764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/tags?post=13764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}