{"id":11091,"date":"2025-05-18T13:37:08","date_gmt":"2025-05-18T16:37:08","guid":{"rendered":"https:\/\/redelitoralrs.com\/?p=11091"},"modified":"2025-05-18T13:37:09","modified_gmt":"2025-05-18T16:37:09","slug":"xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil","status":"publish","type":"post","link":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/18\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\/","title":{"rendered":"Xangri-L\u00e1 poder\u00e1 receber escola profissionalizante voltada \u00e0 constru\u00e7\u00e3o civil"},"content":{"rendered":"\n<p>Xangri-L\u00e1 poder\u00e1 contar, em breve, com uma escola profissionalizante voltada \u00e0 \u00e1rea da constru\u00e7\u00e3o civil. <strong>Nesta sexta-feira (16), representantes do SESI\/SENAI e do Sinduscon Litoral Norte estiveram na Escola Municipal de Ensino Fundamental Nayde Emerim Pereira para avaliar a viabilidade estrutural do local para a instala\u00e7\u00e3o da unidade.<\/strong><\/p>\n\n\n\n<p>A proposta, ainda em fase de estudo, visa a oferta de cursos t\u00e9cnicos e programas de Educa\u00e7\u00e3o de Jovens e Adultos (EJA), com foco na qualifica\u00e7\u00e3o de m\u00e3o de obra para o setor da constru\u00e7\u00e3o civil. A iniciativa segue o modelo de parcerias j\u00e1 existentes entre o SESI\/SENAI, o Sinduscon e prefeituras de outros munic\u00edpios do interior do Rio Grande do Sul.<\/p>\n\n\n\n<p>Participaram da visita t\u00e9cnica autoridades locais e representantes das institui\u00e7\u00f5es envolvidas, incluindo o Prefeito de Xangri-L\u00e1, Celsinho Barbosa, o Vice-Prefeito e Secret\u00e1rio interino de Educa\u00e7\u00e3o, Fred Figueir\u00f3, al\u00e9m de membros da dire\u00e7\u00e3o do SESI\/SENAI, Sistema Fiergs e Sinduscon RS Litoral Norte.<\/p>\n\n\n\n<p>A implementa\u00e7\u00e3o da escola representa uma possibilidade concreta de ampliar o acesso \u00e0 forma\u00e7\u00e3o t\u00e9cnica e profissional para a popula\u00e7\u00e3o da regi\u00e3o, contribuindo com o desenvolvimento econ\u00f4mico e social do Litoral Norte. A expectativa \u00e9 de que, caso aprovada, a iniciativa comece a ser estruturada ainda neste ano.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"11094\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/13-3-819x1024.jpg\" alt=\"\" class=\"wp-image-11094\" srcset=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/13-3-819x1024.jpg 819w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/13-3-240x300.jpg 240w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/13-3-768x960.jpg 768w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/13-3.jpg 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><figcaption class=\"wp-element-caption\">Foto: Ascom\/PMX<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"11093\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/12-3-819x1024.jpg\" alt=\"\" class=\"wp-image-11093\" srcset=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/12-3-819x1024.jpg 819w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/12-3-240x300.jpg 240w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/12-3-768x960.jpg 768w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/12-3.jpg 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><figcaption class=\"wp-element-caption\">Foto: Ascom\/PMX<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"11092\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/11-3-819x1024.jpg\" alt=\"\" class=\"wp-image-11092\" srcset=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/11-3-819x1024.jpg 819w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/11-3-240x300.jpg 240w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/11-3-768x960.jpg 768w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/11-3.jpg 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><figcaption class=\"wp-element-caption\">Foto: Ascom\/PMX<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"11095\" src=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/14-2-819x1024.jpg\" alt=\"\" class=\"wp-image-11095\" srcset=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/14-2-819x1024.jpg 819w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/14-2-240x300.jpg 240w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/14-2-768x960.jpg 768w, https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/14-2.jpg 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><figcaption class=\"wp-element-caption\">Foto: Ascom\/PMX<\/figcaption><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Xangri-L\u00e1 poder\u00e1 contar, em breve, com uma escola profissionalizante voltada \u00e0 \u00e1rea da constru\u00e7\u00e3o civil. Nesta sexta-feira (16), representantes do SESI\/SENAI e do Sinduscon Litoral Norte estiveram na Escola Municipal de Ensino Fundamental Nayde Emerim Pereira para avaliar a viabilidade estrutural do local para a instala\u00e7\u00e3o da unidade. A proposta, ainda em fase de estudo, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11097,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[228,20,15,34],"tags":[912,139,103,92,128,914,915,913,383],"class_list":["post-11091","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","category-litoral_norte","category-noticias","category-xangri-la","tag-construcao-civil","tag-educacao","tag-litoral-norte","tag-noticia","tag-rio-grande-do-sul","tag-senai","tag-sesi","tag-sinduscon","tag-xangrila"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Xangri-L\u00e1 poder\u00e1 receber escola profissionalizante voltada \u00e0 constru\u00e7\u00e3o civil - Rede Litoral RS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/18\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Xangri-L\u00e1 poder\u00e1 receber escola profissionalizante voltada \u00e0 constru\u00e7\u00e3o civil - Rede Litoral RS\" \/>\n<meta property=\"og:description\" content=\"Xangri-L\u00e1 poder\u00e1 contar, em breve, com uma escola profissionalizante voltada \u00e0 \u00e1rea da constru\u00e7\u00e3o civil. Nesta sexta-feira (16), representantes do SESI\/SENAI e do Sinduscon Litoral Norte estiveram na Escola Municipal de Ensino Fundamental Nayde Emerim Pereira para avaliar a viabilidade estrutural do local para a instala\u00e7\u00e3o da unidade. A proposta, ainda em fase de estudo, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/18\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\/\" \/>\n<meta property=\"og:site_name\" content=\"Rede Litoral RS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tvlitoralrsoficial\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-18T16:37:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-18T16:37:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/15.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1069\" \/>\n\t<meta property=\"og:image:height\" content=\"775\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/18\\\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/18\\\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\"},\"headline\":\"Xangri-L\u00e1 poder\u00e1 receber escola profissionalizante voltada \u00e0 constru\u00e7\u00e3o civil\",\"datePublished\":\"2025-05-18T16:37:08+00:00\",\"dateModified\":\"2025-05-18T16:37:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/18\\\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\\\/\"},\"wordCount\":239,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/18\\\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/15.jpeg\",\"keywords\":[\"constru\u00e7\u00e3o civil\",\"educa\u00e7\u00e3o\",\"litoral norte\",\"not\u00edcia\",\"rio grande do sul\",\"senai\",\"sesi\",\"sinduscon\",\"xangrila\"],\"articleSection\":[\"Educa\u00e7\u00e3o\",\"Litoral Norte\",\"\u00daltimas not\u00edcias\",\"Xangri-L\u00e1\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/18\\\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/18\\\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/18\\\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\\\/\",\"name\":\"Xangri-L\u00e1 poder\u00e1 receber escola profissionalizante voltada \u00e0 constru\u00e7\u00e3o civil - Rede Litoral RS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/18\\\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/18\\\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/15.jpeg\",\"datePublished\":\"2025-05-18T16:37:08+00:00\",\"dateModified\":\"2025-05-18T16:37:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/18\\\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/18\\\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/18\\\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/15.jpeg\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/15.jpeg\",\"width\":1069,\"height\":775,\"caption\":\"Foto: Ascom\\\/PMX\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/18\\\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/redelitoralrs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Xangri-L\u00e1 poder\u00e1 receber escola profissionalizante voltada \u00e0 constru\u00e7\u00e3o civil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"name\":\"TV Litoral\",\"description\":\"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redelitoralrs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\",\"name\":\"TV Litoral\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"width\":454,\"height\":454,\"caption\":\"TV Litoral\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tvlitoralrsoficial\",\"https:\\\/\\\/www.instagram.com\\\/tvlitoral.rs\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\",\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"caption\":\"Reda\u00e7\u00e3o TV Litoral\"},\"description\":\"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.\",\"sameAs\":[\"https:\\\/\\\/redelitoralrs.com\",\"https:\\\/\\\/www.instagram.com\\\/redelitoralrs\",\"https:\\\/\\\/www.youtube.com\\\/@redelitoralrs\"],\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/author\\\/redacaotvlitoral\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Xangri-L\u00e1 poder\u00e1 receber escola profissionalizante voltada \u00e0 constru\u00e7\u00e3o civil - Rede Litoral RS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/18\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\/","og_locale":"pt_BR","og_type":"article","og_title":"Xangri-L\u00e1 poder\u00e1 receber escola profissionalizante voltada \u00e0 constru\u00e7\u00e3o civil - Rede Litoral RS","og_description":"Xangri-L\u00e1 poder\u00e1 contar, em breve, com uma escola profissionalizante voltada \u00e0 \u00e1rea da constru\u00e7\u00e3o civil. Nesta sexta-feira (16), representantes do SESI\/SENAI e do Sinduscon Litoral Norte estiveram na Escola Municipal de Ensino Fundamental Nayde Emerim Pereira para avaliar a viabilidade estrutural do local para a instala\u00e7\u00e3o da unidade. A proposta, ainda em fase de estudo, [&hellip;]","og_url":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/18\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\/","og_site_name":"Rede Litoral RS","article_publisher":"https:\/\/www.facebook.com\/tvlitoralrsoficial","article_published_time":"2025-05-18T16:37:08+00:00","article_modified_time":"2025-05-18T16:37:09+00:00","og_image":[{"width":1069,"height":775,"url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/15.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o TV Litoral","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o TV Litoral","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/18\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\/#article","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/18\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\/"},"author":{"name":"Reda\u00e7\u00e3o TV Litoral","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a"},"headline":"Xangri-L\u00e1 poder\u00e1 receber escola profissionalizante voltada \u00e0 constru\u00e7\u00e3o civil","datePublished":"2025-05-18T16:37:08+00:00","dateModified":"2025-05-18T16:37:09+00:00","mainEntityOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/18\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\/"},"wordCount":239,"commentCount":0,"publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/18\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/15.jpeg","keywords":["constru\u00e7\u00e3o civil","educa\u00e7\u00e3o","litoral norte","not\u00edcia","rio grande do sul","senai","sesi","sinduscon","xangrila"],"articleSection":["Educa\u00e7\u00e3o","Litoral Norte","\u00daltimas not\u00edcias","Xangri-L\u00e1"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/05\/18\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/18\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\/","url":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/18\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\/","name":"Xangri-L\u00e1 poder\u00e1 receber escola profissionalizante voltada \u00e0 constru\u00e7\u00e3o civil - Rede Litoral RS","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/18\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\/#primaryimage"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/18\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/15.jpeg","datePublished":"2025-05-18T16:37:08+00:00","dateModified":"2025-05-18T16:37:09+00:00","breadcrumb":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/18\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/05\/18\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/18\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\/#primaryimage","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/15.jpeg","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/15.jpeg","width":1069,"height":775,"caption":"Foto: Ascom\/PMX"},{"@type":"BreadcrumbList","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/18\/xangri-la-podera-receber-escola-profissionalizante-voltada-a-construcao-civil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/redelitoralrs.com\/"},{"@type":"ListItem","position":2,"name":"Xangri-L\u00e1 poder\u00e1 receber escola profissionalizante voltada \u00e0 constru\u00e7\u00e3o civil"}]},{"@type":"WebSite","@id":"https:\/\/redelitoralrs.com\/#website","url":"https:\/\/redelitoralrs.com\/","name":"TV Litoral","description":"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.","publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redelitoralrs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redelitoralrs.com\/#organization","name":"TV Litoral","url":"https:\/\/redelitoralrs.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","width":454,"height":454,"caption":"TV Litoral"},"image":{"@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tvlitoralrsoficial","https:\/\/www.instagram.com\/tvlitoral.rs"]},{"@type":"Person","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a","name":"Reda\u00e7\u00e3o TV Litoral","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","url":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","caption":"Reda\u00e7\u00e3o TV Litoral"},"description":"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.","sameAs":["https:\/\/redelitoralrs.com","https:\/\/www.instagram.com\/redelitoralrs","https:\/\/www.youtube.com\/@redelitoralrs"],"url":"https:\/\/redelitoralrs.com\/index.php\/author\/redacaotvlitoral\/"}]}},"_links":{"self":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/11091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/comments?post=11091"}],"version-history":[{"count":1,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/11091\/revisions"}],"predecessor-version":[{"id":11098,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/11091\/revisions\/11098"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media\/11097"}],"wp:attachment":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media?parent=11091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/categories?post=11091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/tags?post=11091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}