{"id":10820,"date":"2025-05-11T19:38:40","date_gmt":"2025-05-11T22:38:40","guid":{"rendered":"https:\/\/redelitoralrs.com\/?p=10820"},"modified":"2025-05-11T19:38:41","modified_gmt":"2025-05-11T22:38:41","slug":"brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas","status":"publish","type":"post","link":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/11\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\/","title":{"rendered":"Brigada Militar prende homem com arma e mais de um quilo de drogas"},"content":{"rendered":"\n<p>Um homem de 34 anos foi preso na noite da \u00faltima quinta-feira (8) no bairro Arco-\u00cdris, em Cap\u00e3o da Canoa, por porte ilegal de arma de fogo e tr\u00e1fico de drogas. A a\u00e7\u00e3o foi realizada por uma equipe da For\u00e7a T\u00e1tica do 2\u00ba Batalh\u00e3o de Policiamento de \u00c1reas Tur\u00edsticas (2\u00ba BPAT), ap\u00f3s den\u00fancia recebida via telefone 190.<\/p>\n\n\n\n<p>De acordo com a Brigada Militar, o suspeito foi localizado enquanto caminhava em via p\u00fablica com uma mochila. Ao perceber a aproxima\u00e7\u00e3o da viatura, ele tentou se esconder atr\u00e1s de um ve\u00edculo, sendo abordado em seguida.<\/p>\n\n\n\n<p><em>Durante a revista, os policiais encontraram uma pistola calibre 9 mil\u00edmetros com 13 muni\u00e7\u00f5es na cintura do indiv\u00edduo. Na mochila, foram localizadas 18 por\u00e7\u00f5es de maconha (1,2 kg), 72 por\u00e7\u00f5es de coca\u00edna e uma balan\u00e7a de precis\u00e3o.<\/em><\/p>\n\n\n\n<p>O preso possui antecedentes criminais por tr\u00e1fico de entorpecentes e roubo a estabelecimento comercial. Ele foi encaminhado \u00e0 delegacia para registro da ocorr\u00eancia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem de 34 anos foi preso na noite da \u00faltima quinta-feira (8) no bairro Arco-\u00cdris, em Cap\u00e3o da Canoa, por porte ilegal de arma de fogo e tr\u00e1fico de drogas. A a\u00e7\u00e3o foi realizada por uma equipe da For\u00e7a T\u00e1tica do 2\u00ba Batalh\u00e3o de Policiamento de \u00c1reas Tur\u00edsticas (2\u00ba BPAT), ap\u00f3s den\u00fancia recebida via [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10821,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[24,15],"tags":[274,103,92,102,128],"class_list":["post-10820","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-capao-da-canoa","category-noticias","tag-capao-da-canoa-2","tag-litoral-norte","tag-noticia","tag-policia","tag-rio-grande-do-sul"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brigada Militar prende homem com arma e mais de um quilo de drogas - Rede Litoral RS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/11\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brigada Militar prende homem com arma e mais de um quilo de drogas - Rede Litoral RS\" \/>\n<meta property=\"og:description\" content=\"Um homem de 34 anos foi preso na noite da \u00faltima quinta-feira (8) no bairro Arco-\u00cdris, em Cap\u00e3o da Canoa, por porte ilegal de arma de fogo e tr\u00e1fico de drogas. A a\u00e7\u00e3o foi realizada por uma equipe da For\u00e7a T\u00e1tica do 2\u00ba Batalh\u00e3o de Policiamento de \u00c1reas Tur\u00edsticas (2\u00ba BPAT), ap\u00f3s den\u00fancia recebida via [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/11\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\/\" \/>\n<meta property=\"og:site_name\" content=\"Rede Litoral RS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tvlitoralrsoficial\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-11T22:38:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-11T22:38:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-11-at-19.27.35-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1605\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o TV Litoral\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/11\\\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/11\\\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\"},\"headline\":\"Brigada Militar prende homem com arma e mais de um quilo de drogas\",\"datePublished\":\"2025-05-11T22:38:40+00:00\",\"dateModified\":\"2025-05-11T22:38:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/11\\\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\\\/\"},\"wordCount\":179,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/11\\\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/WhatsApp-Image-2025-05-11-at-19.27.35-scaled.jpeg\",\"keywords\":[\"capao da canoa\",\"litoral norte\",\"not\u00edcia\",\"pol\u00edcia\",\"rio grande do sul\"],\"articleSection\":[\"Cap\u00e3o da Canoa\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/11\\\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/11\\\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/11\\\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\\\/\",\"name\":\"Brigada Militar prende homem com arma e mais de um quilo de drogas - Rede Litoral RS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/11\\\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/11\\\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/WhatsApp-Image-2025-05-11-at-19.27.35-scaled.jpeg\",\"datePublished\":\"2025-05-11T22:38:40+00:00\",\"dateModified\":\"2025-05-11T22:38:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/11\\\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/11\\\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/11\\\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/WhatsApp-Image-2025-05-11-at-19.27.35-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/WhatsApp-Image-2025-05-11-at-19.27.35-scaled.jpeg\",\"width\":2560,\"height\":1605,\"caption\":\"Fotos: Divulga\u00e7\u00e3o\\\/2\u00ba BPAT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/2025\\\/05\\\/11\\\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/redelitoralrs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brigada Militar prende homem com arma e mais de um quilo de drogas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#website\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"name\":\"TV Litoral\",\"description\":\"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redelitoralrs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#organization\",\"name\":\"TV Litoral\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/faviconicon-1-1.png\",\"width\":454,\"height\":454,\"caption\":\"TV Litoral\"},\"image\":{\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tvlitoralrsoficial\",\"https:\\\/\\\/www.instagram.com\\\/tvlitoral.rs\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/#\\\/schema\\\/person\\\/9f8181f2a7359dd3986f05ebaf5bd68a\",\"name\":\"Reda\u00e7\u00e3o TV Litoral\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"contentUrl\":\"https:\\\/\\\/redelitoralrs.com\\\/wp-content\\\/litespeed\\\/avatar\\\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043\",\"caption\":\"Reda\u00e7\u00e3o TV Litoral\"},\"description\":\"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.\",\"sameAs\":[\"https:\\\/\\\/redelitoralrs.com\",\"https:\\\/\\\/www.instagram.com\\\/redelitoralrs\",\"https:\\\/\\\/www.youtube.com\\\/@redelitoralrs\"],\"url\":\"https:\\\/\\\/redelitoralrs.com\\\/index.php\\\/author\\\/redacaotvlitoral\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brigada Militar prende homem com arma e mais de um quilo de drogas - Rede Litoral RS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/11\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\/","og_locale":"pt_BR","og_type":"article","og_title":"Brigada Militar prende homem com arma e mais de um quilo de drogas - Rede Litoral RS","og_description":"Um homem de 34 anos foi preso na noite da \u00faltima quinta-feira (8) no bairro Arco-\u00cdris, em Cap\u00e3o da Canoa, por porte ilegal de arma de fogo e tr\u00e1fico de drogas. A a\u00e7\u00e3o foi realizada por uma equipe da For\u00e7a T\u00e1tica do 2\u00ba Batalh\u00e3o de Policiamento de \u00c1reas Tur\u00edsticas (2\u00ba BPAT), ap\u00f3s den\u00fancia recebida via [&hellip;]","og_url":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/11\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\/","og_site_name":"Rede Litoral RS","article_publisher":"https:\/\/www.facebook.com\/tvlitoralrsoficial","article_published_time":"2025-05-11T22:38:40+00:00","article_modified_time":"2025-05-11T22:38:41+00:00","og_image":[{"width":2560,"height":1605,"url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-11-at-19.27.35-scaled.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o TV Litoral","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o TV Litoral","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/11\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\/#article","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/11\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\/"},"author":{"name":"Reda\u00e7\u00e3o TV Litoral","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a"},"headline":"Brigada Militar prende homem com arma e mais de um quilo de drogas","datePublished":"2025-05-11T22:38:40+00:00","dateModified":"2025-05-11T22:38:41+00:00","mainEntityOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/11\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\/"},"wordCount":179,"commentCount":0,"publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/11\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-11-at-19.27.35-scaled.jpeg","keywords":["capao da canoa","litoral norte","not\u00edcia","pol\u00edcia","rio grande do sul"],"articleSection":["Cap\u00e3o da Canoa","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/05\/11\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/11\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\/","url":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/11\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\/","name":"Brigada Militar prende homem com arma e mais de um quilo de drogas - Rede Litoral RS","isPartOf":{"@id":"https:\/\/redelitoralrs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/11\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\/#primaryimage"},"image":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/11\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\/#primaryimage"},"thumbnailUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-11-at-19.27.35-scaled.jpeg","datePublished":"2025-05-11T22:38:40+00:00","dateModified":"2025-05-11T22:38:41+00:00","breadcrumb":{"@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/11\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redelitoralrs.com\/index.php\/2025\/05\/11\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/11\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\/#primaryimage","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-11-at-19.27.35-scaled.jpeg","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-11-at-19.27.35-scaled.jpeg","width":2560,"height":1605,"caption":"Fotos: Divulga\u00e7\u00e3o\/2\u00ba BPAT"},{"@type":"BreadcrumbList","@id":"https:\/\/redelitoralrs.com\/index.php\/2025\/05\/11\/brigada-militar-prende-homem-com-arma-e-mais-de-um-quilo-de-drogas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/redelitoralrs.com\/"},{"@type":"ListItem","position":2,"name":"Brigada Militar prende homem com arma e mais de um quilo de drogas"}]},{"@type":"WebSite","@id":"https:\/\/redelitoralrs.com\/#website","url":"https:\/\/redelitoralrs.com\/","name":"TV Litoral","description":"Acompanhe tudo do litoral ga\u00facho com a cobertura completa e atualizada da Rede Litoral RS. Nossos jornalistas trazem as \u00faltimas not\u00edcias, os acontecimentos mais quentes e as hist\u00f3rias que importam sobre nosso amado litoral.","publisher":{"@id":"https:\/\/redelitoralrs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redelitoralrs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redelitoralrs.com\/#organization","name":"TV Litoral","url":"https:\/\/redelitoralrs.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/","url":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/uploads\/2024\/01\/faviconicon-1-1.png","width":454,"height":454,"caption":"TV Litoral"},"image":{"@id":"https:\/\/redelitoralrs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tvlitoralrsoficial","https:\/\/www.instagram.com\/tvlitoral.rs"]},{"@type":"Person","@id":"https:\/\/redelitoralrs.com\/#\/schema\/person\/9f8181f2a7359dd3986f05ebaf5bd68a","name":"Reda\u00e7\u00e3o TV Litoral","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","url":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","contentUrl":"https:\/\/redelitoralrs.com\/wp-content\/litespeed\/avatar\/779aafbb45e66c7f82733e21abb48259.jpg?ver=1783610043","caption":"Reda\u00e7\u00e3o TV Litoral"},"description":"A Rede Litoral de Comunica\u00e7\u00e3o \u00e9 um grupo de m\u00eddia multiplataforma do Litoral Norte do RS. Com atua\u00e7\u00e3o em TV, r\u00e1dio, portal e redes sociais, levamos informa\u00e7\u00e3o, conte\u00fado e entretenimento \u00e0 comunidade, fortalecendo a comunica\u00e7\u00e3o local e impulsionando o desenvolvimento regional. Acompanhe atrav\u00e9s de @redelitoralrs.","sameAs":["https:\/\/redelitoralrs.com","https:\/\/www.instagram.com\/redelitoralrs","https:\/\/www.youtube.com\/@redelitoralrs"],"url":"https:\/\/redelitoralrs.com\/index.php\/author\/redacaotvlitoral\/"}]}},"_links":{"self":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/10820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/comments?post=10820"}],"version-history":[{"count":1,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/10820\/revisions"}],"predecessor-version":[{"id":10822,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/posts\/10820\/revisions\/10822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media\/10821"}],"wp:attachment":[{"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/media?parent=10820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/categories?post=10820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redelitoralrs.com\/index.php\/wp-json\/wp\/v2\/tags?post=10820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}